{"id":10052,"date":"2023-02-23T12:11:40","date_gmt":"2023-02-23T11:11:40","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=10052"},"modified":"2023-02-23T12:11:43","modified_gmt":"2023-02-23T11:11:43","slug":"les-compositions-selon-la-presse-aguilar-pret-a-debuter","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/23\/les-compositions-selon-la-presse-aguilar-pret-a-debuter\/","title":{"rendered":"Les compositions selon la presse : Aguilar pr\u00eat \u00e0 d\u00e9buter ?"},"content":{"rendered":"\n\n\n<p>C&rsquo;est l&rsquo;une des interrogations de Philippe Clement et un cas qui sera tranch\u00e9 aujourd&rsquo;hui. Ruben Aguilar, victime d&rsquo;une d\u00e9chirure aux ischios jeudi dernier, sera-t-il en mesure de d\u00e9buter la rencontre et d&rsquo;\u00eatre inscrit sur la feuille de match ou va-t-il devoir laisser sa place ? Selon <em>Nice-Matin<\/em>, il devrait d\u00e9buter sur le banc des rempla\u00e7ants et laisser sa place \u00e0 Matsima alors que <em>L&rsquo;\u00c9quipe<\/em> le voit en titulaire.<\/p>\n\n\n\n<p>Autre interrogation sur le pr\u00e9sence de Minamino dans le onze pour <em>Nice-Matin<\/em>, et qui se verrait confier une nouvelle chance par Philippe Clement apr\u00e8s \u00eatre pass\u00e9 \u00e0 c\u00f4t\u00e9 lors du match aller.<\/p>\n\n\n\n<p><strong>Le onze mon\u00e9gasque selon <em>L\u2019\u00c9quipe<\/em> (4-4-2) :<\/strong> N\u00fcbel &#8211; Aguilar, Disasi (cap.), Sarr, C. Henrique &#8211; Diatta, Fofana, Camara, Golovin &#8211; Ben Seghir, Embolo.<\/p>\n\n\n\n<p><strong>Le onze mon\u00e9gasque selon <em>Nice-Matin<\/em> (4-2-3-1) :<\/strong> N\u00fcbel &#8211; Matsima, Disasi (cap.), Sarr, C. Henrique &#8211; Fofana, Camara &#8211; Diatta, Minamino, Golovin &#8211; Embolo.<\/p>\n\n\n\n<p>Du c\u00f4t\u00e9 du Bayer Leverkusen, Diaby ne devrait pas d\u00e9buter la rencontre mais les deux onze propos\u00e9s sont tr\u00e8s diff\u00e9rents.<\/p>\n\n\n\n<p><strong>Le onze allemand selon <em>L\u2019\u00c9quipe<\/em> (3-4-3) :<\/strong> Hradecky (cap.) &#8211; Tah, Tapsoba, Hincapie &#8211; Frimpong, Palacios, Andrich, Bakker &#8211; Adli, Schick, Wirtz.<\/p>\n\n\n\n<p><strong>Le onze allemand selon <em>Nice-Matin<\/em> (4-2-3-1) :<\/strong> Hradecky (cap.) &#8211; Frimpong, Tah, Tapsoba, Hincapie &#8211; Palacios, Andrich &#8211; Amiri, Wirtz, Hudson-Odoi &#8211; Hlozek.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>C&rsquo;est l&rsquo;une des interrogations de Philippe Clement et un cas qui sera tranch\u00e9 aujourd&rsquo;hui. Ruben Aguilar, victime d&rsquo;une d\u00e9chirure aux ischios jeudi dernier, sera-t-il en mesure de d\u00e9buter la rencontre et d&rsquo;\u00eatre inscrit sur la feuille de match ou va-t-il devoir laisser sa place ? Selon Nice-Matin, il devrait d\u00e9buter sur le banc des rempla\u00e7ants [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[86,213,224,419],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les compositions selon la presse : Aguilar pr\u00eat \u00e0 d\u00e9buter ? - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/23\/les-compositions-selon-la-presse-aguilar-pret-a-debuter\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les compositions selon la presse : Aguilar pr\u00eat \u00e0 d\u00e9buter ? - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"C&rsquo;est l&rsquo;une des interrogations de Philippe Clement et un cas qui sera tranch\u00e9 aujourd&rsquo;hui. Ruben Aguilar, victime d&rsquo;une d\u00e9chirure aux ischios jeudi dernier, sera-t-il en mesure de d\u00e9buter la rencontre et d&rsquo;\u00eatre inscrit sur la feuille de match ou va-t-il devoir laisser sa place ? Selon Nice-Matin, il devrait d\u00e9buter sur le banc des rempla\u00e7ants [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/23\/les-compositions-selon-la-presse-aguilar-pret-a-debuter\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-23T11:11:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-23T11:11:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/11\/aguilar.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/11\/aguilar.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/23\/les-compositions-selon-la-presse-aguilar-pret-a-debuter\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/23\/les-compositions-selon-la-presse-aguilar-pret-a-debuter\/\",\"name\":\"Les compositions selon la presse : Aguilar pr\u00eat \u00e0 d\u00e9buter ? - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2023-02-23T11:11:40+00:00\",\"dateModified\":\"2023-02-23T11:11:43+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/23\/les-compositions-selon-la-presse-aguilar-pret-a-debuter\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/23\/les-compositions-selon-la-presse-aguilar-pret-a-debuter\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/23\/les-compositions-selon-la-presse-aguilar-pret-a-debuter\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les compositions selon la presse : Aguilar pr\u00eat \u00e0 d\u00e9buter ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les compositions selon la presse : Aguilar pr\u00eat \u00e0 d\u00e9buter ? - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/23\/les-compositions-selon-la-presse-aguilar-pret-a-debuter\/","og_locale":"fr_FR","og_type":"article","og_title":"Les compositions selon la presse : Aguilar pr\u00eat \u00e0 d\u00e9buter ? - La Diagonale","og_description":"C&rsquo;est l&rsquo;une des interrogations de Philippe Clement et un cas qui sera tranch\u00e9 aujourd&rsquo;hui. Ruben Aguilar, victime d&rsquo;une d\u00e9chirure aux ischios jeudi dernier, sera-t-il en mesure de d\u00e9buter la rencontre et d&rsquo;\u00eatre inscrit sur la feuille de match ou va-t-il devoir laisser sa place ? Selon Nice-Matin, il devrait d\u00e9buter sur le banc des rempla\u00e7ants [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/23\/les-compositions-selon-la-presse-aguilar-pret-a-debuter\/","og_site_name":"La Diagonale","article_published_time":"2023-02-23T11:11:40+00:00","article_modified_time":"2023-02-23T11:11:43+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/11\/aguilar.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/11\/aguilar.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/23\/les-compositions-selon-la-presse-aguilar-pret-a-debuter\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/23\/les-compositions-selon-la-presse-aguilar-pret-a-debuter\/","name":"Les compositions selon la presse : Aguilar pr\u00eat \u00e0 d\u00e9buter ? - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2023-02-23T11:11:40+00:00","dateModified":"2023-02-23T11:11:43+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/23\/les-compositions-selon-la-presse-aguilar-pret-a-debuter\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/23\/les-compositions-selon-la-presse-aguilar-pret-a-debuter\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/23\/les-compositions-selon-la-presse-aguilar-pret-a-debuter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Les compositions selon la presse : Aguilar pr\u00eat \u00e0 d\u00e9buter ?"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/10052"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=10052"}],"version-history":[{"count":1,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/10052\/revisions"}],"predecessor-version":[{"id":10053,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/10052\/revisions\/10053"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=10052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=10052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=10052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}