{"id":10233,"date":"2023-02-26T19:49:41","date_gmt":"2023-02-26T18:49:41","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=10233"},"modified":"2023-02-26T19:49:44","modified_gmt":"2023-02-26T18:49:44","slug":"camara-le-chemin-est-encore-long","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/26\/camara-le-chemin-est-encore-long\/","title":{"rendered":"Camara : \u00ab\u00a0Le chemin est encore long\u00a0\u00bb"},"content":{"rendered":"\n\n\n<p>Monaco a pris une claque face \u00e0 Nice dans le derby (0-3) et Mohamed Camara a confi\u00e9 sa d\u00e9ception au micro de <em>Prime Video<\/em> \u00e0 l\u2019issue de la rencontre : \u00ab\u00a0<em>\u00c7a fait mal. On voulait gagner ce match, on savait que c\u2019\u00e9tait important pour nous et tous nos supporters, malheureusement en premi\u00e8re mi-temps, ils ont mis leurs occasions au fond et \u00e7a nous a co\u00fbt\u00e9 cher.<\/em>\u00a0\u00bb<\/p>\n\n\n\n<p>Monaco a v\u00e9cu une semaine difficile apr\u00e8s l\u2019\u00e9limination en Ligue Europa : \u00ab\u00a0<em>La d\u00e9faite de Leverkusen ce n\u2019est pas une excuse. Aujourd\u2019hui en premi\u00e8re mi-temps ils \u00e9taient mieux en place et ils profit\u00e9 de leurs forces en contre-attaque pour mettre deux buts. Mais ce n\u2019est pas fini, le chemin est encore long et on va travailler pour revenir.<\/em>\u00a0\u00bb<\/p>\n\n\n\n<p>Au classement, Monaco restera quoiqu&rsquo;il arrive sur le podium \u00e0 la fin de cette journ\u00e9e mais ne profitera pas de l\u2019affrontement entre Marseille et Paris de ce dimanche soir : \u00ab\u00a0<em>C\u2019\u00e9tait important pour nous (de combler l&rsquo;\u00e9cart, ndlr). Tous les points sont importants maintenant dans cette phase de la saison. C\u2019est difficile mais on va travailler plus.<\/em>\u00a0\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Monaco a pris une claque face \u00e0 Nice dans le derby (0-3) et Mohamed Camara a confi\u00e9 sa d\u00e9ception au micro de Prime Video \u00e0 l\u2019issue de la rencontre : \u00ab\u00a0\u00c7a fait mal. On voulait gagner ce match, on savait que c\u2019\u00e9tait important pour nous et tous nos supporters, malheureusement en premi\u00e8re mi-temps, ils ont [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[86,94,143,422],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Camara : \u00ab\u00a0Le chemin est encore long\u00a0\u00bb - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/26\/camara-le-chemin-est-encore-long\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Camara : \u00ab\u00a0Le chemin est encore long\u00a0\u00bb - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Monaco a pris une claque face \u00e0 Nice dans le derby (0-3) et Mohamed Camara a confi\u00e9 sa d\u00e9ception au micro de Prime Video \u00e0 l\u2019issue de la rencontre : \u00ab\u00a0\u00c7a fait mal. On voulait gagner ce match, on savait que c\u2019\u00e9tait important pour nous et tous nos supporters, malheureusement en premi\u00e8re mi-temps, ils ont [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/26\/camara-le-chemin-est-encore-long\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-26T18:49:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-26T18:49:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/11\/camara.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/11\/camara.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/26\/camara-le-chemin-est-encore-long\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/26\/camara-le-chemin-est-encore-long\/\",\"name\":\"Camara : \u00ab\u00a0Le chemin est encore long\u00a0\u00bb - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2023-02-26T18:49:41+00:00\",\"dateModified\":\"2023-02-26T18:49:44+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/26\/camara-le-chemin-est-encore-long\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/26\/camara-le-chemin-est-encore-long\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/26\/camara-le-chemin-est-encore-long\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Camara : \u00ab\u00a0Le chemin est encore long\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Camara : \u00ab\u00a0Le chemin est encore long\u00a0\u00bb - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/26\/camara-le-chemin-est-encore-long\/","og_locale":"fr_FR","og_type":"article","og_title":"Camara : \u00ab\u00a0Le chemin est encore long\u00a0\u00bb - La Diagonale","og_description":"Monaco a pris une claque face \u00e0 Nice dans le derby (0-3) et Mohamed Camara a confi\u00e9 sa d\u00e9ception au micro de Prime Video \u00e0 l\u2019issue de la rencontre : \u00ab\u00a0\u00c7a fait mal. On voulait gagner ce match, on savait que c\u2019\u00e9tait important pour nous et tous nos supporters, malheureusement en premi\u00e8re mi-temps, ils ont [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/26\/camara-le-chemin-est-encore-long\/","og_site_name":"La Diagonale","article_published_time":"2023-02-26T18:49:41+00:00","article_modified_time":"2023-02-26T18:49:44+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/11\/camara.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/11\/camara.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/26\/camara-le-chemin-est-encore-long\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/26\/camara-le-chemin-est-encore-long\/","name":"Camara : \u00ab\u00a0Le chemin est encore long\u00a0\u00bb - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2023-02-26T18:49:41+00:00","dateModified":"2023-02-26T18:49:44+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/26\/camara-le-chemin-est-encore-long\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/26\/camara-le-chemin-est-encore-long\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/26\/camara-le-chemin-est-encore-long\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Camara : \u00ab\u00a0Le chemin est encore long\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/10233"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=10233"}],"version-history":[{"count":1,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/10233\/revisions"}],"predecessor-version":[{"id":10234,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/10233\/revisions\/10234"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=10233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=10233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=10233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}