{"id":10591,"date":"2023-03-12T14:25:31","date_gmt":"2023-03-12T13:25:31","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=10591"},"modified":"2023-03-12T16:27:38","modified_gmt":"2023-03-12T15:27:38","slug":"live-nantes-monaco-coupe-gambardella","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/12\/live-nantes-monaco-coupe-gambardella\/","title":{"rendered":"Gambardella : Regardez le replay de Nantes-Monaco"},"content":{"rendered":"\n<p>Ce dimanche (14h30), les U19 de l&rsquo;AS Monaco affrontent le FC Nantes en quart de finale de la Coupe Gambardella. <\/p>\n\n\n\n<p>Le match est retransmis en direct et comment\u00e9 sur la plateforme audiovisuelle de la FFF. Vous pouvez le regarder directement sur le lecteur ci-dessous.<\/p>\n\n\n\n<p><strong>Composition : <\/strong>Schulz &#8211; Sitou, Eser, Valm\u00e9, Sinat\u00e9 &#8211; Benama, Cabral, Tour\u00e9 &#8211; Tincres, Bouabr\u00e9, Michal.<\/p>\n\n\n\n<p><em>Rempla\u00e7ants :<\/em> Minguzzi (g.), Sow, Bamba, Bertolucci, Dendani.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Quarts I FC Nantes - AS Monaco en direct (14h25) I Coupe Gambardella-Cr\u00e9dit Agricole 2022-2023\" width=\"1020\" height=\"765\" src=\"https:\/\/www.youtube.com\/embed\/oiojOR6xT7Q?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Ce dimanche (14h30), les U19 de l&rsquo;AS Monaco affrontent le FC Nantes en quart de finale de la Coupe Gambardella. Le match est retransmis en direct et comment\u00e9 sur la plateforme audiovisuelle de la FFF. Vous pouvez le regarder directement sur le lecteur ci-dessous. Composition : Schulz &#8211; Sitou, Eser, Valm\u00e9, Sinat\u00e9 &#8211; Benama, Cabral, [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[76,86,321],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gambardella : Regardez le replay de Nantes-Monaco - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/12\/live-nantes-monaco-coupe-gambardella\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gambardella : Regardez le replay de Nantes-Monaco - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Ce dimanche (14h30), les U19 de l&rsquo;AS Monaco affrontent le FC Nantes en quart de finale de la Coupe Gambardella. Le match est retransmis en direct et comment\u00e9 sur la plateforme audiovisuelle de la FFF. Vous pouvez le regarder directement sur le lecteur ci-dessous. Composition : Schulz &#8211; Sitou, Eser, Valm\u00e9, Sinat\u00e9 &#8211; Benama, Cabral, [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/12\/live-nantes-monaco-coupe-gambardella\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-12T13:25:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-12T15:27:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/02\/sinate-gambardella.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/02\/sinate-gambardella.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/12\/live-nantes-monaco-coupe-gambardella\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/12\/live-nantes-monaco-coupe-gambardella\/\",\"name\":\"Gambardella : Regardez le replay de Nantes-Monaco - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2023-03-12T13:25:31+00:00\",\"dateModified\":\"2023-03-12T15:27:38+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/12\/live-nantes-monaco-coupe-gambardella\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/12\/live-nantes-monaco-coupe-gambardella\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/12\/live-nantes-monaco-coupe-gambardella\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gambardella : Regardez le replay de Nantes-Monaco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gambardella : Regardez le replay de Nantes-Monaco - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/12\/live-nantes-monaco-coupe-gambardella\/","og_locale":"fr_FR","og_type":"article","og_title":"Gambardella : Regardez le replay de Nantes-Monaco - La Diagonale","og_description":"Ce dimanche (14h30), les U19 de l&rsquo;AS Monaco affrontent le FC Nantes en quart de finale de la Coupe Gambardella. Le match est retransmis en direct et comment\u00e9 sur la plateforme audiovisuelle de la FFF. Vous pouvez le regarder directement sur le lecteur ci-dessous. Composition : Schulz &#8211; Sitou, Eser, Valm\u00e9, Sinat\u00e9 &#8211; Benama, Cabral, [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/12\/live-nantes-monaco-coupe-gambardella\/","og_site_name":"La Diagonale","article_published_time":"2023-03-12T13:25:31+00:00","article_modified_time":"2023-03-12T15:27:38+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/02\/sinate-gambardella.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/02\/sinate-gambardella.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/12\/live-nantes-monaco-coupe-gambardella\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/12\/live-nantes-monaco-coupe-gambardella\/","name":"Gambardella : Regardez le replay de Nantes-Monaco - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2023-03-12T13:25:31+00:00","dateModified":"2023-03-12T15:27:38+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/12\/live-nantes-monaco-coupe-gambardella\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/12\/live-nantes-monaco-coupe-gambardella\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/12\/live-nantes-monaco-coupe-gambardella\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Gambardella : Regardez le replay de Nantes-Monaco"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/10591"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=10591"}],"version-history":[{"count":11,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/10591\/revisions"}],"predecessor-version":[{"id":10610,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/10591\/revisions\/10610"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=10591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=10591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=10591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}