{"id":10803,"date":"2023-03-19T08:36:00","date_gmt":"2023-03-19T07:36:00","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=10803"},"modified":"2023-03-19T03:41:52","modified_gmt":"2023-03-19T02:41:52","slug":"plus-de-temps-a-perdre","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/19\/plus-de-temps-a-perdre\/","title":{"rendered":"Plus de temps \u00e0 perdre"},"content":{"rendered":"\n\n\n<p><strong>Face \u00e0 une \u00e9quipe de l&rsquo;AC Ajaccio qu&rsquo;ils avaient martyris\u00e9e lors du match aller il y a deux mois, les Mon\u00e9gasques vont essayer de se relancer ce dimanche (13h) dans un championnat qui n&rsquo;attend pas.<\/strong><\/p>\n\n\n\n<h4 class=\"wp-block-heading has-vivid-red-color has-text-color\" style=\"font-style:normal;font-weight:400;text-transform:uppercase\">forme et enjeux<\/h4>\n\n\n\n<p>Apr\u00e8s un d\u00e9but d&rsquo;ann\u00e9e men\u00e9 tambour battant, le club de la Principaut\u00e9 conna\u00eet une p\u00e9riode de creux en cette fin d&rsquo;hiver. Les joueurs de Philippe Clement sont toujours en qu\u00eate d&rsquo;une victoire apr\u00e8s quatre rencontres infructueuses toutes comp\u00e9titions confondues (<em>trois d\u00e9faites et un nul<\/em>). Une s\u00e9rie plut\u00f4t rare dans la saison de l&rsquo;AS Monaco, puisque cela n&rsquo;est arriv\u00e9 qu&rsquo;\u00e0 deux reprises et la derni\u00e8re fois c&rsquo;\u00e9tait en octobre 2022 (<em>deux d\u00e9faites et deux nuls<\/em>). Mais cela ne semble pas inqui\u00e9ter du c\u00f4t\u00e9 de La Turbie, o\u00f9 l&rsquo;on travaille encore sereinement. En conf\u00e9rence de presse, Vanderson a maintenu que la confiance \u00e9tait toujours bien pr\u00e9sente dans les rangs as\u00e9mistes mais elle semble toutefois s&rsquo;\u00eatre quelque peu \u00e9tiol\u00e9e depuis le coup re\u00e7u avec l&rsquo;\u00e9limination contre Leverkusen. D\u00e9fensivement, les Mon\u00e9gasques commettent des erreurs qu&rsquo;ils payent <em>cash <\/em>depuis plusieurs rencontres, \u00e0 l&rsquo;image de son vice-capitaine Axel Disasi.<\/p>\n\n\n\n<p>Ce n&rsquo;est pourtant pas dans ce domaine que l&rsquo;ASM excelle mais davantage pour son efficacit\u00e9 devant la cage adverse. Seul hic : les Rouge et Blanc ont \u00e9t\u00e9 muets \u00e0 deux reprises, contre Nice (0-3) et contre Reims (0-1), ce qui dit tout de la mauvaise passe que Monaco traverse, apr\u00e8s avoir port\u00e9 \u00e0 34 matchs le nombre de victoires cons\u00e9cutives en Ligue 1 avec au moins un but inscrit. Retrouver la victoire face \u00e0 Ajaccio, ce sera aussi retrouver le chemin du but. Wissam Ben Yedder et ses co\u00e9quipiers n&rsquo;ont \u00e9videmment pas perdu la recette, d&rsquo;autant plus qu&rsquo;ils se sont montr\u00e9s dangereux contre Reims et ont touch\u00e9 le poteau \u00e0 deux reprises, mais ils vont avoir besoin de revenir aux fondamentaux, comme l&rsquo;a indiqu\u00e9 Philippe Clement en conf\u00e9rence de presse : \u00ab&nbsp;<em>On doit faire une reboot sur les bonnes choses qui le sont moins en ce moment. On a fait une grande s\u00e9rie et maintenant les r\u00e9sultats sont moins bons. On doit retrouver certaines bases.<\/em>&nbsp;\u00bb<\/p>\n\n\n\n<p>M\u00eame si la diff\u00e9rence entre Monaco et Ajaccio est grande, il faudra quand m\u00eame arriver \u00e0 se tirer de l&rsquo;orni\u00e8re sans Aleksandr Golovin. Le Russe n&rsquo;a rat\u00e9 qu&rsquo;un seul match cette saison, lors de la premi\u00e8re journ\u00e9e de championnat contre Strasbourg, et il p\u00e8se pour beaucoup dans la force de frappe offensive de l&rsquo;\u00e9quipe princi\u00e8re, malgr\u00e9 quelques prestations en de\u00e7\u00e0 r\u00e9cemment. Philippe Clement ne pourra pas non plus aligner Ismail Jakobs comme milieu gauche, poste auquel il entre souvent en cours de jeu puisque l&rsquo;international s\u00e9n\u00e9galais est lui aussi forfait. Il va en revanche retrouver Ben Seghir, m\u00eame si son \u00e9tat de sant\u00e9 lui a encore jou\u00e9 des tours dans la semaine, Camara et Maripan. De bonne augure alors que le sprint final a d\u00e9j\u00e0 d\u00e9but\u00e9 et que Lens a remis la machine en route, car Monaco ne peut pas se permettre de perdre des points en cours de route comme \u00e0 Troyes. <\/p>\n\n\n\n<h4 class=\"wp-block-heading has-vivid-red-color has-text-color\" style=\"font-style:normal;font-weight:400;text-transform:uppercase\">L&rsquo;adversaire<\/h4>\n\n\n\n<p>Depuis leur visite au stade Louis-II, d&rsquo;o\u00f9 ils sont repartis avec une valise (<em>7-1, le 15 janvier<\/em>), les choses ne se sont pas beaucoup am\u00e9lior\u00e9es du c\u00f4t\u00e9 d&rsquo;Ajaccio. Le club corse continue de lutter pour sa survie et le maintien mais ne parvient toujours pas \u00e0 cr\u00e9er une s\u00e9rie positive comme ont pu conna\u00eetre certains de ses concurrents directs. Sur les huit rencontres disput\u00e9es depuis le match aller contre l&rsquo;ASM, les Ajacciens ont gagn\u00e9 deux fois et perdu six fois. Dans leur malheur, il y a tout de m\u00eame une l\u00e9g\u00e8re note d&rsquo;espoir puisque les Ajacciens ont battu deux \u00e9quipes en zone rouge r\u00e9cemment, Angers et Troyes, et tous leurs succ\u00e8s cette saison, \u00e0 l&rsquo;exception de Marseille, l&rsquo;ont \u00e9t\u00e9 contre des \u00e9quipes qui ne d\u00e9passent pas la 15<sup>e<\/sup> place du classement.<\/p>\n\n\n\n<p>Contre les petits dont il fait partie, Ajaccio arrive \u00e0 bien man\u0153uvrer, ce qui, dans la perspective du maintien, peut constituer une donn\u00e9e importante. Surtout, les hommes d&rsquo;Olivier Pantaloni ne sont pas largu\u00e9s au classement pour esp\u00e9rer rester en Ligue 1, malgr\u00e9 une 19<sup>e<\/sup> place peu avenante. Avec 21 points, ils ne sont qu&rsquo;\u00e0 deux longueurs de Strasbourg, Auxerre et Brest. Si la marge est mince, les possibilit\u00e9s de se maintenir sont bien r\u00e9elles, d&rsquo;autant plus que les rencontres de la phase retour contre ces formations sont encore \u00e0 venir. Mais Ajaccio devra enfin trouver une solidit\u00e9 d\u00e9fensive, ce qui faisait sa force l&rsquo;an dernier en Ligue 2, avec seulement 19 buts encaiss\u00e9s. Cette saison, ils ont encaiss\u00e9 48 buts, ce qui en fait une des pires d\u00e9fenses de l&rsquo;\u00e9lite, et ils n&rsquo;ont surtout r\u00e9alis\u00e9 qu&rsquo;un seul <em>clean sheet<\/em>. C&rsquo;\u00e9tait lors de la deuxi\u00e8me journ\u00e9e contre Lens. <\/p>\n\n\n\n<h4 class=\"has-vivid-red-color has-text-color\" style=\"font-style:normal;font-weight:400;text-transform:uppercase\">Le joueur \u00e0 surveiller<\/h4>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:30% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" width=\"700\" height=\"700\" src=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/03\/74073.jpg\" alt=\"\" class=\"wp-image-10787 size-full\"\/><\/figure><div class=\"wp-block-media-text__content\">\n<p style=\"font-size:16px\"><strong>Mounaim El Idrissy &#8211; 24 ans &#8211; Attaquant<\/strong><\/p>\n\n\n\n<p style=\"font-size:15px\">Si la formation ajaccienne peut compter sur son meilleur buteur, Youcef Bela\u00efli (6 buts, dont un contre Monaco), elle aura un autre joueur capable de faire la diff\u00e9rence. Mounaim El Idrissy a inscrit cinq buts cette saison, notamment lors des deux derni\u00e8res victoire de l&rsquo;ACA contre Angers et Troyes. C&rsquo;est aussi le joueur qui tente le plus (45 tirs), m\u00eame si son ratio de tirs cadr\u00e9s n&rsquo;est pas tr\u00e8s \u00e9lev\u00e9e (37,8). En revanche, El Idrissy commet beaucoup de fautes (61, record de l&rsquo;\u00e9quipe) et prend de nombreux cartons jaunes. Une donn\u00e9e \u00e0 prendre en compte.<\/p>\n<\/div><\/div>\n\n\n\n<h4 class=\"wp-block-heading has-vivid-red-color has-text-color\" style=\"font-style:normal;font-weight:400;text-transform:uppercase\">L&rsquo;historique<\/h4>\n\n\n\n<p>Contrairement aux confrontations \u00e0 domicile, o\u00f9 Monaco a nettement la main par rapport \u00e0 Ajaccio, le rapport de force en Corse est compl\u00e8tement \u00e0 l\u2019\u00e9quilibre entre les deux formations. Sur les huit rencontres d\u00e9j\u00e0 disput\u00e9es en Corse, quatre d\u2019entre elles sont revenues aux locaux et quatre aux Mon\u00e9gasques. Il n\u2019y a donc jamais eu de partage des points entre Monaco et Ajaccio.<\/p>\n\n\n\n<p>Sur les cinq derni\u00e8res confrontations, l\u2019avantage est \u00e0 l\u2019ASM, avec trois victoires. Mais difficile de pouvoir parler v\u00e9ritablement d\u2019une tendance. Le tout dernier affrontement entre les deux clubs remonte \u00e0 la saison 2013-2014 (victoire 1-4), et les quatre pr\u00e9c\u00e9dentes encore au d\u00e9but des ann\u00e9es 2000. En 2014, Dimitar Berbatov avait notamment inscrit un doubl\u00e9.<\/p>\n\n\n\n<div style=\"position:relative;padding-bottom:56.25%;height:0;overflow:hidden;\"> <iframe loading=\"lazy\" style=\"width:100%;height:100%;position:absolute;left:0px;top:0px;overflow:hidden\" type=\"text\/html\" src=\"https:\/\/www.dailymotion.com\/embed\/video\/x6qcold?autoplay=1\" allowfullscreen=\"\" title=\"Dailymotion Video Player\" allow=\"autoplay\" width=\"100%\" height=\"100%\" frameborder=\"0\"> <\/iframe> <\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Les cinq derni\u00e8res confrontations en Ligue 1 au stade Fran\u00e7ois-Coty<\/h4>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">Saison 2013-2014<\/td><td class=\"has-text-align-center\" data-align=\"center\">J35<\/td><td class=\"has-text-align-right\" data-align=\"right\">Ajaccio<\/td><td class=\"has-text-align-center\" data-align=\"center\">1-4<\/td><td class=\"has-text-align-left\" data-align=\"left\">Monaco<\/td><td>\ud83d\udfe2<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Saison 2005-2006<\/td><td class=\"has-text-align-center\" data-align=\"center\">J31<\/td><td class=\"has-text-align-right\" data-align=\"right\">Ajaccio<\/td><td class=\"has-text-align-center\" data-align=\"center\">1-0<\/td><td class=\"has-text-align-left\" data-align=\"left\">Monaco<\/td><td>\ud83d\udd34<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Saison 2004-2005<\/td><td class=\"has-text-align-center\" data-align=\"center\">J31<\/td><td class=\"has-text-align-right\" data-align=\"right\">Ajaccio<\/td><td class=\"has-text-align-center\" data-align=\"center\">3-0<\/td><td class=\"has-text-align-left\" data-align=\"left\">Monaco<\/td><td>\ud83d\udd34<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Saison 2003-2004<\/td><td class=\"has-text-align-center\" data-align=\"center\">J13<\/td><td class=\"has-text-align-right\" data-align=\"right\">Ajaccio<\/td><td class=\"has-text-align-center\" data-align=\"center\">0-1<\/td><td class=\"has-text-align-left\" data-align=\"left\">Monaco<\/td><td>\ud83d\udfe2<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Saison 2002-2003<\/td><td class=\"has-text-align-center\" data-align=\"center\">J33<\/td><td class=\"has-text-align-right\" data-align=\"right\">Ajaccio<\/td><td class=\"has-text-align-center\" data-align=\"center\">2-4<\/td><td class=\"has-text-align-left\" data-align=\"left\">Monaco<\/td><td>\ud83d\udfe2<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h4 class=\"wp-block-heading has-vivid-red-color has-text-color\" style=\"font-style:normal;font-weight:400;text-transform:uppercase\">Les groupes<\/h4>\n\n\n\n<p><strong>Le groupe ajaccien<\/strong><\/p>\n\n\n\n<ul><li>Gardiens : Leroy, Sollacaro.<\/li><li>D\u00e9fenseurs : Alphonse, Avinel, Diallo, Gonzalez, Mayembo, Vidal, Youssouf.<\/li><li>Milieux : Barreto, Bayala, Chabrolle, Coutadeur, Nouri.<\/li><li>Attaquants : Bela\u00efli, Djitt\u00e9, El Idrissy, Levine, Spadanuda, Soumano.<\/li><\/ul>\n\n\n\n<p><em>Absents :<\/em> Kon\u00e9, Mangani, Marchetti, Touzghar (bless\u00e9s)<\/p>\n\n\n\n<p><strong>Le groupe mon\u00e9gasque<\/strong><\/p>\n\n\n\n<ul><li><strong>Gardiens :<\/strong> Didillon, Lienard, N\u00fcbel.<\/li><li><strong>D\u00e9fenseurs :<\/strong> Aguilar, C. Henrique, Disasi, Maripan, Matsima, Okou, Sarr, Vanderson.<\/li><li><strong>Milieux :<\/strong> Akliouche, Ben Seghir, Camara, Diatta, Diop, Fofana, G. Martins, Matazo, Minamino.<\/li><li><strong>Attaquants :<\/strong> Ben Yedder, Boadu, Embolo.<\/li><\/ul>\n\n\n\n<p><em>Absents :<\/em> Volland (bless\u00e9), Golovin, Jakobs (g\u00eane), J. Lucas, Magassa (choix).<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-vivid-red-color has-text-color\" style=\"font-style:normal;font-weight:400;text-transform:uppercase\">La d\u00e9claration<\/h4>\n\n\n\n<blockquote class=\"wp-block-quote is-style-default\"><p>\u00ab&nbsp;<em>Vous me connaissez, je ne pense jamais que nous sommes favoris. Les joueurs sont tr\u00e8s conscients que l\u2019on doit gagner et que c\u2019est un environnement tr\u00e8s chaud, avec beaucoup de passion, contre une \u00e9quipe qui joue pour le maintien, qui lutte sur chaque action, sur chaque duel, pour chaque point. On doit \u00eatre pr\u00eats pour \u00e7a, \u00eatre forts dans les duels et faire des bonnes choses avec ballon. Les joueurs savent que c\u2019est sp\u00e9cial de jouer en Corse.<\/em> \u00bb<\/p><cite>Philippe Clement<\/cite><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Face \u00e0 une \u00e9quipe de l&rsquo;AC Ajaccio qu&rsquo;ils avaient martyris\u00e9e lors du match aller il y a deux mois, les Mon\u00e9gasques vont essayer de se relancer ce dimanche (13h) dans un championnat qui n&rsquo;attend pas. forme et enjeux Apr\u00e8s un d\u00e9but d&rsquo;ann\u00e9e men\u00e9 tambour battant, le club de la Principaut\u00e9 conna\u00eet une p\u00e9riode de creux [&#8230;]\n","protected":false},"author":2,"featured_media":10789,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,6],"tags":[443,86,206,94],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Plus de temps \u00e0 perdre - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/19\/plus-de-temps-a-perdre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plus de temps \u00e0 perdre - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Face \u00e0 une \u00e9quipe de l&rsquo;AC Ajaccio qu&rsquo;ils avaient martyris\u00e9e lors du match aller il y a deux mois, les Mon\u00e9gasques vont essayer de se relancer ce dimanche (13h) dans un championnat qui n&rsquo;attend pas. forme et enjeux Apr\u00e8s un d\u00e9but d&rsquo;ann\u00e9e men\u00e9 tambour battant, le club de la Principaut\u00e9 conna\u00eet une p\u00e9riode de creux [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/19\/plus-de-temps-a-perdre\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-19T07:36:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-19T02:41:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/03\/asmaca.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/03\/asmaca.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/19\/plus-de-temps-a-perdre\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/19\/plus-de-temps-a-perdre\/\",\"name\":\"Plus de temps \u00e0 perdre - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2023-03-19T07:36:00+00:00\",\"dateModified\":\"2023-03-19T02:41:52+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/19\/plus-de-temps-a-perdre\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/19\/plus-de-temps-a-perdre\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/19\/plus-de-temps-a-perdre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plus de temps \u00e0 perdre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plus de temps \u00e0 perdre - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/19\/plus-de-temps-a-perdre\/","og_locale":"fr_FR","og_type":"article","og_title":"Plus de temps \u00e0 perdre - La Diagonale","og_description":"Face \u00e0 une \u00e9quipe de l&rsquo;AC Ajaccio qu&rsquo;ils avaient martyris\u00e9e lors du match aller il y a deux mois, les Mon\u00e9gasques vont essayer de se relancer ce dimanche (13h) dans un championnat qui n&rsquo;attend pas. forme et enjeux Apr\u00e8s un d\u00e9but d&rsquo;ann\u00e9e men\u00e9 tambour battant, le club de la Principaut\u00e9 conna\u00eet une p\u00e9riode de creux [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/19\/plus-de-temps-a-perdre\/","og_site_name":"La Diagonale","article_published_time":"2023-03-19T07:36:00+00:00","article_modified_time":"2023-03-19T02:41:52+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/03\/asmaca.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/03\/asmaca.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/19\/plus-de-temps-a-perdre\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/19\/plus-de-temps-a-perdre\/","name":"Plus de temps \u00e0 perdre - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2023-03-19T07:36:00+00:00","dateModified":"2023-03-19T02:41:52+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/19\/plus-de-temps-a-perdre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/19\/plus-de-temps-a-perdre\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/19\/plus-de-temps-a-perdre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Plus de temps \u00e0 perdre"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/10803"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=10803"}],"version-history":[{"count":4,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/10803\/revisions"}],"predecessor-version":[{"id":10810,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/10803\/revisions\/10810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media\/10789"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=10803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=10803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=10803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}