{"id":11046,"date":"2023-03-27T13:56:24","date_gmt":"2023-03-27T11:56:24","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=11046"},"modified":"2023-03-27T13:56:27","modified_gmt":"2023-03-27T11:56:27","slug":"benama-et-la-france-u18-corriges-par-lallemagne","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/27\/benama-et-la-france-u18-corriges-par-lallemagne\/","title":{"rendered":"Benama et la France U18 corrig\u00e9s par l\u2019Allemagne"},"content":{"rendered":"\n\n\n<p>Mayssam Benama et l\u2019\u00e9quipe de France U18 se sont inclin\u00e9s face \u00e0 l\u2019Allemagne (0-3), lors de la deuxi\u00e8me manche amicale entre les deux \u00e9quipes. Le Mon\u00e9gasque a \u00e9t\u00e9 titularis\u00e9 par Bernard Diom\u00e8de en tant que pointe basse d\u2019un milieu \u00e0 trois.<\/p>\n\n\n\n<p>S\u2019il a montr\u00e9 de bonnes orientations dans le jeu et de l&rsquo;activit\u00e9, il n\u2019a pas eu l\u2019influence qu\u2019on lui conna\u00eet avec l\u2019ASM et il a \u00e9t\u00e9 un peu en retard pour intervenir sur l\u2019ouverture du score allemande. Le jeune milieu de terrain as\u00e9miste a disput\u00e9 66 minutes avant d\u2019\u00eatre remplac\u00e9.<\/p>\n\n\n\n<p>Pour ce rassemblement, Benama a pu ajouter deux s\u00e9lections avec les U18, portant ainsi son total \u00e0 quatre s\u00e9lections avec les Bleuets. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mayssam Benama et l\u2019\u00e9quipe de France U18 se sont inclin\u00e9s face \u00e0 l\u2019Allemagne (0-3), lors de la deuxi\u00e8me manche amicale entre les deux \u00e9quipes. Le Mon\u00e9gasque a \u00e9t\u00e9 titularis\u00e9 par Bernard Diom\u00e8de en tant que pointe basse d\u2019un milieu \u00e0 trois. S\u2019il a montr\u00e9 de bonnes orientations dans le jeu et de l&rsquo;activit\u00e9, il n\u2019a [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[76,86,78,453,116],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Benama et la France U18 corrig\u00e9s par l\u2019Allemagne - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/27\/benama-et-la-france-u18-corriges-par-lallemagne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Benama et la France U18 corrig\u00e9s par l\u2019Allemagne - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Mayssam Benama et l\u2019\u00e9quipe de France U18 se sont inclin\u00e9s face \u00e0 l\u2019Allemagne (0-3), lors de la deuxi\u00e8me manche amicale entre les deux \u00e9quipes. Le Mon\u00e9gasque a \u00e9t\u00e9 titularis\u00e9 par Bernard Diom\u00e8de en tant que pointe basse d\u2019un milieu \u00e0 trois. S\u2019il a montr\u00e9 de bonnes orientations dans le jeu et de l&rsquo;activit\u00e9, il n\u2019a [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/27\/benama-et-la-france-u18-corriges-par-lallemagne\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-27T11:56:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-27T11:56:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/12\/benama.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/12\/benama.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/27\/benama-et-la-france-u18-corriges-par-lallemagne\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/27\/benama-et-la-france-u18-corriges-par-lallemagne\/\",\"name\":\"Benama et la France U18 corrig\u00e9s par l\u2019Allemagne - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2023-03-27T11:56:24+00:00\",\"dateModified\":\"2023-03-27T11:56:27+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/27\/benama-et-la-france-u18-corriges-par-lallemagne\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/27\/benama-et-la-france-u18-corriges-par-lallemagne\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/27\/benama-et-la-france-u18-corriges-par-lallemagne\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Benama et la France U18 corrig\u00e9s par l\u2019Allemagne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Benama et la France U18 corrig\u00e9s par l\u2019Allemagne - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/27\/benama-et-la-france-u18-corriges-par-lallemagne\/","og_locale":"fr_FR","og_type":"article","og_title":"Benama et la France U18 corrig\u00e9s par l\u2019Allemagne - La Diagonale","og_description":"Mayssam Benama et l\u2019\u00e9quipe de France U18 se sont inclin\u00e9s face \u00e0 l\u2019Allemagne (0-3), lors de la deuxi\u00e8me manche amicale entre les deux \u00e9quipes. Le Mon\u00e9gasque a \u00e9t\u00e9 titularis\u00e9 par Bernard Diom\u00e8de en tant que pointe basse d\u2019un milieu \u00e0 trois. S\u2019il a montr\u00e9 de bonnes orientations dans le jeu et de l&rsquo;activit\u00e9, il n\u2019a [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/27\/benama-et-la-france-u18-corriges-par-lallemagne\/","og_site_name":"La Diagonale","article_published_time":"2023-03-27T11:56:24+00:00","article_modified_time":"2023-03-27T11:56:27+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/12\/benama.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/12\/benama.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/27\/benama-et-la-france-u18-corriges-par-lallemagne\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/27\/benama-et-la-france-u18-corriges-par-lallemagne\/","name":"Benama et la France U18 corrig\u00e9s par l\u2019Allemagne - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2023-03-27T11:56:24+00:00","dateModified":"2023-03-27T11:56:27+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/27\/benama-et-la-france-u18-corriges-par-lallemagne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/27\/benama-et-la-france-u18-corriges-par-lallemagne\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/27\/benama-et-la-france-u18-corriges-par-lallemagne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Benama et la France U18 corrig\u00e9s par l\u2019Allemagne"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/11046"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=11046"}],"version-history":[{"count":1,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/11046\/revisions"}],"predecessor-version":[{"id":11047,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/11046\/revisions\/11047"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=11046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=11046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=11046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}