{"id":11168,"date":"2023-03-31T23:39:37","date_gmt":"2023-03-31T21:39:37","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=11168"},"modified":"2023-03-31T23:39:39","modified_gmt":"2023-03-31T21:39:39","slug":"antonetti-monaco-la-meilleure-equipe-de-l1-avec-paris","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/31\/antonetti-monaco-la-meilleure-equipe-de-l1-avec-paris\/","title":{"rendered":"Antonetti : \u00ab&nbsp;Monaco, la meilleure \u00e9quipe de L1 avec Paris&nbsp;\u00bb"},"content":{"rendered":"\n<p>L\u2019entra\u00eeneur de Strasbourg, Fr\u00e9d\u00e9ric Antonetti, a annonc\u00e9 que le d\u00e9placement au stade Louis-II contre selon lui, la meilleure \u00e9quipe du championnat avec Paris, sera compliqu\u00e9 : \u00ab\u00a0<em>Je consid\u00e8re Monaco comme \u00e9tant l\u2019\u00e9quipe du championnat qui a le plus de talent avec Paris. Donc ce sera un match difficile bien s\u00fbr, techniquement c\u2019est avec Paris la meilleure \u00e9quipe du championnat, capable de faire de tr\u00e8s, tr\u00e8s belles choses. Il va falloir faire un gros match pour obtenir un r\u00e9sultat.<\/em>\u00a0\u00bb<\/p>\n\n\n\n<p>Si l\u2019ASM a la deuxi\u00e8me meilleure attaque de Ligue 1, elle a aussi une d\u00e9fense moyenne : \u00ab\u00a0<em>C\u2019est son style de jeu<\/em>, a expliqu\u00e9 Antonetti. <em>Elle cr\u00e9e beaucoup de probl\u00e8mes aux adversaires, donc ils s\u2019ouvrent un petit peu. C\u2019est une \u00e9quipe qui a vraiment beaucoup de tr\u00e8s, tr\u00e8s bons joueurs et un niveau technique tr\u00e8s \u00e9lev\u00e9.<\/em>\u00a0\u00bb Questionn\u00e9 sur le manque de ferveur en Principaut\u00e9, le coach de la formation alsacienne a indiqu\u00e9 pr\u00e9f\u00e9rer les matchs dans des stades avec plus d\u2019ambiance : \u00ab\u00a0<em>Les joueurs trouvent une motivation, c\u2019est beaucoup plus int\u00e9ressant.<\/em>\u00a0\u00bb<\/p>\n\n\n\n<p>Cela ne l\u2019a pas emp\u00each\u00e9 de se rem\u00e9morer des souvenirs de derbys enflamm\u00e9s lorsqu\u2019il \u00e9tait entra\u00eeneur de l\u2019OGC Nice au milieu des ann\u00e9es 2000 : \u00ab\u00a0<em>Ces derni\u00e8res ann\u00e9es, les matchs contre Monaco \u00e9taient un peu plus difficiles.\u00a0Avec Nice j\u2019ai eu des r\u00e9sultats au Louis-II, des beaux derbys, \u00e7a je me rappelle. Une demi-finale de Coupe de la Ligue qu\u2019on a gagn\u00e9 l\u00e0-bas (0-1, le 7 f\u00e9vrier 2006). Le stade \u00e9tait rouge et noir, je me rappelle tr\u00e8s, tr\u00e8s bien de cette demi-finale, c\u2019\u00e9tait jour de f\u00eate pour Nice.<\/em> \u00bb<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>L\u2019entra\u00eeneur de Strasbourg, Fr\u00e9d\u00e9ric Antonetti, a annonc\u00e9 que le d\u00e9placement au stade Louis-II contre selon lui, la meilleure \u00e9quipe du championnat avec Paris, sera compliqu\u00e9 : \u00ab\u00a0Je consid\u00e8re Monaco comme \u00e9tant l\u2019\u00e9quipe du championnat qui a le plus de talent avec Paris. Donc ce sera un match difficile bien s\u00fbr, techniquement c\u2019est avec Paris la [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[86,469,94,432],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Antonetti : \u00ab&nbsp;Monaco, la meilleure \u00e9quipe de L1 avec Paris&nbsp;\u00bb - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/31\/antonetti-monaco-la-meilleure-equipe-de-l1-avec-paris\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Antonetti : \u00ab&nbsp;Monaco, la meilleure \u00e9quipe de L1 avec Paris&nbsp;\u00bb - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"L\u2019entra\u00eeneur de Strasbourg, Fr\u00e9d\u00e9ric Antonetti, a annonc\u00e9 que le d\u00e9placement au stade Louis-II contre selon lui, la meilleure \u00e9quipe du championnat avec Paris, sera compliqu\u00e9 : \u00ab\u00a0Je consid\u00e8re Monaco comme \u00e9tant l\u2019\u00e9quipe du championnat qui a le plus de talent avec Paris. Donc ce sera un match difficile bien s\u00fbr, techniquement c\u2019est avec Paris la [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/31\/antonetti-monaco-la-meilleure-equipe-de-l1-avec-paris\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-31T21:39:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-31T21:39:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/03\/antonetti.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/03\/antonetti.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/31\/antonetti-monaco-la-meilleure-equipe-de-l1-avec-paris\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/31\/antonetti-monaco-la-meilleure-equipe-de-l1-avec-paris\/\",\"name\":\"Antonetti : \u00ab&nbsp;Monaco, la meilleure \u00e9quipe de L1 avec Paris&nbsp;\u00bb - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2023-03-31T21:39:37+00:00\",\"dateModified\":\"2023-03-31T21:39:39+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/31\/antonetti-monaco-la-meilleure-equipe-de-l1-avec-paris\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/31\/antonetti-monaco-la-meilleure-equipe-de-l1-avec-paris\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/31\/antonetti-monaco-la-meilleure-equipe-de-l1-avec-paris\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Antonetti : \u00ab&nbsp;Monaco, la meilleure \u00e9quipe de L1 avec Paris&nbsp;\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Antonetti : \u00ab&nbsp;Monaco, la meilleure \u00e9quipe de L1 avec Paris&nbsp;\u00bb - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/31\/antonetti-monaco-la-meilleure-equipe-de-l1-avec-paris\/","og_locale":"fr_FR","og_type":"article","og_title":"Antonetti : \u00ab&nbsp;Monaco, la meilleure \u00e9quipe de L1 avec Paris&nbsp;\u00bb - La Diagonale","og_description":"L\u2019entra\u00eeneur de Strasbourg, Fr\u00e9d\u00e9ric Antonetti, a annonc\u00e9 que le d\u00e9placement au stade Louis-II contre selon lui, la meilleure \u00e9quipe du championnat avec Paris, sera compliqu\u00e9 : \u00ab\u00a0Je consid\u00e8re Monaco comme \u00e9tant l\u2019\u00e9quipe du championnat qui a le plus de talent avec Paris. Donc ce sera un match difficile bien s\u00fbr, techniquement c\u2019est avec Paris la [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/31\/antonetti-monaco-la-meilleure-equipe-de-l1-avec-paris\/","og_site_name":"La Diagonale","article_published_time":"2023-03-31T21:39:37+00:00","article_modified_time":"2023-03-31T21:39:39+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/03\/antonetti.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/03\/antonetti.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/31\/antonetti-monaco-la-meilleure-equipe-de-l1-avec-paris\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/31\/antonetti-monaco-la-meilleure-equipe-de-l1-avec-paris\/","name":"Antonetti : \u00ab&nbsp;Monaco, la meilleure \u00e9quipe de L1 avec Paris&nbsp;\u00bb - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2023-03-31T21:39:37+00:00","dateModified":"2023-03-31T21:39:39+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/31\/antonetti-monaco-la-meilleure-equipe-de-l1-avec-paris\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/31\/antonetti-monaco-la-meilleure-equipe-de-l1-avec-paris\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/03\/31\/antonetti-monaco-la-meilleure-equipe-de-l1-avec-paris\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Antonetti : \u00ab&nbsp;Monaco, la meilleure \u00e9quipe de L1 avec Paris&nbsp;\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/11168"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=11168"}],"version-history":[{"count":1,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/11168\/revisions"}],"predecessor-version":[{"id":11170,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/11168\/revisions\/11170"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=11168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=11168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=11168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}