{"id":12030,"date":"2023-04-30T10:45:33","date_gmt":"2023-04-30T08:45:33","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=12030"},"modified":"2023-04-30T10:45:37","modified_gmt":"2023-04-30T08:45:37","slug":"monaco-et-benama-negocient-pour-un-contrat-pro-mais","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2023\/04\/30\/monaco-et-benama-negocient-pour-un-contrat-pro-mais\/","title":{"rendered":"Monaco et Benama n\u00e9gocient pour un contrat pro mais\u2026"},"content":{"rendered":"\n<p>Mayssam Benama signera-t-il son premier contrat professionnel avec l\u2019AS Monaco ? D\u2019apr\u00e8s <em>Nice-Matin,<\/em> les discussions \u00e0 ce sujet sont en cours entre les deux parties depuis le d\u00e9but de l\u2019ann\u00e9e et elles se sont intensifi\u00e9es r\u00e9cemment. Toutefois, le milieu de terrain, <a href=\"https:\/\/www.ladiagonale.net\/index.php\/2023\/04\/29\/monaco-remporte-la-coupe-gambardella\/\">r\u00e9cent vainqueur de la Coupe Gambardella<\/a> o\u00f9 il a \u00e9t\u00e9 un des grands acteurs de ce succ\u00e8s, se laisserait le temps de la r\u00e9flexion et selon le quotidien azur\u00e9en, attendrait de la consid\u00e9ration de la part du club de la Principaut\u00e9.<\/p>\n\n\n\n<p>En outre, Benama est fortement courtis\u00e9. L&rsquo;international fran\u00e7ais U18 serait suivi par Marseille, Nantes, Reims ou encore Toulouse en Ligue 1, mais \u00e9galement pas des \u00e9curies de Bundesliga et d&rsquo;Italie. Certaines de ces \u00e9quipes lui promettrait une place dans leur groupe pro et c&rsquo;est \u00e9galement ce qu&rsquo;attendrait le milieu de terrain de 18 ans de la part de l&rsquo;AS Monaco avant de s&rsquo;engager pleinement avec son club formateur. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mayssam Benama signera-t-il son premier contrat professionnel avec l\u2019AS Monaco ? D\u2019apr\u00e8s Nice-Matin, les discussions \u00e0 ce sujet sont en cours entre les deux parties depuis le d\u00e9but de l\u2019ann\u00e9e et elles se sont intensifi\u00e9es r\u00e9cemment. Toutefois, le milieu de terrain, r\u00e9cent vainqueur de la Coupe Gambardella o\u00f9 il a \u00e9t\u00e9 un des grands acteurs [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[76,86,314,453],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Monaco et Benama n\u00e9gocient pour un contrat pro mais\u2026 - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2023\/04\/30\/monaco-et-benama-negocient-pour-un-contrat-pro-mais\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Monaco et Benama n\u00e9gocient pour un contrat pro mais\u2026 - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Mayssam Benama signera-t-il son premier contrat professionnel avec l\u2019AS Monaco ? D\u2019apr\u00e8s Nice-Matin, les discussions \u00e0 ce sujet sont en cours entre les deux parties depuis le d\u00e9but de l\u2019ann\u00e9e et elles se sont intensifi\u00e9es r\u00e9cemment. Toutefois, le milieu de terrain, r\u00e9cent vainqueur de la Coupe Gambardella o\u00f9 il a \u00e9t\u00e9 un des grands acteurs [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2023\/04\/30\/monaco-et-benama-negocient-pour-un-contrat-pro-mais\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-30T08:45:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-30T08:45:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/12\/benama.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/12\/benama.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/04\/30\/monaco-et-benama-negocient-pour-un-contrat-pro-mais\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/04\/30\/monaco-et-benama-negocient-pour-un-contrat-pro-mais\/\",\"name\":\"Monaco et Benama n\u00e9gocient pour un contrat pro mais\u2026 - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2023-04-30T08:45:33+00:00\",\"dateModified\":\"2023-04-30T08:45:37+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/04\/30\/monaco-et-benama-negocient-pour-un-contrat-pro-mais\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2023\/04\/30\/monaco-et-benama-negocient-pour-un-contrat-pro-mais\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/04\/30\/monaco-et-benama-negocient-pour-un-contrat-pro-mais\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Monaco et Benama n\u00e9gocient pour un contrat pro mais\u2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Monaco et Benama n\u00e9gocient pour un contrat pro mais\u2026 - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2023\/04\/30\/monaco-et-benama-negocient-pour-un-contrat-pro-mais\/","og_locale":"fr_FR","og_type":"article","og_title":"Monaco et Benama n\u00e9gocient pour un contrat pro mais\u2026 - La Diagonale","og_description":"Mayssam Benama signera-t-il son premier contrat professionnel avec l\u2019AS Monaco ? D\u2019apr\u00e8s Nice-Matin, les discussions \u00e0 ce sujet sont en cours entre les deux parties depuis le d\u00e9but de l\u2019ann\u00e9e et elles se sont intensifi\u00e9es r\u00e9cemment. Toutefois, le milieu de terrain, r\u00e9cent vainqueur de la Coupe Gambardella o\u00f9 il a \u00e9t\u00e9 un des grands acteurs [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2023\/04\/30\/monaco-et-benama-negocient-pour-un-contrat-pro-mais\/","og_site_name":"La Diagonale","article_published_time":"2023-04-30T08:45:33+00:00","article_modified_time":"2023-04-30T08:45:37+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/12\/benama.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/12\/benama.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/04\/30\/monaco-et-benama-negocient-pour-un-contrat-pro-mais\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2023\/04\/30\/monaco-et-benama-negocient-pour-un-contrat-pro-mais\/","name":"Monaco et Benama n\u00e9gocient pour un contrat pro mais\u2026 - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2023-04-30T08:45:33+00:00","dateModified":"2023-04-30T08:45:37+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/04\/30\/monaco-et-benama-negocient-pour-un-contrat-pro-mais\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2023\/04\/30\/monaco-et-benama-negocient-pour-un-contrat-pro-mais\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/04\/30\/monaco-et-benama-negocient-pour-un-contrat-pro-mais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Monaco et Benama n\u00e9gocient pour un contrat pro mais\u2026"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/12030"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=12030"}],"version-history":[{"count":2,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/12030\/revisions"}],"predecessor-version":[{"id":12032,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/12030\/revisions\/12032"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=12030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=12030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=12030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}