{"id":1387,"date":"2022-07-20T18:20:49","date_gmt":"2022-07-20T16:20:49","guid":{"rendered":"https:\/\/www.ladiagonale.net\/index.php\/2022\/07\/20\/le-geste-de-matazo-envers-embolo\/"},"modified":"2022-07-26T14:18:29","modified_gmt":"2022-07-26T12:18:29","slug":"le-geste-de-matazo-envers-embolo","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2022\/07\/20\/le-geste-de-matazo-envers-embolo\/","title":{"rendered":"Le geste de Matazo envers Embolo"},"content":{"rendered":"<p>Cette saison, Breel Embolo portera la tunique \u00e0 la diagonale flanqu\u00e9e du num\u00e9ro 36. Un num\u00e9ro pourtant d\u00e9volu \u00e0 Eliot Matazo, comme cela \u00e9tait le cas lors du dernier match amical face \u00e0 l\u2019Inter Milan. En conf\u00e9rence de presse, la nouvelle recrue a r\u00e9v\u00e9l\u00e9 qu\u2019Eliot Matazo avait gracieusement accept\u00e9 de laisser le num\u00e9ro 36 pour lui.<\/p>\n<p>\u00ab *Je veux dire un merci particulier \u00e0 Eliot qui a fait un grand geste en me laissant le num\u00e9ro 36, ce qui prouve que ce groupe a de grandes qualit\u00e9s humaines* \u00bb, a comment\u00e9 Embolo. De ce que l\u2019on peut voir sur la boutique officielle du club, Matazo devrait r\u00e9cup\u00e9rer le num\u00e9ro 15, vacant depuis la saison 2018-2019. Le dernier \u00e0 l\u2019avoir port\u00e9 lors d&rsquo;une saison compl\u00e8te \u00e9tait Adrien Silva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cette saison, Breel Embolo portera la tunique \u00e0 la diagonale flanqu\u00e9e du num\u00e9ro 36. Un num\u00e9ro pourtant d\u00e9volu \u00e0 Eliot Matazo, comme cela \u00e9tait le cas lors du dernier match amical face \u00e0 l\u2019Inter Milan. En conf\u00e9rence de presse, la nouvelle recrue a r\u00e9v\u00e9l\u00e9 qu\u2019Eliot Matazo avait gracieusement accept\u00e9 de laisser le num\u00e9ro 36 pour [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le geste de Matazo envers Embolo - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/07\/20\/le-geste-de-matazo-envers-embolo\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le geste de Matazo envers Embolo - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Cette saison, Breel Embolo portera la tunique \u00e0 la diagonale flanqu\u00e9e du num\u00e9ro 36. Un num\u00e9ro pourtant d\u00e9volu \u00e0 Eliot Matazo, comme cela \u00e9tait le cas lors du dernier match amical face \u00e0 l\u2019Inter Milan. En conf\u00e9rence de presse, la nouvelle recrue a r\u00e9v\u00e9l\u00e9 qu\u2019Eliot Matazo avait gracieusement accept\u00e9 de laisser le num\u00e9ro 36 pour [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/07\/20\/le-geste-de-matazo-envers-embolo\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-20T16:20:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-26T12:18:29+00:00\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/07\/20\/le-geste-de-matazo-envers-embolo\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/07\/20\/le-geste-de-matazo-envers-embolo\/\",\"name\":\"Le geste de Matazo envers Embolo - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2022-07-20T16:20:49+00:00\",\"dateModified\":\"2022-07-26T12:18:29+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/07\/20\/le-geste-de-matazo-envers-embolo\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2022\/07\/20\/le-geste-de-matazo-envers-embolo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/07\/20\/le-geste-de-matazo-envers-embolo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le geste de Matazo envers Embolo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le geste de Matazo envers Embolo - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2022\/07\/20\/le-geste-de-matazo-envers-embolo\/","og_locale":"fr_FR","og_type":"article","og_title":"Le geste de Matazo envers Embolo - La Diagonale","og_description":"Cette saison, Breel Embolo portera la tunique \u00e0 la diagonale flanqu\u00e9e du num\u00e9ro 36. Un num\u00e9ro pourtant d\u00e9volu \u00e0 Eliot Matazo, comme cela \u00e9tait le cas lors du dernier match amical face \u00e0 l\u2019Inter Milan. En conf\u00e9rence de presse, la nouvelle recrue a r\u00e9v\u00e9l\u00e9 qu\u2019Eliot Matazo avait gracieusement accept\u00e9 de laisser le num\u00e9ro 36 pour [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/07\/20\/le-geste-de-matazo-envers-embolo\/","og_site_name":"La Diagonale","article_published_time":"2022-07-20T16:20:49+00:00","article_modified_time":"2022-07-26T12:18:29+00:00","author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/07\/20\/le-geste-de-matazo-envers-embolo\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/07\/20\/le-geste-de-matazo-envers-embolo\/","name":"Le geste de Matazo envers Embolo - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2022-07-20T16:20:49+00:00","dateModified":"2022-07-26T12:18:29+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/07\/20\/le-geste-de-matazo-envers-embolo\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2022\/07\/20\/le-geste-de-matazo-envers-embolo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/07\/20\/le-geste-de-matazo-envers-embolo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Le geste de Matazo envers Embolo"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/1387"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=1387"}],"version-history":[{"count":1,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/1387\/revisions"}],"predecessor-version":[{"id":1426,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/1387\/revisions\/1426"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=1387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=1387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=1387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}