{"id":17524,"date":"2023-10-27T16:28:36","date_gmt":"2023-10-27T14:28:36","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=17524"},"modified":"2023-10-27T16:28:40","modified_gmt":"2023-10-27T14:28:40","slug":"hutter-defendre-notre-place-de-leader","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2023\/10\/27\/hutter-defendre-notre-place-de-leader\/","title":{"rendered":"H\u00fctter : \u00ab\u00a0D\u00e9fendre notre place de leader\u00a0\u00bb"},"content":{"rendered":"\n<p>Dimanche, Monaco va affronter un gros morceau du championnat avec un d\u00e9placement \u00e0 Lille. Bien que peu impressionnant en ce d\u00e9but de saison, les Lillois pointent tout de m\u00eame au quatri\u00e8me rang, ce qui pousse Adi H\u00fctter \u00e0 s\u2019en m\u00e9fier : \u00ab\u00a0<em>Nous comptons 20 points apr\u00e8s neuf matches et dimanche, nous avons un match tr\u00e8s difficile contre un club historique du championnat. Ils sont quatri\u00e8mes et en bonne forme en ce moment. Leur style de jeu n\u2019est pas similaire au n\u00f4tre, mais ils veulent jouer vers l\u2019avant et marquer beaucoup de buts, donc je pense que ce sera un match ouvert et j\u2019ai h\u00e2te d\u2019y \u00eatre.<\/em>\u00a0\u00bb<\/p>\n\n\n\n<p>Pour l\u2019entra\u00eeneur autrichien, il y a un statut \u00e0 d\u00e9fendre, m\u00eame s\u2019il a conscience que beaucoup d\u2019\u00e9quipes r\u00eavent de faire tomber le leader du championnat : \u00ab\u00a0<em>Nous voulons d\u00e9fendre cette place de leader, mais chaque semaine tous les clubs veulent nous battre. Nous savons que nous pouvons battre tout le monde, mais nous devons nous m\u00e9fier, car si l\u2019on ne joue pas \u00e0 notre meilleur niveau, on peut perdre des matches. Lille sera un gros challenge.<\/em>\u00a0\u00bb Sur le bon niveau de performance de l\u2019\u00e9quipe, H\u00fctter n\u2019est pas surpris, m\u00eame si selon lui, le fait d\u2019\u00eatre premier pouvait \u00ab\u00a0<em>\u00eatre une surprise<\/em>\u00a0\u00bb.<\/p>\n\n\n\n<h3>La 7<sup>e<\/sup> meilleure attaque d\u2019Europe<\/h3>\n\n\n\n<p>Si Monaco marche aussi fort en ce d\u00e9but de saison, c\u2019est principalement gr\u00e2ce \u00e0 son attaque, la septi\u00e8me meilleure d\u2019Europe : \u00ab <em>Nous avons de bons joueurs n\u2019est-ce pas ? (sourire) Pour nos offensifs, notre style de jeu aide beaucoup. Nous d\u00e9fendons plus haut que d\u2019autres \u00e9quipes et cela nous permet d\u2019\u00eatre plus proches du but adverse. Dans ma carri\u00e8re, j\u2019ai toujours cherch\u00e9 \u00e0 jouer vers l\u2019avant et marquer beaucoup de buts. Le plus important c\u2019est de finir avec un but de plus que l\u2019adversaire et avec une victoire. Nous pouvons faire encore mieux, avec les joueurs que nous avons.<\/em>\u00a0\u00bb<\/p>\n\n\n\n<p>H\u00fctter esp\u00e8re continuer \u00e0 marquer autant de buts jusqu\u2019\u00e0 la fin de la saison : \u00ab\u00a0<em>C\u2019est notre style de vouloir toujours jouer vers l\u2019avant. Nous avons trois v\u00e9ritables finisseurs en attaque, quatre joueurs intelligents en num\u00e9ro 10 qui savent marquer et faire des passes d\u00e9cisives. Cela rend l\u2019analyse difficile pour nos adversaires et j\u2019esp\u00e8re que nous pourrons garder cette dynamique jusqu\u2019au bout, mais cela demande de travailler tr\u00e8s dur tout le temps.<\/em>\u00a0\u00bb<\/p>\n\n\n\n<h3>H\u00fctter salue les performances d\u2019Akliouche, Jakobs et Diatta<\/h3>\n\n\n\n<p>Le coach mon\u00e9gasque a aussi compliment\u00e9 Maghnes Akliouche, <a href=\"https:\/\/www.ladiagonale.net\/index.php\/2023\/10\/26\/a-lille-des-choix-a-faire-en-attaque\/\">qui monte en r\u00e9gime depuis quelques semaines<\/a> : \u00ab\u00a0<em>Maghnes est tr\u00e8s bon en ce moment et il a fait plusieurs pas dans la bonne direction et nous aide beaucoup. (\u2026) Je le connaissais d\u00e9j\u00e0, j\u2019avais vu des matches de la saison derni\u00e8re. C\u2019est un joueur tr\u00e8s talentueux. Il s\u2019est tr\u00e8s bien entra\u00een\u00e9 depuis plusieurs semaines et il a m\u00e9rit\u00e9 d\u2019\u00eatre dans le onze de d\u00e9part contre Marseille. Mais nous avons aussi Golovin qui a marqu\u00e9 et fait des passes d\u00e9cisives, Taki (Minamino) qui a \u00e9t\u00e9 le joueur du mois d\u2019ao\u00fbt. Eliesse (Ben Seghir) veut aussi revenir dans l\u2019\u00e9quipe et apporte de la concurrence. Ce n\u2019est pas \u00e9vident de choisir la composition de d\u00e9part.<\/em>\u00a0\u00bb<\/p>\n\n\n\n<p>H\u00fctter a aussi salu\u00e9 l\u2019apport des entrants en cours de jeu ainsi que ceux d\u2019Ismail Jakobs et Kr\u00e9pin Diatta, qui remplacent Vanderson et Caio Henrique, et pas forc\u00e9ment \u00e0 leur poste de pr\u00e9dilection, en particulier pour Diatta : \u00ab\u00a0<em>Tous les joueurs qui entrent en jeu apportent beaucoup, parfois avec des buts ou des passes d\u00e9cisives. Par exemple, nos deux br\u00e9siliens Caio Henrique et Vanderson \u00e9taient tout le temps titulaires et leurs rempla\u00e7ants Jakobs et Diatta ont fait de tr\u00e8s bons matches contre Reims et Metz. J\u2019aime ces joueurs. Au d\u00e9but, ils n\u2019\u00e9taient pas m\u00e9contents, mais ils voulaient jouer, et quand ils ont pu, ils ont aid\u00e9 l\u2019\u00e9quipe. J\u2019aime cette mentalit\u00e9.<\/em>\u00a0\u00bb<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Dimanche, Monaco va affronter un gros morceau du championnat avec un d\u00e9placement \u00e0 Lille. Bien que peu impressionnant en ce d\u00e9but de saison, les Lillois pointent tout de m\u00eame au quatri\u00e8me rang, ce qui pousse Adi H\u00fctter \u00e0 s\u2019en m\u00e9fier : \u00ab\u00a0Nous comptons 20 points apr\u00e8s neuf matches et dimanche, nous avons un match tr\u00e8s [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[576,86,94,246],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>H\u00fctter : \u00ab\u00a0D\u00e9fendre notre place de leader\u00a0\u00bb - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2023\/10\/27\/hutter-defendre-notre-place-de-leader\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"H\u00fctter : \u00ab\u00a0D\u00e9fendre notre place de leader\u00a0\u00bb - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Dimanche, Monaco va affronter un gros morceau du championnat avec un d\u00e9placement \u00e0 Lille. Bien que peu impressionnant en ce d\u00e9but de saison, les Lillois pointent tout de m\u00eame au quatri\u00e8me rang, ce qui pousse Adi H\u00fctter \u00e0 s\u2019en m\u00e9fier : \u00ab\u00a0Nous comptons 20 points apr\u00e8s neuf matches et dimanche, nous avons un match tr\u00e8s [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2023\/10\/27\/hutter-defendre-notre-place-de-leader\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-27T14:28:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-27T14:28:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/07\/hu\u0308tter.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/07\/hu\u0308tter.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/10\/27\/hutter-defendre-notre-place-de-leader\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/10\/27\/hutter-defendre-notre-place-de-leader\/\",\"name\":\"H\u00fctter : \u00ab\u00a0D\u00e9fendre notre place de leader\u00a0\u00bb - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2023-10-27T14:28:36+00:00\",\"dateModified\":\"2023-10-27T14:28:40+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/10\/27\/hutter-defendre-notre-place-de-leader\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2023\/10\/27\/hutter-defendre-notre-place-de-leader\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/10\/27\/hutter-defendre-notre-place-de-leader\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"H\u00fctter : \u00ab\u00a0D\u00e9fendre notre place de leader\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"H\u00fctter : \u00ab\u00a0D\u00e9fendre notre place de leader\u00a0\u00bb - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2023\/10\/27\/hutter-defendre-notre-place-de-leader\/","og_locale":"fr_FR","og_type":"article","og_title":"H\u00fctter : \u00ab\u00a0D\u00e9fendre notre place de leader\u00a0\u00bb - La Diagonale","og_description":"Dimanche, Monaco va affronter un gros morceau du championnat avec un d\u00e9placement \u00e0 Lille. Bien que peu impressionnant en ce d\u00e9but de saison, les Lillois pointent tout de m\u00eame au quatri\u00e8me rang, ce qui pousse Adi H\u00fctter \u00e0 s\u2019en m\u00e9fier : \u00ab\u00a0Nous comptons 20 points apr\u00e8s neuf matches et dimanche, nous avons un match tr\u00e8s [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2023\/10\/27\/hutter-defendre-notre-place-de-leader\/","og_site_name":"La Diagonale","article_published_time":"2023-10-27T14:28:36+00:00","article_modified_time":"2023-10-27T14:28:40+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/07\/hu\u0308tter.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/07\/hu\u0308tter.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/10\/27\/hutter-defendre-notre-place-de-leader\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2023\/10\/27\/hutter-defendre-notre-place-de-leader\/","name":"H\u00fctter : \u00ab\u00a0D\u00e9fendre notre place de leader\u00a0\u00bb - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2023-10-27T14:28:36+00:00","dateModified":"2023-10-27T14:28:40+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/10\/27\/hutter-defendre-notre-place-de-leader\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2023\/10\/27\/hutter-defendre-notre-place-de-leader\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/10\/27\/hutter-defendre-notre-place-de-leader\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"H\u00fctter : \u00ab\u00a0D\u00e9fendre notre place de leader\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/17524"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=17524"}],"version-history":[{"count":1,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/17524\/revisions"}],"predecessor-version":[{"id":17525,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/17524\/revisions\/17525"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=17524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=17524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=17524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}