{"id":18146,"date":"2023-11-13T09:19:00","date_gmt":"2023-11-13T08:19:00","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=18146"},"modified":"2023-11-13T04:41:41","modified_gmt":"2023-11-13T03:41:41","slug":"les-u17-accrochent-saint-etienne-apres-une-remontee-folle","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2023\/11\/13\/les-u17-accrochent-saint-etienne-apres-une-remontee-folle\/","title":{"rendered":"Les U17 accrochent Saint-\u00c9tienne apr\u00e8s une remont\u00e9e folle"},"content":{"rendered":"\n\n\n<p>Les U17 de l&rsquo;AS Monaco et de l&rsquo;AS Saint-\u00c9tienne se sont s\u00e9par\u00e9s dimanche matin sur un score de parit\u00e9 mais au terme d&rsquo;un match riche en buts (4-4). Les hommes de Manu Dos Santos ont montr\u00e9 beaucoup de caract\u00e8re pour remonter une situation qui semblait bien compromise face au leader de la poule D. La rencontre a d\u00e9marr\u00e9 tambour battant avec une ouverture du score st\u00e9phanoise (0-1, 4<sup>e<\/sup>) \u00e0 laquelle Wassim Moussaoui, d\u00e9j\u00e0 buteur la semaine pr\u00e9c\u00e9dente, a r\u00e9pondu sans attendre (1-1, 6<sup>e<\/sup>).<\/p>\n\n\n\n<p>Les Verts, dominateurs lors du premier acte, ont ensuite marqu\u00e9 deux fois coup sur coup (20<sup>e<\/sup>, 31<sup>e<\/sup>) avant que Far\u00e8s Boujlifa ne r\u00e9duise l&rsquo;\u00e9cart juste avant la mi-temps (2-3, 44<sup>e<\/sup>). Mais les As\u00e9mistes seront de nouveaux cueillis \u00e0 froid avant le retour aux vestiaires, par un quatri\u00e8me but st\u00e9phanois dans le temps additionnel du premier acte (45<sup>e<\/sup>+2). Men\u00e9 de deux buts, Monaco a r\u00e9agi en fin de match, avec des r\u00e9alisations d&rsquo;Hamidou Kant\u00e9 (79<sup>e<\/sup>) et de Yannick Dodo (81<sup>e<\/sup>), permettant \u00e0 l&rsquo;ASM d&rsquo;accrocher un nul presque inesp\u00e9r\u00e9.<\/p>\n\n\n\n<p>Dans cette poule tr\u00e8s serr\u00e9e, l&rsquo;ASM pointe d\u00e9sormais au quatri\u00e8me rang et voit l&rsquo;Olympique lyonnais lui passer devant gr\u00e2ce \u00e0 la diff\u00e9rence de buts particuli\u00e8re. Dimanche (14h30), Monaco affrontera le Gaz\u00e9lec Ajaccio sur l&rsquo;\u00eele corse.<\/p>\n\n\n\n<div class=\"wp-container-1 wp-block-buttons\">\n<div class=\"wp-block-button is-style-outline\"><a class=\"wp-block-button__link has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background\" href=\"https:\/\/www.ladiagonale.net\/index.php\/event\/monaco-u17-saint-etienne-u17-2\/\" target=\"_blank\" rel=\"noreferrer noopener\">La feuille de match<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Les U17 de l&rsquo;AS Monaco et de l&rsquo;AS Saint-\u00c9tienne se sont s\u00e9par\u00e9s dimanche matin sur un score de parit\u00e9 mais au terme d&rsquo;un match riche en buts (4-4). Les hommes de Manu Dos Santos ont montr\u00e9 beaucoup de caract\u00e8re pour remonter une situation qui semblait bien compromise face au leader de la poule D. La [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[76,86,130],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les U17 accrochent Saint-\u00c9tienne apr\u00e8s une remont\u00e9e folle - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2023\/11\/13\/les-u17-accrochent-saint-etienne-apres-une-remontee-folle\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les U17 accrochent Saint-\u00c9tienne apr\u00e8s une remont\u00e9e folle - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Les U17 de l&rsquo;AS Monaco et de l&rsquo;AS Saint-\u00c9tienne se sont s\u00e9par\u00e9s dimanche matin sur un score de parit\u00e9 mais au terme d&rsquo;un match riche en buts (4-4). Les hommes de Manu Dos Santos ont montr\u00e9 beaucoup de caract\u00e8re pour remonter une situation qui semblait bien compromise face au leader de la poule D. La [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2023\/11\/13\/les-u17-accrochent-saint-etienne-apres-une-remontee-folle\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-13T08:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-13T03:41:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/09\/dodo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/09\/dodo.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/11\/13\/les-u17-accrochent-saint-etienne-apres-une-remontee-folle\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/11\/13\/les-u17-accrochent-saint-etienne-apres-une-remontee-folle\/\",\"name\":\"Les U17 accrochent Saint-\u00c9tienne apr\u00e8s une remont\u00e9e folle - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2023-11-13T08:19:00+00:00\",\"dateModified\":\"2023-11-13T03:41:41+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/11\/13\/les-u17-accrochent-saint-etienne-apres-une-remontee-folle\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2023\/11\/13\/les-u17-accrochent-saint-etienne-apres-une-remontee-folle\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/11\/13\/les-u17-accrochent-saint-etienne-apres-une-remontee-folle\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les U17 accrochent Saint-\u00c9tienne apr\u00e8s une remont\u00e9e folle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les U17 accrochent Saint-\u00c9tienne apr\u00e8s une remont\u00e9e folle - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2023\/11\/13\/les-u17-accrochent-saint-etienne-apres-une-remontee-folle\/","og_locale":"fr_FR","og_type":"article","og_title":"Les U17 accrochent Saint-\u00c9tienne apr\u00e8s une remont\u00e9e folle - La Diagonale","og_description":"Les U17 de l&rsquo;AS Monaco et de l&rsquo;AS Saint-\u00c9tienne se sont s\u00e9par\u00e9s dimanche matin sur un score de parit\u00e9 mais au terme d&rsquo;un match riche en buts (4-4). Les hommes de Manu Dos Santos ont montr\u00e9 beaucoup de caract\u00e8re pour remonter une situation qui semblait bien compromise face au leader de la poule D. La [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2023\/11\/13\/les-u17-accrochent-saint-etienne-apres-une-remontee-folle\/","og_site_name":"La Diagonale","article_published_time":"2023-11-13T08:19:00+00:00","article_modified_time":"2023-11-13T03:41:41+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/09\/dodo.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/09\/dodo.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/11\/13\/les-u17-accrochent-saint-etienne-apres-une-remontee-folle\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2023\/11\/13\/les-u17-accrochent-saint-etienne-apres-une-remontee-folle\/","name":"Les U17 accrochent Saint-\u00c9tienne apr\u00e8s une remont\u00e9e folle - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2023-11-13T08:19:00+00:00","dateModified":"2023-11-13T03:41:41+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/11\/13\/les-u17-accrochent-saint-etienne-apres-une-remontee-folle\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2023\/11\/13\/les-u17-accrochent-saint-etienne-apres-une-remontee-folle\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/11\/13\/les-u17-accrochent-saint-etienne-apres-une-remontee-folle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Les U17 accrochent Saint-\u00c9tienne apr\u00e8s une remont\u00e9e folle"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/18146"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=18146"}],"version-history":[{"count":3,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/18146\/revisions"}],"predecessor-version":[{"id":18149,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/18146\/revisions\/18149"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=18146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=18146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=18146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}