{"id":19123,"date":"2023-12-20T14:10:10","date_gmt":"2023-12-20T13:10:10","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=19123"},"modified":"2023-12-20T14:10:12","modified_gmt":"2023-12-20T13:10:12","slug":"martinez-novell-monaco-nest-pas-stereotype","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2023\/12\/20\/martinez-novell-monaco-nest-pas-stereotype\/","title":{"rendered":"Martinez Novell : \u00ab&nbsp;Monaco n\u2019est pas st\u00e9r\u00e9otyp\u00e9&nbsp;\u00bb"},"content":{"rendered":"\n<p>Carles Martinez Novell\u00a0s&rsquo;est exprim\u00e9 sur l&rsquo;AS Monaco, alors que son \u00e9quipe de Toulouse recevra le club de la Principaut\u00e9 ce mercredi au Stadium. L&rsquo;entra\u00eeneur des Violets appr\u00e9cie Monaco et le style d&rsquo;Adi H\u00fctter : \u00ab\u00a0<em>J\u2019aime beaucoup cette \u00e9quipe de Monaco. Elle est tr\u00e8s attractive avec un jeu tr\u00e8s offensif et beaucoup de pressing. Il faudra \u00eatre pr\u00eat et concentr\u00e9 sur chaque action car ils sont tr\u00e8s forts et tr\u00e8s rapides dans toutes leurs s\u00e9quences de jeu.<\/em>\u00a0\u00bb\u00a0<\/p>\n\n\n\n<p>Pour l&rsquo;Espagnol, l&rsquo;ASM n&rsquo;est pas forc\u00e9ment l&rsquo;\u00e9quipe pr\u00e9visible qui a eu du mal \u00e0 faire des diff\u00e9rences sur ces derni\u00e8res semaines : \u00ab<em>\u00a0Il y a beaucoup de libert\u00e9 quand ils jouent. Ce n\u2019est pas st\u00e9r\u00e9otyp\u00e9 mais dynamique pour pouvoir surprendre. Ils ont beaucoup de talents avec des joueurs capables de casser des lignes. Cela va nous demander beaucoup de vigilance.\u00a0<\/em>\u00bb<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Carles Martinez Novell\u00a0s&rsquo;est exprim\u00e9 sur l&rsquo;AS Monaco, alors que son \u00e9quipe de Toulouse recevra le club de la Principaut\u00e9 ce mercredi au Stadium. L&rsquo;entra\u00eeneur des Violets appr\u00e9cie Monaco et le style d&rsquo;Adi H\u00fctter : \u00ab\u00a0J\u2019aime beaucoup cette \u00e9quipe de Monaco. Elle est tr\u00e8s attractive avec un jeu tr\u00e8s offensif et beaucoup de pressing. Il faudra [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[86,746,230],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Martinez Novell : \u00ab&nbsp;Monaco n\u2019est pas st\u00e9r\u00e9otyp\u00e9&nbsp;\u00bb - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2023\/12\/20\/martinez-novell-monaco-nest-pas-stereotype\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Martinez Novell : \u00ab&nbsp;Monaco n\u2019est pas st\u00e9r\u00e9otyp\u00e9&nbsp;\u00bb - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Carles Martinez Novell\u00a0s&rsquo;est exprim\u00e9 sur l&rsquo;AS Monaco, alors que son \u00e9quipe de Toulouse recevra le club de la Principaut\u00e9 ce mercredi au Stadium. L&rsquo;entra\u00eeneur des Violets appr\u00e9cie Monaco et le style d&rsquo;Adi H\u00fctter : \u00ab\u00a0J\u2019aime beaucoup cette \u00e9quipe de Monaco. Elle est tr\u00e8s attractive avec un jeu tr\u00e8s offensif et beaucoup de pressing. Il faudra [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2023\/12\/20\/martinez-novell-monaco-nest-pas-stereotype\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-20T13:10:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-20T13:10:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/12\/1200-L-toulouse-carles-martinez-novell-trs-heureux-aprs-le-match-nul-contre-le-psg.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/12\/1200-L-toulouse-carles-martinez-novell-trs-heureux-aprs-le-match-nul-contre-le-psg.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/12\/20\/martinez-novell-monaco-nest-pas-stereotype\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/12\/20\/martinez-novell-monaco-nest-pas-stereotype\/\",\"name\":\"Martinez Novell : \u00ab&nbsp;Monaco n\u2019est pas st\u00e9r\u00e9otyp\u00e9&nbsp;\u00bb - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2023-12-20T13:10:10+00:00\",\"dateModified\":\"2023-12-20T13:10:12+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/12\/20\/martinez-novell-monaco-nest-pas-stereotype\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2023\/12\/20\/martinez-novell-monaco-nest-pas-stereotype\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/12\/20\/martinez-novell-monaco-nest-pas-stereotype\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Martinez Novell : \u00ab&nbsp;Monaco n\u2019est pas st\u00e9r\u00e9otyp\u00e9&nbsp;\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Martinez Novell : \u00ab&nbsp;Monaco n\u2019est pas st\u00e9r\u00e9otyp\u00e9&nbsp;\u00bb - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2023\/12\/20\/martinez-novell-monaco-nest-pas-stereotype\/","og_locale":"fr_FR","og_type":"article","og_title":"Martinez Novell : \u00ab&nbsp;Monaco n\u2019est pas st\u00e9r\u00e9otyp\u00e9&nbsp;\u00bb - La Diagonale","og_description":"Carles Martinez Novell\u00a0s&rsquo;est exprim\u00e9 sur l&rsquo;AS Monaco, alors que son \u00e9quipe de Toulouse recevra le club de la Principaut\u00e9 ce mercredi au Stadium. L&rsquo;entra\u00eeneur des Violets appr\u00e9cie Monaco et le style d&rsquo;Adi H\u00fctter : \u00ab\u00a0J\u2019aime beaucoup cette \u00e9quipe de Monaco. Elle est tr\u00e8s attractive avec un jeu tr\u00e8s offensif et beaucoup de pressing. Il faudra [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2023\/12\/20\/martinez-novell-monaco-nest-pas-stereotype\/","og_site_name":"La Diagonale","article_published_time":"2023-12-20T13:10:10+00:00","article_modified_time":"2023-12-20T13:10:12+00:00","og_image":[{"width":1200,"height":640,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/12\/1200-L-toulouse-carles-martinez-novell-trs-heureux-aprs-le-match-nul-contre-le-psg.jpg","type":"image\/jpeg"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/12\/1200-L-toulouse-carles-martinez-novell-trs-heureux-aprs-le-match-nul-contre-le-psg.jpg","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/12\/20\/martinez-novell-monaco-nest-pas-stereotype\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2023\/12\/20\/martinez-novell-monaco-nest-pas-stereotype\/","name":"Martinez Novell : \u00ab&nbsp;Monaco n\u2019est pas st\u00e9r\u00e9otyp\u00e9&nbsp;\u00bb - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2023-12-20T13:10:10+00:00","dateModified":"2023-12-20T13:10:12+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/12\/20\/martinez-novell-monaco-nest-pas-stereotype\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2023\/12\/20\/martinez-novell-monaco-nest-pas-stereotype\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/12\/20\/martinez-novell-monaco-nest-pas-stereotype\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Martinez Novell : \u00ab&nbsp;Monaco n\u2019est pas st\u00e9r\u00e9otyp\u00e9&nbsp;\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/19123"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=19123"}],"version-history":[{"count":1,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/19123\/revisions"}],"predecessor-version":[{"id":19125,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/19123\/revisions\/19125"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=19123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=19123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=19123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}