{"id":19391,"date":"2024-01-01T16:23:27","date_gmt":"2024-01-01T15:23:27","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=19391"},"modified":"2024-01-01T16:24:20","modified_gmt":"2024-01-01T15:24:20","slug":"minamino-buteur-avec-le-japon-et-convoque-pour-la-coupe-dasie","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2024\/01\/01\/minamino-buteur-avec-le-japon-et-convoque-pour-la-coupe-dasie\/","title":{"rendered":"Minamino buteur avec le Japon et convoqu\u00e9 pour la Coupe d&rsquo;Asie"},"content":{"rendered":"\n\n\n<p>Takumi Minamino a d\u00e9but\u00e9 la nouvelle ann\u00e9e de fa\u00e7on id\u00e9ale. Le milieu offensif de l&rsquo;AS Monaco a inscrit un but avec le Japon, lors de la facile victoire des <em>Samurai Blue<\/em> contre la Tha\u00eflande (5-0), \u00e0 l&rsquo;occasion de la <em>Toyo Tires Cup<\/em>. Entr\u00e9 en jeu \u00e0 la 69<sup>e<\/sup> minute, en rempla\u00e7ant du R\u00e9mois Junya Ito, Minamino a inscrit le cinqui\u00e8me et dernier but de son \u00e9quipe avec le brassard de capitaine au bras. Gr\u00e2ce \u00e0 ce niveau de performance retrouv\u00e9, Minamino disputera la Coupe d&rsquo;Asie des nations du 12 janvier au 10 f\u00e9vrier, dont la liste a \u00e9t\u00e9 d\u00e9voil\u00e9e ce lundi.<\/p>\n\n\n\n<p>Les hommes d&rsquo;Hajime Moriyasu, quadruples vainqueurs de la comp\u00e9tition et grands favoris de cette \u00e9dition 2024, d\u00e9buteront par un match contre le Vi\u00eat Nam le 14 janvier. Puis ils devront ferrailler avec l&rsquo;Iraq et l&rsquo;Indon\u00e9sie les 19 et 24 janvier prochains pour sortir de leur groupe et tenter d&rsquo;aller chercher un cinqui\u00e8me sacre continental. Mais avant, c&rsquo;est un match de pr\u00e9paration contre la Jordanie, le 9 janvier, qui attendront Minamino et ses co\u00e9quipiers.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Takumi Minamino a d\u00e9but\u00e9 la nouvelle ann\u00e9e de fa\u00e7on id\u00e9ale. Le milieu offensif de l&rsquo;AS Monaco a inscrit un but avec le Japon, lors de la facile victoire des Samurai Blue contre la Tha\u00eflande (5-0), \u00e0 l&rsquo;occasion de la Toyo Tires Cup. Entr\u00e9 en jeu \u00e0 la 69e minute, en rempla\u00e7ant du R\u00e9mois Junya Ito, [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[86,758,165,116,164],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Minamino buteur avec le Japon et convoqu\u00e9 pour la Coupe d&#039;Asie - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2024\/01\/01\/minamino-buteur-avec-le-japon-et-convoque-pour-la-coupe-dasie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Minamino buteur avec le Japon et convoqu\u00e9 pour la Coupe d&#039;Asie - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Takumi Minamino a d\u00e9but\u00e9 la nouvelle ann\u00e9e de fa\u00e7on id\u00e9ale. Le milieu offensif de l&rsquo;AS Monaco a inscrit un but avec le Japon, lors de la facile victoire des Samurai Blue contre la Tha\u00eflande (5-0), \u00e0 l&rsquo;occasion de la Toyo Tires Cup. Entr\u00e9 en jeu \u00e0 la 69e minute, en rempla\u00e7ant du R\u00e9mois Junya Ito, [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2024\/01\/01\/minamino-buteur-avec-le-japon-et-convoque-pour-la-coupe-dasie\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-01T15:23:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-01T15:24:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/11\/minamino-japon.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/11\/minamino-japon.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/01\/01\/minamino-buteur-avec-le-japon-et-convoque-pour-la-coupe-dasie\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/01\/01\/minamino-buteur-avec-le-japon-et-convoque-pour-la-coupe-dasie\/\",\"name\":\"Minamino buteur avec le Japon et convoqu\u00e9 pour la Coupe d'Asie - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2024-01-01T15:23:27+00:00\",\"dateModified\":\"2024-01-01T15:24:20+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/01\/01\/minamino-buteur-avec-le-japon-et-convoque-pour-la-coupe-dasie\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2024\/01\/01\/minamino-buteur-avec-le-japon-et-convoque-pour-la-coupe-dasie\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/01\/01\/minamino-buteur-avec-le-japon-et-convoque-pour-la-coupe-dasie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Minamino buteur avec le Japon et convoqu\u00e9 pour la Coupe d&rsquo;Asie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Minamino buteur avec le Japon et convoqu\u00e9 pour la Coupe d'Asie - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2024\/01\/01\/minamino-buteur-avec-le-japon-et-convoque-pour-la-coupe-dasie\/","og_locale":"fr_FR","og_type":"article","og_title":"Minamino buteur avec le Japon et convoqu\u00e9 pour la Coupe d'Asie - La Diagonale","og_description":"Takumi Minamino a d\u00e9but\u00e9 la nouvelle ann\u00e9e de fa\u00e7on id\u00e9ale. Le milieu offensif de l&rsquo;AS Monaco a inscrit un but avec le Japon, lors de la facile victoire des Samurai Blue contre la Tha\u00eflande (5-0), \u00e0 l&rsquo;occasion de la Toyo Tires Cup. Entr\u00e9 en jeu \u00e0 la 69e minute, en rempla\u00e7ant du R\u00e9mois Junya Ito, [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2024\/01\/01\/minamino-buteur-avec-le-japon-et-convoque-pour-la-coupe-dasie\/","og_site_name":"La Diagonale","article_published_time":"2024-01-01T15:23:27+00:00","article_modified_time":"2024-01-01T15:24:20+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/11\/minamino-japon.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/11\/minamino-japon.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/01\/01\/minamino-buteur-avec-le-japon-et-convoque-pour-la-coupe-dasie\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2024\/01\/01\/minamino-buteur-avec-le-japon-et-convoque-pour-la-coupe-dasie\/","name":"Minamino buteur avec le Japon et convoqu\u00e9 pour la Coupe d'Asie - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2024-01-01T15:23:27+00:00","dateModified":"2024-01-01T15:24:20+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/01\/01\/minamino-buteur-avec-le-japon-et-convoque-pour-la-coupe-dasie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2024\/01\/01\/minamino-buteur-avec-le-japon-et-convoque-pour-la-coupe-dasie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/01\/01\/minamino-buteur-avec-le-japon-et-convoque-pour-la-coupe-dasie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Minamino buteur avec le Japon et convoqu\u00e9 pour la Coupe d&rsquo;Asie"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/19391"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=19391"}],"version-history":[{"count":3,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/19391\/revisions"}],"predecessor-version":[{"id":19396,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/19391\/revisions\/19396"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=19391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=19391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=19391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}