{"id":20665,"date":"2024-02-10T09:53:00","date_gmt":"2024-02-10T08:53:00","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=20665"},"modified":"2024-10-25T10:50:12","modified_gmt":"2024-10-25T08:50:12","slug":"monaco-est-a-lequilibre-dans-ses-confrontations-face-a-nice","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2024\/02\/10\/monaco-est-a-lequilibre-dans-ses-confrontations-face-a-nice\/","title":{"rendered":"Monaco est \u00e0 l&rsquo;\u00e9quilibre dans ses confrontations face \u00e0 Nice"},"content":{"rendered":"\n\n\n<p>Dimanche, ce sera la 53<sup>e<\/sup> opposition de l&rsquo;histoire entre Ni\u00e7ois et Mon\u00e9gasques \u00e0 Nice dans le cadre du championnat de premi\u00e8re division. Et pour l&rsquo;instant, et apr\u00e8s autant de matches, les deux clubs font jeu \u00e9gal. Les locaux l&rsquo;ont emport\u00e9 \u00e0 20 reprises dans ce derby, tout comme l&rsquo;ASM, qui a profit\u00e9 de sa victoire acquise \u00e0 l&rsquo;Allianz Riviera le 4 septembre 2022 pour \u00e9galiser son rival. Les points ont \u00e9t\u00e9 partag\u00e9s \u00e0 12 reprises. Point positif, les Rouge et Blanc sont invaincus sur le terrain du Gym depuis trois saisons.<\/p>\n\n\n\n<p>La saison derni\u00e8re, Monaco s&rsquo;\u00e9tait impos\u00e9 d&rsquo;une courte t\u00eate (1-0), gr\u00e2ce \u00e0 un but de la t\u00eate d&rsquo;Embolo, au terme d&rsquo;une rencontre assommante. Les Mon\u00e9gasques avaient \u00e9t\u00e9 convaincants dans le jeu sans ballon, avec une bonne organisation d\u00e9fensive et un bon pressing, mais cela avait \u00e9t\u00e9 plus compliqu\u00e9 en phase de possession, r\u00e9v\u00e9lant une certaine pauvret\u00e9 dans l&rsquo;animation. Mais apr\u00e8s un d\u00e9but de saison cauchemardesque (une victoire en cinq matches), l&rsquo;essentiel \u00e9tait alors ailleurs.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"OGC Nice 0-1 AS Monaco - Ligue 1 - 6\u00e8me journ\u00e9e\" width=\"1020\" height=\"574\" src=\"https:\/\/www.youtube.com\/embed\/auEFARjCcKE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3>Les cinq derni\u00e8res confrontations en Ligue 1 \u00e0 l\u2019Allianz Riviera<\/h3>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">Saison 2022-2023<\/td><td class=\"has-text-align-center\" data-align=\"center\">6<sup>e<\/sup> journ\u00e9e<\/td><td class=\"has-text-align-right\" data-align=\"right\">Nice<\/td><td class=\"has-text-align-center\" data-align=\"center\">0-1<\/td><td><strong>Monaco<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">\ud83d\udfe2<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Saison 2021-2022<\/td><td class=\"has-text-align-center\" data-align=\"center\">6<sup>e<\/sup> journ\u00e9e<\/td><td class=\"has-text-align-right\" data-align=\"right\">Nice<\/td><td class=\"has-text-align-center\" data-align=\"center\">2-2<\/td><td>Monaco<\/td><td class=\"has-text-align-center\" data-align=\"center\">\ud83d\udfe1<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Saison 2020-2021<\/td><td class=\"has-text-align-center\" data-align=\"center\">10<sup>e<\/sup> journ\u00e9e<\/td><td class=\"has-text-align-right\" data-align=\"right\">Nice<\/td><td class=\"has-text-align-center\" data-align=\"center\">1-2<\/td><td><strong>Monaco<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">\ud83d\udfe2<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Saison 2019-2020<\/td><td class=\"has-text-align-center\" data-align=\"center\">28<sup>e<\/sup> journ\u00e9e<\/td><td class=\"has-text-align-right\" data-align=\"right\"><strong>Nice<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">2-1<\/td><td>Monaco<\/td><td class=\"has-text-align-center\" data-align=\"center\">\ud83d\udd34<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Saison 2018-2019<\/td><td class=\"has-text-align-center\" data-align=\"center\">38<sup>e<\/sup> journ\u00e9e<\/td><td class=\"has-text-align-right\" data-align=\"right\"><strong>Nice<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">2-0<\/td><td>Monaco<\/td><td class=\"has-text-align-center\" data-align=\"center\">\ud83d\udd34<\/td><\/tr><\/tbody><\/table><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Dimanche, ce sera la 53e opposition de l&rsquo;histoire entre Ni\u00e7ois et Mon\u00e9gasques \u00e0 Nice dans le cadre du championnat de premi\u00e8re division. Et pour l&rsquo;instant, et apr\u00e8s autant de matches, les deux clubs font jeu \u00e9gal. Les locaux l&rsquo;ont emport\u00e9 \u00e0 20 reprises dans ce derby, tout comme l&rsquo;ASM, qui a profit\u00e9 de sa victoire [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[86,261,94,774],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Monaco est \u00e0 l&#039;\u00e9quilibre dans ses confrontations face \u00e0 Nice - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2024\/02\/10\/monaco-est-a-lequilibre-dans-ses-confrontations-face-a-nice\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Monaco est \u00e0 l&#039;\u00e9quilibre dans ses confrontations face \u00e0 Nice - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Dimanche, ce sera la 53e opposition de l&rsquo;histoire entre Ni\u00e7ois et Mon\u00e9gasques \u00e0 Nice dans le cadre du championnat de premi\u00e8re division. Et pour l&rsquo;instant, et apr\u00e8s autant de matches, les deux clubs font jeu \u00e9gal. Les locaux l&rsquo;ont emport\u00e9 \u00e0 20 reprises dans ce derby, tout comme l&rsquo;ASM, qui a profit\u00e9 de sa victoire [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2024\/02\/10\/monaco-est-a-lequilibre-dans-ses-confrontations-face-a-nice\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-10T08:53:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-25T08:50:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/02\/embolo-nice.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/02\/embolo-nice.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/02\/10\/monaco-est-a-lequilibre-dans-ses-confrontations-face-a-nice\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/02\/10\/monaco-est-a-lequilibre-dans-ses-confrontations-face-a-nice\/\",\"name\":\"Monaco est \u00e0 l'\u00e9quilibre dans ses confrontations face \u00e0 Nice - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2024-02-10T08:53:00+00:00\",\"dateModified\":\"2024-10-25T08:50:12+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/02\/10\/monaco-est-a-lequilibre-dans-ses-confrontations-face-a-nice\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2024\/02\/10\/monaco-est-a-lequilibre-dans-ses-confrontations-face-a-nice\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/02\/10\/monaco-est-a-lequilibre-dans-ses-confrontations-face-a-nice\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Monaco est \u00e0 l&rsquo;\u00e9quilibre dans ses confrontations face \u00e0 Nice\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Monaco est \u00e0 l'\u00e9quilibre dans ses confrontations face \u00e0 Nice - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2024\/02\/10\/monaco-est-a-lequilibre-dans-ses-confrontations-face-a-nice\/","og_locale":"fr_FR","og_type":"article","og_title":"Monaco est \u00e0 l'\u00e9quilibre dans ses confrontations face \u00e0 Nice - La Diagonale","og_description":"Dimanche, ce sera la 53e opposition de l&rsquo;histoire entre Ni\u00e7ois et Mon\u00e9gasques \u00e0 Nice dans le cadre du championnat de premi\u00e8re division. Et pour l&rsquo;instant, et apr\u00e8s autant de matches, les deux clubs font jeu \u00e9gal. Les locaux l&rsquo;ont emport\u00e9 \u00e0 20 reprises dans ce derby, tout comme l&rsquo;ASM, qui a profit\u00e9 de sa victoire [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2024\/02\/10\/monaco-est-a-lequilibre-dans-ses-confrontations-face-a-nice\/","og_site_name":"La Diagonale","article_published_time":"2024-02-10T08:53:00+00:00","article_modified_time":"2024-10-25T08:50:12+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/02\/embolo-nice.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/02\/embolo-nice.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/02\/10\/monaco-est-a-lequilibre-dans-ses-confrontations-face-a-nice\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2024\/02\/10\/monaco-est-a-lequilibre-dans-ses-confrontations-face-a-nice\/","name":"Monaco est \u00e0 l'\u00e9quilibre dans ses confrontations face \u00e0 Nice - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2024-02-10T08:53:00+00:00","dateModified":"2024-10-25T08:50:12+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/02\/10\/monaco-est-a-lequilibre-dans-ses-confrontations-face-a-nice\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2024\/02\/10\/monaco-est-a-lequilibre-dans-ses-confrontations-face-a-nice\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/02\/10\/monaco-est-a-lequilibre-dans-ses-confrontations-face-a-nice\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Monaco est \u00e0 l&rsquo;\u00e9quilibre dans ses confrontations face \u00e0 Nice"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/20665"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=20665"}],"version-history":[{"count":3,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/20665\/revisions"}],"predecessor-version":[{"id":26922,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/20665\/revisions\/26922"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=20665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=20665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=20665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}