{"id":21751,"date":"2024-03-24T21:57:37","date_gmt":"2024-03-24T20:57:37","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=21751"},"modified":"2024-03-24T21:57:41","modified_gmt":"2024-03-24T20:57:41","slug":"les-u17-trop-forts-pour-valence","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2024\/03\/24\/les-u17-trop-forts-pour-valence\/","title":{"rendered":"Les U17 trop forts pour Valence"},"content":{"rendered":"\n\n\n<p>Depuis cinq journ\u00e9es, les U17 de l\u2019AS Monaco alternent entre nuls et victoires. Une semaine apr\u00e8s avoir pris un point sur la pelouse de l\u2019AC Ajaccio, les Mon\u00e9gasques ont donc respect\u00e9 cette alternance en s\u2019imposant largement face \u00e0 l\u2019Olympique de Valence ce dimanche (4-1), pour la 22<sup>e<\/sup> journ\u00e9e de championnat.<\/p>\n\n\n\n<p>En t\u00eate \u00e0 la pause gr\u00e2ce \u00e0 une r\u00e9alisation de Joris Silvente (39<sup>e<\/sup>), les hommes de Manu Dos Santos ont acc\u00e9l\u00e9r\u00e9 en seconde pour se mettre \u00e0 l\u2019abri des Dr\u00f4mois. Ladji Sylla (47<sup>e<\/sup>), Yannick Dodo (77<sup>e<\/sup>) et Nick Mokabakila (89<sup>e<\/sup>) y sont ensuite all\u00e9s de leur but. L\u2019ASM n\u2019a toutefois pas r\u00e9ussi de <em>clean sheet<\/em>, c\u00e9dant en toute fin de rencontre (90<sup>e<\/sup>).<\/p>\n\n\n\n<p>Gr\u00e2ce \u00e0 ce succ\u00e8s, Monaco conserve sa deuxi\u00e8me place, \u00e0 \u00e9galit\u00e9 de points (39) avec le Gaz\u00e9lec Ajaccio, mais met d\u00e9sormais la pression sur Saint-\u00c9tienne, d\u00e9fait pour la deuxi\u00e8me fois de suite. Les Rouge et Blanc reviennent \u00e0 deux points de la t\u00eate et pourraient m\u00eame passer devant dans quinze jours, puisqu\u2019ils iront dans le Forez pour d\u00e9fier le leader st\u00e9phanois, dans une rencontre de la plus haute importance.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis cinq journ\u00e9es, les U17 de l\u2019AS Monaco alternent entre nuls et victoires. Une semaine apr\u00e8s avoir pris un point sur la pelouse de l\u2019AC Ajaccio, les Mon\u00e9gasques ont donc respect\u00e9 cette alternance en s\u2019imposant largement face \u00e0 l\u2019Olympique de Valence ce dimanche (4-1), pour la 22e journ\u00e9e de championnat. En t\u00eate \u00e0 la pause [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[76,86,130],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les U17 trop forts pour Valence - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2024\/03\/24\/les-u17-trop-forts-pour-valence\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les U17 trop forts pour Valence - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Depuis cinq journ\u00e9es, les U17 de l\u2019AS Monaco alternent entre nuls et victoires. Une semaine apr\u00e8s avoir pris un point sur la pelouse de l\u2019AC Ajaccio, les Mon\u00e9gasques ont donc respect\u00e9 cette alternance en s\u2019imposant largement face \u00e0 l\u2019Olympique de Valence ce dimanche (4-1), pour la 22e journ\u00e9e de championnat. En t\u00eate \u00e0 la pause [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2024\/03\/24\/les-u17-trop-forts-pour-valence\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-24T20:57:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-24T20:57:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/03\/ydodo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/03\/ydodo.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/03\/24\/les-u17-trop-forts-pour-valence\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/03\/24\/les-u17-trop-forts-pour-valence\/\",\"name\":\"Les U17 trop forts pour Valence - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2024-03-24T20:57:37+00:00\",\"dateModified\":\"2024-03-24T20:57:41+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/03\/24\/les-u17-trop-forts-pour-valence\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2024\/03\/24\/les-u17-trop-forts-pour-valence\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/03\/24\/les-u17-trop-forts-pour-valence\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les U17 trop forts pour Valence\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les U17 trop forts pour Valence - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2024\/03\/24\/les-u17-trop-forts-pour-valence\/","og_locale":"fr_FR","og_type":"article","og_title":"Les U17 trop forts pour Valence - La Diagonale","og_description":"Depuis cinq journ\u00e9es, les U17 de l\u2019AS Monaco alternent entre nuls et victoires. Une semaine apr\u00e8s avoir pris un point sur la pelouse de l\u2019AC Ajaccio, les Mon\u00e9gasques ont donc respect\u00e9 cette alternance en s\u2019imposant largement face \u00e0 l\u2019Olympique de Valence ce dimanche (4-1), pour la 22e journ\u00e9e de championnat. En t\u00eate \u00e0 la pause [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2024\/03\/24\/les-u17-trop-forts-pour-valence\/","og_site_name":"La Diagonale","article_published_time":"2024-03-24T20:57:37+00:00","article_modified_time":"2024-03-24T20:57:41+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/03\/ydodo.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/03\/ydodo.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/03\/24\/les-u17-trop-forts-pour-valence\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2024\/03\/24\/les-u17-trop-forts-pour-valence\/","name":"Les U17 trop forts pour Valence - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2024-03-24T20:57:37+00:00","dateModified":"2024-03-24T20:57:41+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/03\/24\/les-u17-trop-forts-pour-valence\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2024\/03\/24\/les-u17-trop-forts-pour-valence\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/03\/24\/les-u17-trop-forts-pour-valence\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Les U17 trop forts pour Valence"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/21751"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=21751"}],"version-history":[{"count":1,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/21751\/revisions"}],"predecessor-version":[{"id":21752,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/21751\/revisions\/21752"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=21751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=21751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=21751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}