{"id":22153,"date":"2024-04-07T09:43:00","date_gmt":"2024-04-07T07:43:00","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=22153"},"modified":"2024-04-06T23:46:33","modified_gmt":"2024-04-06T21:46:33","slug":"sur-quelle-chaine-suivre-monaco-rennes","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2024\/04\/07\/sur-quelle-chaine-suivre-monaco-rennes\/","title":{"rendered":"Sur quelle cha\u00eene suivre Monaco-Rennes ?"},"content":{"rendered":"\n\n\n<p>L&rsquo;AS Monaco re\u00e7oit Rennes ce dimanche pour la 28<sup>e<\/sup> journ\u00e9e de Ligue 1. Le coup d&rsquo;envoi du match sera donn\u00e9 \u00e0 17h05 heures au stade Louis-II et sera \u00e0 voir sur <em>Canal+ Foot<\/em>.<\/p>\n\n\n\n<p>David Berger sera le commentateur, \u00e9paul\u00e9 par Sidney Govou comme consultant. Le micro de bord terrain sera confi\u00e9 \u00e0 Laurent Paganelli, tandis que Cl\u00e9ment Gacheny assurera la pr\u00e9sentation de la rencontre.<\/p>\n\n\n\n<p>Source : <a href=\"https:\/\/twitter.com\/EnPleineLucarne\">En Pleine Lucarne<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;AS Monaco re\u00e7oit Rennes ce dimanche pour la 28e journ\u00e9e de Ligue 1. Le coup d&rsquo;envoi du match sera donn\u00e9 \u00e0 17h05 heures au stade Louis-II et sera \u00e0 voir sur Canal+ Foot. David Berger sera le commentateur, \u00e9paul\u00e9 par Sidney Govou comme consultant. Le micro de bord terrain sera confi\u00e9 \u00e0 Laurent Paganelli, tandis [&#8230;]\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[86,706,94,222],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sur quelle cha\u00eene suivre Monaco-Rennes ? - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2024\/04\/07\/sur-quelle-chaine-suivre-monaco-rennes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sur quelle cha\u00eene suivre Monaco-Rennes ? - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;AS Monaco re\u00e7oit Rennes ce dimanche pour la 28e journ\u00e9e de Ligue 1. Le coup d&rsquo;envoi du match sera donn\u00e9 \u00e0 17h05 heures au stade Louis-II et sera \u00e0 voir sur Canal+ Foot. David Berger sera le commentateur, \u00e9paul\u00e9 par Sidney Govou comme consultant. Le micro de bord terrain sera confi\u00e9 \u00e0 Laurent Paganelli, tandis [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2024\/04\/07\/sur-quelle-chaine-suivre-monaco-rennes\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-07T07:43:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-06T21:46:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/01\/canalL1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/01\/canalL1.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/04\/07\/sur-quelle-chaine-suivre-monaco-rennes\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/04\/07\/sur-quelle-chaine-suivre-monaco-rennes\/\",\"name\":\"Sur quelle cha\u00eene suivre Monaco-Rennes ? - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2024-04-07T07:43:00+00:00\",\"dateModified\":\"2024-04-06T21:46:33+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/03fa041acd51875ece8bf97a37252a4d\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/04\/07\/sur-quelle-chaine-suivre-monaco-rennes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2024\/04\/07\/sur-quelle-chaine-suivre-monaco-rennes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/04\/07\/sur-quelle-chaine-suivre-monaco-rennes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sur quelle cha\u00eene suivre Monaco-Rennes ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/03fa041acd51875ece8bf97a37252a4d\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/894b9daaf19cc759b072b6bb09cac5f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/894b9daaf19cc759b072b6bb09cac5f2?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/v2.ladiagonale.net\"],\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sur quelle cha\u00eene suivre Monaco-Rennes ? - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2024\/04\/07\/sur-quelle-chaine-suivre-monaco-rennes\/","og_locale":"fr_FR","og_type":"article","og_title":"Sur quelle cha\u00eene suivre Monaco-Rennes ? - La Diagonale","og_description":"L&rsquo;AS Monaco re\u00e7oit Rennes ce dimanche pour la 28e journ\u00e9e de Ligue 1. Le coup d&rsquo;envoi du match sera donn\u00e9 \u00e0 17h05 heures au stade Louis-II et sera \u00e0 voir sur Canal+ Foot. David Berger sera le commentateur, \u00e9paul\u00e9 par Sidney Govou comme consultant. Le micro de bord terrain sera confi\u00e9 \u00e0 Laurent Paganelli, tandis [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2024\/04\/07\/sur-quelle-chaine-suivre-monaco-rennes\/","og_site_name":"La Diagonale","article_published_time":"2024-04-07T07:43:00+00:00","article_modified_time":"2024-04-06T21:46:33+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/01\/canalL1.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/01\/canalL1.png","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/04\/07\/sur-quelle-chaine-suivre-monaco-rennes\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2024\/04\/07\/sur-quelle-chaine-suivre-monaco-rennes\/","name":"Sur quelle cha\u00eene suivre Monaco-Rennes ? - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2024-04-07T07:43:00+00:00","dateModified":"2024-04-06T21:46:33+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/03fa041acd51875ece8bf97a37252a4d"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/04\/07\/sur-quelle-chaine-suivre-monaco-rennes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2024\/04\/07\/sur-quelle-chaine-suivre-monaco-rennes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/04\/07\/sur-quelle-chaine-suivre-monaco-rennes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Sur quelle cha\u00eene suivre Monaco-Rennes ?"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/03fa041acd51875ece8bf97a37252a4d","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/894b9daaf19cc759b072b6bb09cac5f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/894b9daaf19cc759b072b6bb09cac5f2?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/v2.ladiagonale.net"],"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/22153"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=22153"}],"version-history":[{"count":1,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/22153\/revisions"}],"predecessor-version":[{"id":22154,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/22153\/revisions\/22154"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=22153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=22153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=22153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}