{"id":23669,"date":"2024-06-03T11:53:23","date_gmt":"2024-06-03T09:53:23","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=23669"},"modified":"2024-06-03T12:46:34","modified_gmt":"2024-06-03T10:46:34","slug":"valme-et-benama-reflechiraient-a-un-pret","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2024\/06\/03\/valme-et-benama-reflechiraient-a-un-pret\/","title":{"rendered":"Valme et Benama r\u00e9fl\u00e9chiraient \u00e0 un pr\u00eat"},"content":{"rendered":"\n<p>L\u2019AS Monaco mise beaucoup sur les jeunes issus de sa formation mais gagner sa place chez les professionnels n\u2019est pas une \u00e9vidence pour tous. Alors qu\u2019ils ne sont jamais apparus sur le terrain avec l\u2019\u00e9quipe premi\u00e8re au cours de la saison qui s\u2019est achev\u00e9e, le milieu de terrain Mayssam Benama et le d\u00e9fenseur central Ritchy Valme, tous deux \u00e2g\u00e9s de 19 ans, envisageraient un pr\u00eat en vue de la saison prochaine, comme le r\u00e9v\u00e8le <em>Nice-Matin<\/em>. Cela ne serait toutefois pas la volont\u00e9 des dirigeants mon\u00e9gasques, qui voudraient les incorporer \u00e0 la rotation sur la seconde moiti\u00e9 de l\u2019ann\u00e9e 2024.<\/p>\n\n\n\n<p>Benama aurait notamment fait l\u2019objet d\u2019un int\u00e9r\u00eat de la part de Strasbourg, sans qu\u2019une proposition concr\u00e8te ne soit faite, mais il ne souhaiterait pas \u00eatre vendu, alors que son contrat sur le Rocher court jusqu\u2019en juin 2026. Un pr\u00eat en Ligue 2, dans une \u00e9quipe \u00ab\u00a0<em>joueuse<\/em>\u00a0\u00bb pr\u00e9cise le quotidien azur\u00e9en, ou en <em>Jupiler Pro League<\/em>, l\u2019\u00e9lite du football belge, serait de nature \u00e0 l\u2019int\u00e9resser. Valme est dans la m\u00eame optique que son co\u00e9quipier au sein de l\u2019Academy, mais un \u00e9ventuel pr\u00eat devrait \u00eatre conditionn\u00e9 \u00e0 une prolongation au vu de sa situation contractuelle, puisqu&rsquo;il est li\u00e9 \u00e0 l&rsquo;ASM jusqu&rsquo;en 2025.<\/p>\n\n\n\n<p>La saison derni\u00e8re, les deux joueurs ont d\u00e9pass\u00e9 les 30 matches jou\u00e9s avec le Groupe \u00c9lite mais aussi les U19. Ils ont figur\u00e9 sur le banc des rempla\u00e7ants en Ligue 1 (deux fois pour Benama, cinq pour Valme), m\u00eame si Adi H\u00fctter ne les a pas encore lanc\u00e9s dans le grand bain. Ils avaient toutefois pris part \u00e0 quelques rencontres amicales l&rsquo;\u00e9t\u00e9 dernier (quatre pour Valme, deux pour Benama).<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>L\u2019AS Monaco mise beaucoup sur les jeunes issus de sa formation mais gagner sa place chez les professionnels n\u2019est pas une \u00e9vidence pour tous. Alors qu\u2019ils ne sont jamais apparus sur le terrain avec l\u2019\u00e9quipe premi\u00e8re au cours de la saison qui s\u2019est achev\u00e9e, le milieu de terrain Mayssam Benama et le d\u00e9fenseur central Ritchy [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[86,453,111,693,110],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Valme et Benama r\u00e9fl\u00e9chiraient \u00e0 un pr\u00eat - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2024\/06\/03\/valme-et-benama-reflechiraient-a-un-pret\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Valme et Benama r\u00e9fl\u00e9chiraient \u00e0 un pr\u00eat - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"L\u2019AS Monaco mise beaucoup sur les jeunes issus de sa formation mais gagner sa place chez les professionnels n\u2019est pas une \u00e9vidence pour tous. Alors qu\u2019ils ne sont jamais apparus sur le terrain avec l\u2019\u00e9quipe premi\u00e8re au cours de la saison qui s\u2019est achev\u00e9e, le milieu de terrain Mayssam Benama et le d\u00e9fenseur central Ritchy [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2024\/06\/03\/valme-et-benama-reflechiraient-a-un-pret\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-03T09:53:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-03T10:46:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/09\/valme23.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/09\/valme23.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/06\/03\/valme-et-benama-reflechiraient-a-un-pret\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/06\/03\/valme-et-benama-reflechiraient-a-un-pret\/\",\"name\":\"Valme et Benama r\u00e9fl\u00e9chiraient \u00e0 un pr\u00eat - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2024-06-03T09:53:23+00:00\",\"dateModified\":\"2024-06-03T10:46:34+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/06\/03\/valme-et-benama-reflechiraient-a-un-pret\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2024\/06\/03\/valme-et-benama-reflechiraient-a-un-pret\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/06\/03\/valme-et-benama-reflechiraient-a-un-pret\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Valme et Benama r\u00e9fl\u00e9chiraient \u00e0 un pr\u00eat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Valme et Benama r\u00e9fl\u00e9chiraient \u00e0 un pr\u00eat - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2024\/06\/03\/valme-et-benama-reflechiraient-a-un-pret\/","og_locale":"fr_FR","og_type":"article","og_title":"Valme et Benama r\u00e9fl\u00e9chiraient \u00e0 un pr\u00eat - La Diagonale","og_description":"L\u2019AS Monaco mise beaucoup sur les jeunes issus de sa formation mais gagner sa place chez les professionnels n\u2019est pas une \u00e9vidence pour tous. Alors qu\u2019ils ne sont jamais apparus sur le terrain avec l\u2019\u00e9quipe premi\u00e8re au cours de la saison qui s\u2019est achev\u00e9e, le milieu de terrain Mayssam Benama et le d\u00e9fenseur central Ritchy [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2024\/06\/03\/valme-et-benama-reflechiraient-a-un-pret\/","og_site_name":"La Diagonale","article_published_time":"2024-06-03T09:53:23+00:00","article_modified_time":"2024-06-03T10:46:34+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/09\/valme23.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/09\/valme23.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/06\/03\/valme-et-benama-reflechiraient-a-un-pret\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2024\/06\/03\/valme-et-benama-reflechiraient-a-un-pret\/","name":"Valme et Benama r\u00e9fl\u00e9chiraient \u00e0 un pr\u00eat - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2024-06-03T09:53:23+00:00","dateModified":"2024-06-03T10:46:34+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/06\/03\/valme-et-benama-reflechiraient-a-un-pret\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2024\/06\/03\/valme-et-benama-reflechiraient-a-un-pret\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/06\/03\/valme-et-benama-reflechiraient-a-un-pret\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Valme et Benama r\u00e9fl\u00e9chiraient \u00e0 un pr\u00eat"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/23669"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=23669"}],"version-history":[{"count":7,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/23669\/revisions"}],"predecessor-version":[{"id":23684,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/23669\/revisions\/23684"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=23669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=23669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=23669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}