{"id":24293,"date":"2024-07-05T00:47:02","date_gmt":"2024-07-04T22:47:02","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=24293"},"modified":"2024-07-05T00:47:04","modified_gmt":"2024-07-04T22:47:04","slug":"matsima-et-magassa-vainqueurs-avec-lequipe-de-france-olympique","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2024\/07\/05\/matsima-et-magassa-vainqueurs-avec-lequipe-de-france-olympique\/","title":{"rendered":"Matsima et Magassa vainqueurs avec l&rsquo;\u00e9quipe de France olympique"},"content":{"rendered":"\n\n\n<p>Jeudi, l&rsquo;\u00e9quipe de France olympique a effectu\u00e9 sa premi\u00e8re sortie. Avec Chrislain Matsima, <a href=\"https:\/\/www.ladiagonale.net\/index.php\/2024\/07\/04\/matsima-reserviste-pour-les-jo\/\" target=\"_blank\" rel=\"noreferrer noopener\">qui ne sera que r\u00e9serviste pour les JO<\/a>, et Soungoutou Magassa, les Bleuets ont dispos\u00e9 du Paraguay (4-1), malgr\u00e9 une ouverture du score conc\u00e9d\u00e9e. Matsima a \u00e9t\u00e9 titularis\u00e9 par Thierry Henry et a jou\u00e9 toute la rencontre, tandis que Magassa est entr\u00e9 \u00e0 la mi-temps au poste de d\u00e9fenseur central. Une de ses interceptions a d&rsquo;ailleurs conduit au contre et au troisi\u00e8me but tricolore. Maghnes Akliouche est lui rest\u00e9 sur le banc.<\/p>\n\n\n\n<p>La premi\u00e8re r\u00e9p\u00e9tition de l&rsquo;\u00e9quipe de France, avec une large revue d&rsquo;effectif de la part de son s\u00e9lectionneur, a \u00e9t\u00e9 concluante. Jeudi prochain, elle affrontera la R\u00e9publique dominicaine (21h15) pour son second match de pr\u00e9paration.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jeudi, l&rsquo;\u00e9quipe de France olympique a effectu\u00e9 sa premi\u00e8re sortie. Avec Chrislain Matsima, qui ne sera que r\u00e9serviste pour les JO, et Soungoutou Magassa, les Bleuets ont dispos\u00e9 du Paraguay (4-1), malgr\u00e9 une ouverture du score conc\u00e9d\u00e9e. Matsima a \u00e9t\u00e9 titularis\u00e9 par Thierry Henry et a jou\u00e9 toute la rencontre, tandis que Magassa est entr\u00e9 [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[86,392,882,801,802,190,116,147],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Matsima et Magassa vainqueurs avec l&#039;\u00e9quipe de France olympique - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2024\/07\/05\/matsima-et-magassa-vainqueurs-avec-lequipe-de-france-olympique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Matsima et Magassa vainqueurs avec l&#039;\u00e9quipe de France olympique - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Jeudi, l&rsquo;\u00e9quipe de France olympique a effectu\u00e9 sa premi\u00e8re sortie. Avec Chrislain Matsima, qui ne sera que r\u00e9serviste pour les JO, et Soungoutou Magassa, les Bleuets ont dispos\u00e9 du Paraguay (4-1), malgr\u00e9 une ouverture du score conc\u00e9d\u00e9e. Matsima a \u00e9t\u00e9 titularis\u00e9 par Thierry Henry et a jou\u00e9 toute la rencontre, tandis que Magassa est entr\u00e9 [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2024\/07\/05\/matsima-et-magassa-vainqueurs-avec-lequipe-de-france-olympique\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-04T22:47:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-04T22:47:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/09\/matsima.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/09\/matsima.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/07\/05\/matsima-et-magassa-vainqueurs-avec-lequipe-de-france-olympique\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/07\/05\/matsima-et-magassa-vainqueurs-avec-lequipe-de-france-olympique\/\",\"name\":\"Matsima et Magassa vainqueurs avec l'\u00e9quipe de France olympique - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2024-07-04T22:47:02+00:00\",\"dateModified\":\"2024-07-04T22:47:04+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/07\/05\/matsima-et-magassa-vainqueurs-avec-lequipe-de-france-olympique\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2024\/07\/05\/matsima-et-magassa-vainqueurs-avec-lequipe-de-france-olympique\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/07\/05\/matsima-et-magassa-vainqueurs-avec-lequipe-de-france-olympique\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Matsima et Magassa vainqueurs avec l&rsquo;\u00e9quipe de France olympique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Matsima et Magassa vainqueurs avec l'\u00e9quipe de France olympique - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2024\/07\/05\/matsima-et-magassa-vainqueurs-avec-lequipe-de-france-olympique\/","og_locale":"fr_FR","og_type":"article","og_title":"Matsima et Magassa vainqueurs avec l'\u00e9quipe de France olympique - La Diagonale","og_description":"Jeudi, l&rsquo;\u00e9quipe de France olympique a effectu\u00e9 sa premi\u00e8re sortie. Avec Chrislain Matsima, qui ne sera que r\u00e9serviste pour les JO, et Soungoutou Magassa, les Bleuets ont dispos\u00e9 du Paraguay (4-1), malgr\u00e9 une ouverture du score conc\u00e9d\u00e9e. Matsima a \u00e9t\u00e9 titularis\u00e9 par Thierry Henry et a jou\u00e9 toute la rencontre, tandis que Magassa est entr\u00e9 [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2024\/07\/05\/matsima-et-magassa-vainqueurs-avec-lequipe-de-france-olympique\/","og_site_name":"La Diagonale","article_published_time":"2024-07-04T22:47:02+00:00","article_modified_time":"2024-07-04T22:47:04+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/09\/matsima.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/09\/matsima.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/07\/05\/matsima-et-magassa-vainqueurs-avec-lequipe-de-france-olympique\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2024\/07\/05\/matsima-et-magassa-vainqueurs-avec-lequipe-de-france-olympique\/","name":"Matsima et Magassa vainqueurs avec l'\u00e9quipe de France olympique - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2024-07-04T22:47:02+00:00","dateModified":"2024-07-04T22:47:04+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/07\/05\/matsima-et-magassa-vainqueurs-avec-lequipe-de-france-olympique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2024\/07\/05\/matsima-et-magassa-vainqueurs-avec-lequipe-de-france-olympique\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/07\/05\/matsima-et-magassa-vainqueurs-avec-lequipe-de-france-olympique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Matsima et Magassa vainqueurs avec l&rsquo;\u00e9quipe de France olympique"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/24293"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=24293"}],"version-history":[{"count":1,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/24293\/revisions"}],"predecessor-version":[{"id":24294,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/24293\/revisions\/24294"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=24293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=24293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=24293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}