{"id":25010,"date":"2024-08-16T16:10:24","date_gmt":"2024-08-16T14:10:24","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=25010"},"modified":"2024-08-18T03:09:09","modified_gmt":"2024-08-18T01:09:09","slug":"les-numeros-de-maillot-de-las-monaco-pour-la-saison-2024-2025","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2024\/08\/16\/les-numeros-de-maillot-de-las-monaco-pour-la-saison-2024-2025\/","title":{"rendered":"Les num\u00e9ros de maillot de l\u2019AS Monaco pour la saison 2024-2025"},"content":{"rendered":"\n\n\n<p>Qui dit nouvelle saison dit forc\u00e9ment recrues et nouveaux num\u00e9ros dans l\u2019effectif. \u00c0 ce jour, trois joueurs ont rejoint l&rsquo;AS Monaco durant le mercato estival. Le premier arriv\u00e9, George Ilenikhena, a r\u00e9cup\u00e9r\u00e9 le num\u00e9ro 21, qui \u00e9tait la propri\u00e9t\u00e9 de Maghnes Akliouche. Christian Mawissa, qui portera le 13, et Lamine Camara, qui a fait le choix du 15, ont tous deux opt\u00e9 pour des num\u00e9ros non attribu\u00e9s la saison pass\u00e9e.<\/p>\n\n\n\n<h3>Un nouveau num\u00e9ro 10<\/h3>\n\n\n\n<p>Mais des joueurs plus anciens ont aussi proc\u00e9d\u00e9 \u00e0 des changements, et non des moindres. C&rsquo;est notamment le cas d&rsquo;Aleksandr Golovin, qui a r\u00e9cup\u00e9r\u00e9 le num\u00e9ro 10 laiss\u00e9 vacant par Wissam Ben Yedder, parti libre. Lors de son arriv\u00e9e au club, le milieu russe avait pris le num\u00e9ro 17 puisque le num\u00e9ro le plus iconique du football qui soit \u00e9tait alors la propri\u00e9t\u00e9 de Stevan Jovetic. Au d\u00e9part du Mont\u00e9n\u00e9grin, c&rsquo;est Ben Yedder qui l&rsquo;a r\u00e9cup\u00e9r\u00e9, laissant ainsi Myron Boadu prendre le 9 \u00e0 son arriv\u00e9e. Cette saison, le 9 conna\u00eetra lui aussi un nouveau propri\u00e9taire, Folarin Balogun, qui d\u00e9laisse le 29 pour un num\u00e9ro tout aussi sp\u00e9cial.<\/p>\n\n\n\n<p>Apr\u00e8s Eliesse Ben Seghir l&rsquo;an dernier, qui avait troqu\u00e9 son num\u00e9ro 44 pour le num\u00e9ro 7, c&rsquo;est au tour de Maghnes Akliouche de changer. Habitu\u00e9 du num\u00e9ro 21 depuis deux saisons, le m\u00e9daill\u00e9 d&rsquo;argent des Jeux Olympiques de Paris a pris possession du num\u00e9ro 11 dont le dernier porteur n&rsquo;\u00e9tait autre que Jean Lucas.<\/p>\n\n\n\n<h3>Moins de num\u00e9ros farfelus dans l&rsquo;effectif<\/h3>\n\n\n\n<p>Il y a trois ans, la LFP avait accord\u00e9 un passe-droit \u00e0 Lionel Messi pour pouvoir porter le num\u00e9ro 30 habituellement r\u00e9serv\u00e9 aux gardiens. Un pied gliss\u00e9 dans l&rsquo;entreb\u00e2illement de la porte pour l&rsquo;ouvrir en grand un an plus tard, en autorisant tous les num\u00e9ros compris entre 1 et 99. Certains Mon\u00e9gasques avaient saisi l&rsquo;occasion, tel que Gelson Martins et son num\u00e9ro 77. L&rsquo;an dernier, Wilfried Singo avait opt\u00e9 pour le 99, mais celui-ci ne durera pas puisque l&rsquo;Ivoirien a r\u00e9cup\u00e9r\u00e9 le 17 de Golovin.<\/p>\n\n\n\n<p>Parmi les num\u00e9ros les plus insolites de l&rsquo;effectif, on continuera de voir Soungoutou Magassa arborer le 88, tandis que Breel Embolo portera le 36, un num\u00e9ro <a href=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/08\/13\/la-signification-du-numero-dembolo\/\" target=\"_blank\" rel=\"noreferrer noopener\">charg\u00e9 d&rsquo;histoire et de symboles<\/a> pour lui. De m\u00eame Edan Diop conservera son num\u00e9ro 37, soit le num\u00e9ro de son d\u00e9partement de naissance, l&rsquo;Indre-et-Loire. Chrislain Matsima reste pour l&rsquo;instant fid\u00e8le au num\u00e9ro 34, avec lequel il a disput\u00e9 son premier match sous les couleurs mon\u00e9gasques, contre Strasbourg, en septembre 2020.<\/p>\n\n\n\n<p>La dizaine des 40 est quant \u00e0 elle majoritairement r\u00e9serv\u00e9e aux jeunes joueurs de l&rsquo;Academy. L&rsquo;an pass\u00e9, Mamadou Coulibaly avait \u00e9volu\u00e9 avec le num\u00e9ro 42, mais celui-ci a r\u00e9cemment \u00e9t\u00e9 port\u00e9 par Sa\u00efmon Bouabr\u00e9 contre le Bar\u00e7a. Les num\u00e9ros de certains jeunes, comme Lucas Michal, doivent encore \u00eatre attribu\u00e9s pour la saison \u00e0 venir.<\/p>\n\n\n\n<h3>Quels sont les num\u00e9ros vacants ?<\/h3>\n\n\n\n<p>Pour l&rsquo;instant, l&rsquo;ASM remplit plut\u00f4t bien les premiers nombres avec son effectif actuel et presque tous les num\u00e9ros \u00ab\u00a0importants\u00a0\u00bb sont pris. Dans la premi\u00e8re dizaine, reste le num\u00e9ro 4, laiss\u00e9 libre par Mohamed Camara apr\u00e8s son d\u00e9part vers le Qatar et Al-Sadd. Reste \u00e0 savoir s&rsquo;il sera r\u00e9cup\u00e9r\u00e9 par une nouvelle recrue. Le num\u00e9ro 19, autrefois propri\u00e9t\u00e9 de Willy Sagnol, S\u00e9bastien Squillaci ou encore Djibril Sidib\u00e9, a \u00e9galement vu son porteur actuel, Youssouf Fofana, quitter le club et donc redevenir libre.<\/p>\n\n\n\n<p>Dans la vingtaine, Myron Boadu avait finalement pris le 23 mais il ne le portera pas cette saison, puisqu&rsquo;il est pr\u00eat\u00e9 \u00e0 Bochum. F\u00e9lix Lemarechal abandonne quant \u00e0 lui le 29 apr\u00e8s son transfert \u00e0 Strasbourg. Les 24, 25, 26 et 28 sont aussi vacants.<\/p>\n\n\n\n<h3>Tous les num\u00e9ros de maillots de la saison 2024-2025 (au 16 ao\u00fbt)<\/h3>\n\n\n\n<div class=\"wp-container-3 wp-block-columns\">\n<div class=\"wp-container-1 wp-block-column\">\n<p>1 &#8211; Majecki<br>2 &#8211; Vanderson<br>3 &#8211; Maripan<br>5 &#8211; Kehrer<br>6 &#8211; Zakaria<br>7 &#8211; Ben Seghir<br>8 &#8211; Matazo<br>9 &#8211; Balogun<br>10 &#8211; Golovin<br>11 &#8211; Akliouche<br>12 &#8211; C. Henrique<br>13 &#8211; Mawissa<br>14 &#8211; Jakobs<br>15 &#8211; Camara<\/p>\n<\/div>\n\n\n\n<div class=\"wp-container-2 wp-block-column\">\n<p>16 &#8211; K\u00f6hn<br>17 &#8211; Singo<br>18 &#8211; Minamino<br>20 &#8211; Ouattara<br>21 &#8211; Ilenikhena<br>22 &#8211; Salisu<br>27 &#8211; Diatta<br>34 &#8211; Matsima<br>36 &#8211; Embolo<br>37 &#8211; Diop<br>50 &#8211; Lienard<br>88 &#8211; Magassa<br><\/p>\n<\/div>\n<\/div>\n\n\n\n<p><em>Sa\u00efmon Bouabr\u00e9, Lucas Michal, Mamadou Coulibaly ne se sont pas encore vus attribuer de num\u00e9ro d\u00e9finitif.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qui dit nouvelle saison dit forc\u00e9ment recrues et nouveaux num\u00e9ros dans l\u2019effectif. \u00c0 ce jour, trois joueurs ont rejoint l&rsquo;AS Monaco durant le mercato estival. Le premier arriv\u00e9, George Ilenikhena, a r\u00e9cup\u00e9r\u00e9 le num\u00e9ro 21, qui \u00e9tait la propri\u00e9t\u00e9 de Maghnes Akliouche. Christian Mawissa, qui portera le 13, et Lamine Camara, qui a fait le [&#8230;]\n","protected":false},"author":2,"featured_media":25017,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,6],"tags":[86,905],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les num\u00e9ros de maillot de l\u2019AS Monaco pour la saison 2024-2025 - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2024\/08\/16\/les-numeros-de-maillot-de-las-monaco-pour-la-saison-2024-2025\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les num\u00e9ros de maillot de l\u2019AS Monaco pour la saison 2024-2025 - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Qui dit nouvelle saison dit forc\u00e9ment recrues et nouveaux num\u00e9ros dans l\u2019effectif. \u00c0 ce jour, trois joueurs ont rejoint l&rsquo;AS Monaco durant le mercato estival. Le premier arriv\u00e9, George Ilenikhena, a r\u00e9cup\u00e9r\u00e9 le num\u00e9ro 21, qui \u00e9tait la propri\u00e9t\u00e9 de Maghnes Akliouche. Christian Mawissa, qui portera le 13, et Lamine Camara, qui a fait le [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2024\/08\/16\/les-numeros-de-maillot-de-las-monaco-pour-la-saison-2024-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-16T14:10:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-18T01:09:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/08\/nume\u0301ros.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/08\/nume\u0301ros.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/08\/16\/les-numeros-de-maillot-de-las-monaco-pour-la-saison-2024-2025\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/08\/16\/les-numeros-de-maillot-de-las-monaco-pour-la-saison-2024-2025\/\",\"name\":\"Les num\u00e9ros de maillot de l\u2019AS Monaco pour la saison 2024-2025 - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2024-08-16T14:10:24+00:00\",\"dateModified\":\"2024-08-18T01:09:09+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/08\/16\/les-numeros-de-maillot-de-las-monaco-pour-la-saison-2024-2025\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2024\/08\/16\/les-numeros-de-maillot-de-las-monaco-pour-la-saison-2024-2025\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/08\/16\/les-numeros-de-maillot-de-las-monaco-pour-la-saison-2024-2025\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les num\u00e9ros de maillot de l\u2019AS Monaco pour la saison 2024-2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les num\u00e9ros de maillot de l\u2019AS Monaco pour la saison 2024-2025 - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2024\/08\/16\/les-numeros-de-maillot-de-las-monaco-pour-la-saison-2024-2025\/","og_locale":"fr_FR","og_type":"article","og_title":"Les num\u00e9ros de maillot de l\u2019AS Monaco pour la saison 2024-2025 - La Diagonale","og_description":"Qui dit nouvelle saison dit forc\u00e9ment recrues et nouveaux num\u00e9ros dans l\u2019effectif. \u00c0 ce jour, trois joueurs ont rejoint l&rsquo;AS Monaco durant le mercato estival. Le premier arriv\u00e9, George Ilenikhena, a r\u00e9cup\u00e9r\u00e9 le num\u00e9ro 21, qui \u00e9tait la propri\u00e9t\u00e9 de Maghnes Akliouche. Christian Mawissa, qui portera le 13, et Lamine Camara, qui a fait le [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2024\/08\/16\/les-numeros-de-maillot-de-las-monaco-pour-la-saison-2024-2025\/","og_site_name":"La Diagonale","article_published_time":"2024-08-16T14:10:24+00:00","article_modified_time":"2024-08-18T01:09:09+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/08\/nume\u0301ros.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/08\/nume\u0301ros.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/08\/16\/les-numeros-de-maillot-de-las-monaco-pour-la-saison-2024-2025\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2024\/08\/16\/les-numeros-de-maillot-de-las-monaco-pour-la-saison-2024-2025\/","name":"Les num\u00e9ros de maillot de l\u2019AS Monaco pour la saison 2024-2025 - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2024-08-16T14:10:24+00:00","dateModified":"2024-08-18T01:09:09+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/08\/16\/les-numeros-de-maillot-de-las-monaco-pour-la-saison-2024-2025\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2024\/08\/16\/les-numeros-de-maillot-de-las-monaco-pour-la-saison-2024-2025\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/08\/16\/les-numeros-de-maillot-de-las-monaco-pour-la-saison-2024-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Les num\u00e9ros de maillot de l\u2019AS Monaco pour la saison 2024-2025"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/25010"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=25010"}],"version-history":[{"count":7,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/25010\/revisions"}],"predecessor-version":[{"id":25065,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/25010\/revisions\/25065"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media\/25017"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=25010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=25010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=25010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}