{"id":25259,"date":"2024-08-29T16:44:25","date_gmt":"2024-08-29T14:44:25","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=25259"},"modified":"2024-08-29T16:44:27","modified_gmt":"2024-08-29T14:44:27","slug":"embolo-et-zakaria-selectionnes-avec-la-suisse","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2024\/08\/29\/embolo-et-zakaria-selectionnes-avec-la-suisse\/","title":{"rendered":"Embolo et Zakaria s\u00e9lectionn\u00e9s avec la Suisse"},"content":{"rendered":"\n\n\n<p>Sans surprise, Breel Embolo et Denis Zakaria ne seront pas sur le Rocher lors de la tr\u00eave hivernale qui d\u00e9butera lundi. Les deux joueurs de l&rsquo;AS Monaco ont \u00e9t\u00e9 appel\u00e9s par Murat Yakin pour jouer avec la Suisse en Ligue des nations.<\/p>\n\n\n\n<p>Quart de finaliste du dernier Euro, la Suisse va tenter de poursuivre sur cette dynamique pour les d\u00e9buts de la comp\u00e9tition amicale continentale. Plac\u00e9e dans le groupe 4 de la Ligue A, l&rsquo;adversit\u00e9 sera relev\u00e9e, puisque la Nati affrontera d&rsquo;abord le Danemark, le 5 septembre (20h45), puis le champion d&rsquo;Europe en titre, l&rsquo;Espagne, le 9 (20h45).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sans surprise, Breel Embolo et Denis Zakaria ne seront pas sur le Rocher lors de la tr\u00eave hivernale qui d\u00e9butera lundi. Les deux joueurs de l&rsquo;AS Monaco ont \u00e9t\u00e9 appel\u00e9s par Murat Yakin pour jouer avec la Suisse en Ligue des nations. Quart de finaliste du dernier Euro, la Suisse va tenter de poursuivre sur [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[86,161,631,116,117],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Embolo et Zakaria s\u00e9lectionn\u00e9s avec la Suisse - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2024\/08\/29\/embolo-et-zakaria-selectionnes-avec-la-suisse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Embolo et Zakaria s\u00e9lectionn\u00e9s avec la Suisse - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Sans surprise, Breel Embolo et Denis Zakaria ne seront pas sur le Rocher lors de la tr\u00eave hivernale qui d\u00e9butera lundi. Les deux joueurs de l&rsquo;AS Monaco ont \u00e9t\u00e9 appel\u00e9s par Murat Yakin pour jouer avec la Suisse en Ligue des nations. Quart de finaliste du dernier Euro, la Suisse va tenter de poursuivre sur [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2024\/08\/29\/embolo-et-zakaria-selectionnes-avec-la-suisse\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-29T14:44:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-29T14:44:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/06\/zakaria-embolo-suisse.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/06\/zakaria-embolo-suisse.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/08\/29\/embolo-et-zakaria-selectionnes-avec-la-suisse\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/08\/29\/embolo-et-zakaria-selectionnes-avec-la-suisse\/\",\"name\":\"Embolo et Zakaria s\u00e9lectionn\u00e9s avec la Suisse - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2024-08-29T14:44:25+00:00\",\"dateModified\":\"2024-08-29T14:44:27+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/08\/29\/embolo-et-zakaria-selectionnes-avec-la-suisse\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2024\/08\/29\/embolo-et-zakaria-selectionnes-avec-la-suisse\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/08\/29\/embolo-et-zakaria-selectionnes-avec-la-suisse\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Embolo et Zakaria s\u00e9lectionn\u00e9s avec la Suisse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Embolo et Zakaria s\u00e9lectionn\u00e9s avec la Suisse - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2024\/08\/29\/embolo-et-zakaria-selectionnes-avec-la-suisse\/","og_locale":"fr_FR","og_type":"article","og_title":"Embolo et Zakaria s\u00e9lectionn\u00e9s avec la Suisse - La Diagonale","og_description":"Sans surprise, Breel Embolo et Denis Zakaria ne seront pas sur le Rocher lors de la tr\u00eave hivernale qui d\u00e9butera lundi. Les deux joueurs de l&rsquo;AS Monaco ont \u00e9t\u00e9 appel\u00e9s par Murat Yakin pour jouer avec la Suisse en Ligue des nations. Quart de finaliste du dernier Euro, la Suisse va tenter de poursuivre sur [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2024\/08\/29\/embolo-et-zakaria-selectionnes-avec-la-suisse\/","og_site_name":"La Diagonale","article_published_time":"2024-08-29T14:44:25+00:00","article_modified_time":"2024-08-29T14:44:27+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/06\/zakaria-embolo-suisse.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/06\/zakaria-embolo-suisse.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/08\/29\/embolo-et-zakaria-selectionnes-avec-la-suisse\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2024\/08\/29\/embolo-et-zakaria-selectionnes-avec-la-suisse\/","name":"Embolo et Zakaria s\u00e9lectionn\u00e9s avec la Suisse - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2024-08-29T14:44:25+00:00","dateModified":"2024-08-29T14:44:27+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/08\/29\/embolo-et-zakaria-selectionnes-avec-la-suisse\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2024\/08\/29\/embolo-et-zakaria-selectionnes-avec-la-suisse\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/08\/29\/embolo-et-zakaria-selectionnes-avec-la-suisse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Embolo et Zakaria s\u00e9lectionn\u00e9s avec la Suisse"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/25259"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=25259"}],"version-history":[{"count":1,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/25259\/revisions"}],"predecessor-version":[{"id":25260,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/25259\/revisions\/25260"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=25259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=25259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=25259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}