{"id":25548,"date":"2024-09-09T02:35:48","date_gmt":"2024-09-09T00:35:48","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=25548"},"modified":"2024-09-09T02:42:47","modified_gmt":"2024-09-09T00:42:47","slug":"troisieme-nul-pour-cabral-et-la-france","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2024\/09\/09\/troisieme-nul-pour-cabral-et-la-france\/","title":{"rendered":"Troisi\u00e8me nul pour Cabral et la France U18"},"content":{"rendered":"\n\n\n<p>L\u2019\u00e9quipe de France U18 a conc\u00e9d\u00e9 un troisi\u00e8me match nul en trois matches contre l\u2019Angleterre (1-1, 0-2 aux t.a.b.) au tournoi de Limoges. Pape Cabral a jou\u00e9 la rencontre comme titulaire et est sorti \u00e0 la 87e minute. Sur l\u2019ouverture du score anglaise, il a \u00e9t\u00e9 pris par l\u2019appel du buteur adverse.<\/p>\n\n\n\n<p>Le Portugal a remport\u00e9 ce tournoi apr\u00e8s avoir battu la Suisse de Sirak Bein (3-2). Le d\u00e9fenseur de l\u2019ASM a \u00e9t\u00e9 titularis\u00e9 sur cette rencontre apr\u00e8s avoir purg\u00e9 un match de suspension \u00e0 la suite du carton rouge re\u00e7u contre l\u2019\u00e9quipe de France lors du premier match. Il s\u2019est notamment fait prendre de vitesse sur le second but portugais. Il a \u00e9t\u00e9 remplac\u00e9 \u00e0 la 67e minute.<\/p>\n\n\n\n<p>Pour le second match amical contre l&rsquo;Arabie saoudite, Yanis Benchaouch a \u00e9t\u00e9 titularis\u00e9 avec le Maroc U20. Les <em>Lions de l&rsquo;Atlas<\/em> se sont facilement impos\u00e9s (4-1).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019\u00e9quipe de France U18 a conc\u00e9d\u00e9 un troisi\u00e8me match nul en trois matches contre l\u2019Angleterre (1-1, 0-2 aux t.a.b.) au tournoi de Limoges. Pape Cabral a jou\u00e9 la rencontre comme titulaire et est sorti \u00e0 la 87e minute. Sur l\u2019ouverture du score anglaise, il a \u00e9t\u00e9 pris par l\u2019appel du buteur adverse. Le Portugal a [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[86,116],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Troisi\u00e8me nul pour Cabral et la France U18 - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2024\/09\/09\/troisieme-nul-pour-cabral-et-la-france\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Troisi\u00e8me nul pour Cabral et la France U18 - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"L\u2019\u00e9quipe de France U18 a conc\u00e9d\u00e9 un troisi\u00e8me match nul en trois matches contre l\u2019Angleterre (1-1, 0-2 aux t.a.b.) au tournoi de Limoges. Pape Cabral a jou\u00e9 la rencontre comme titulaire et est sorti \u00e0 la 87e minute. Sur l\u2019ouverture du score anglaise, il a \u00e9t\u00e9 pris par l\u2019appel du buteur adverse. Le Portugal a [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2024\/09\/09\/troisieme-nul-pour-cabral-et-la-france\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-09T00:35:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-09T00:42:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/05\/cabral-france.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/05\/cabral-france.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/09\/09\/troisieme-nul-pour-cabral-et-la-france\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/09\/09\/troisieme-nul-pour-cabral-et-la-france\/\",\"name\":\"Troisi\u00e8me nul pour Cabral et la France U18 - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2024-09-09T00:35:48+00:00\",\"dateModified\":\"2024-09-09T00:42:47+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/09\/09\/troisieme-nul-pour-cabral-et-la-france\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2024\/09\/09\/troisieme-nul-pour-cabral-et-la-france\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/09\/09\/troisieme-nul-pour-cabral-et-la-france\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Troisi\u00e8me nul pour Cabral et la France U18\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Troisi\u00e8me nul pour Cabral et la France U18 - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2024\/09\/09\/troisieme-nul-pour-cabral-et-la-france\/","og_locale":"fr_FR","og_type":"article","og_title":"Troisi\u00e8me nul pour Cabral et la France U18 - La Diagonale","og_description":"L\u2019\u00e9quipe de France U18 a conc\u00e9d\u00e9 un troisi\u00e8me match nul en trois matches contre l\u2019Angleterre (1-1, 0-2 aux t.a.b.) au tournoi de Limoges. Pape Cabral a jou\u00e9 la rencontre comme titulaire et est sorti \u00e0 la 87e minute. Sur l\u2019ouverture du score anglaise, il a \u00e9t\u00e9 pris par l\u2019appel du buteur adverse. Le Portugal a [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2024\/09\/09\/troisieme-nul-pour-cabral-et-la-france\/","og_site_name":"La Diagonale","article_published_time":"2024-09-09T00:35:48+00:00","article_modified_time":"2024-09-09T00:42:47+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/05\/cabral-france.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/05\/cabral-france.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/09\/09\/troisieme-nul-pour-cabral-et-la-france\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2024\/09\/09\/troisieme-nul-pour-cabral-et-la-france\/","name":"Troisi\u00e8me nul pour Cabral et la France U18 - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2024-09-09T00:35:48+00:00","dateModified":"2024-09-09T00:42:47+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/09\/09\/troisieme-nul-pour-cabral-et-la-france\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2024\/09\/09\/troisieme-nul-pour-cabral-et-la-france\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/09\/09\/troisieme-nul-pour-cabral-et-la-france\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Troisi\u00e8me nul pour Cabral et la France U18"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/25548"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=25548"}],"version-history":[{"count":2,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/25548\/revisions"}],"predecessor-version":[{"id":25550,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/25548\/revisions\/25550"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=25548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=25548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=25548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}