{"id":25756,"date":"2024-09-16T14:10:19","date_gmt":"2024-09-16T12:10:19","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=25756"},"modified":"2024-09-16T14:10:52","modified_gmt":"2024-09-16T12:10:52","slug":"monaco-meilleure-equipe-de-la-4e-journee","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2024\/09\/16\/monaco-meilleure-equipe-de-la-4e-journee\/","title":{"rendered":"Monaco, meilleure \u00e9quipe de la 4e journ\u00e9e"},"content":{"rendered":"\n\n\n<p>Trois buts inscrits et aucun encaiss\u00e9, Monaco a livr\u00e9 une tr\u00e8s bonne copie contre Auxerre samedi, ce qui lui permet de glaner un troisi\u00e8me succ\u00e8s en quatre rencontres de Ligue 1. Les Mon\u00e9gasques ont totalement ma\u00eetris\u00e9 leur sujet sur la pelouse de l&rsquo;Abb\u00e9-Deschamps, et avec une moyenne de 6,1\/10, l&rsquo;ASM est la meilleure \u00e9quipe de cette 4e journ\u00e9e de championnat.<\/p>\n\n\n\n<p>Deux Rouge et Blanc se placent dans l&rsquo;\u00e9quipe type : Denis Zakaria et Thilo Kehrer. Le capitaine et vice-capitaine du club ont \u00e9t\u00e9 \u00e9valu\u00e9 \u00e0 8\/10, impliqu\u00e9s sur les trois buts as\u00e9mistes lors de cette rencontre. Pour Kehrer, c&rsquo;est sa deuxi\u00e8me pr\u00e9sence dans le onze du quotidien.<\/p>\n\n\n\n<h3>L&rsquo;\u00e9quipe type de la 4<sup>e<\/sup> journ\u00e9e<\/h3>\n\n\n\n<p class=\"has-white-color has-text-color has-background\" style=\"background-color:#303030\"><em>Gardien :<\/em> Rulli (7, Marseille)<br><em>D\u00e9fenseurs :<\/em> Lala (7, Brest), <strong>Kehrer (8, Monaco)<\/strong>, Abdelhamid (7, Saint-\u00c9tienne), Bard (7, Nice)<br><em>Milieux :<\/em> Zakaria (8, Monaco), H\u00f6jbjerg (7, Marseille), Demb\u00e9l\u00e9 (8, Paris SG), Davitachvili (7, Saint-\u00c9tienne), Cafaro (7, Saint-\u00c9tienne)<br><em>Attaquant :<\/em> Maupay (7, Marseille)<br><em>Entra\u00eeneur :<\/em> Dall&rsquo;Oglio (7, Saint-\u00c9tienne)<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-white-color has-vivid-red-background-color has-text-color has-background\" id=\"pr\u00e9sences-dans-l\u00e9quipe-type-par-journ\u00e9es\" style=\"text-transform:uppercase\">Pr\u00e9sences dans l\u2019\u00e9quipe type par journ\u00e9e<\/h4>\n\n\n\n<ul><li>2<sup>e<\/sup> journ\u00e9e : Thilo Kehrer<\/li><li>4<sup>e<\/sup> journ\u00e9e : Thilo Kehrer, Denis Zakaria<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading has-white-color has-vivid-red-background-color has-text-color has-background\" id=\"nombre-de-pr\u00e9sences-dans-l\u00e9quipe-type\" style=\"text-transform:uppercase\">Nombre de pr\u00e9sences dans l\u2019\u00e9quipe type<\/h4>\n\n\n\n<ul><li>Thilo Kehrer : 2<\/li><li>Denis Zakaria : 1<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Trois buts inscrits et aucun encaiss\u00e9, Monaco a livr\u00e9 une tr\u00e8s bonne copie contre Auxerre samedi, ce qui lui permet de glaner un troisi\u00e8me succ\u00e8s en quatre rencontres de Ligue 1. Les Mon\u00e9gasques ont totalement ma\u00eetris\u00e9 leur sujet sur la pelouse de l&rsquo;Abb\u00e9-Deschamps, et avec une moyenne de 6,1\/10, l&rsquo;ASM est la meilleure \u00e9quipe de [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[86,631,218,94,756],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Monaco, meilleure \u00e9quipe de la 4e journ\u00e9e - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2024\/09\/16\/monaco-meilleure-equipe-de-la-4e-journee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Monaco, meilleure \u00e9quipe de la 4e journ\u00e9e - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Trois buts inscrits et aucun encaiss\u00e9, Monaco a livr\u00e9 une tr\u00e8s bonne copie contre Auxerre samedi, ce qui lui permet de glaner un troisi\u00e8me succ\u00e8s en quatre rencontres de Ligue 1. Les Mon\u00e9gasques ont totalement ma\u00eetris\u00e9 leur sujet sur la pelouse de l&rsquo;Abb\u00e9-Deschamps, et avec une moyenne de 6,1\/10, l&rsquo;ASM est la meilleure \u00e9quipe de [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2024\/09\/16\/monaco-meilleure-equipe-de-la-4e-journee\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-16T12:10:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-16T12:10:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/09\/2024-09-14-auxerre-asm-0109.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/09\/16\/monaco-meilleure-equipe-de-la-4e-journee\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/09\/16\/monaco-meilleure-equipe-de-la-4e-journee\/\",\"name\":\"Monaco, meilleure \u00e9quipe de la 4e journ\u00e9e - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2024-09-16T12:10:19+00:00\",\"dateModified\":\"2024-09-16T12:10:52+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/09\/16\/monaco-meilleure-equipe-de-la-4e-journee\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2024\/09\/16\/monaco-meilleure-equipe-de-la-4e-journee\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/09\/16\/monaco-meilleure-equipe-de-la-4e-journee\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Monaco, meilleure \u00e9quipe de la 4e journ\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Monaco, meilleure \u00e9quipe de la 4e journ\u00e9e - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2024\/09\/16\/monaco-meilleure-equipe-de-la-4e-journee\/","og_locale":"fr_FR","og_type":"article","og_title":"Monaco, meilleure \u00e9quipe de la 4e journ\u00e9e - La Diagonale","og_description":"Trois buts inscrits et aucun encaiss\u00e9, Monaco a livr\u00e9 une tr\u00e8s bonne copie contre Auxerre samedi, ce qui lui permet de glaner un troisi\u00e8me succ\u00e8s en quatre rencontres de Ligue 1. Les Mon\u00e9gasques ont totalement ma\u00eetris\u00e9 leur sujet sur la pelouse de l&rsquo;Abb\u00e9-Deschamps, et avec une moyenne de 6,1\/10, l&rsquo;ASM est la meilleure \u00e9quipe de [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2024\/09\/16\/monaco-meilleure-equipe-de-la-4e-journee\/","og_site_name":"La Diagonale","article_published_time":"2024-09-16T12:10:19+00:00","article_modified_time":"2024-09-16T12:10:52+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/09\/2024-09-14-auxerre-asm-0109.jpg","type":"image\/jpeg"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/09\/16\/monaco-meilleure-equipe-de-la-4e-journee\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2024\/09\/16\/monaco-meilleure-equipe-de-la-4e-journee\/","name":"Monaco, meilleure \u00e9quipe de la 4e journ\u00e9e - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2024-09-16T12:10:19+00:00","dateModified":"2024-09-16T12:10:52+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/09\/16\/monaco-meilleure-equipe-de-la-4e-journee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2024\/09\/16\/monaco-meilleure-equipe-de-la-4e-journee\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/09\/16\/monaco-meilleure-equipe-de-la-4e-journee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Monaco, meilleure \u00e9quipe de la 4e journ\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/25756"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=25756"}],"version-history":[{"count":3,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/25756\/revisions"}],"predecessor-version":[{"id":25761,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/25756\/revisions\/25761"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=25756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=25756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=25756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}