{"id":26610,"date":"2024-10-13T00:21:37","date_gmt":"2024-10-12T22:21:37","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=26610"},"modified":"2024-10-13T16:02:59","modified_gmt":"2024-10-13T14:02:59","slug":"embolo-a-rate-un-penalty-avec-la-suisse","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2024\/10\/13\/embolo-a-rate-un-penalty-avec-la-suisse\/","title":{"rendered":"Embolo a rat\u00e9 un p\u00e9nalty avec la Suisse"},"content":{"rendered":"\n\n\n<p>Breel Embolo n&rsquo;a toujours pas r\u00e9ussi \u00e0 marquer cette saison. Muet en club, l&rsquo;attaquant de l&rsquo;AS Monaco l&rsquo;est tout autant en s\u00e9lection, o\u00f9 il a pourtant eu une occasion en or d&rsquo;ouvrir son compteur. Face \u00e0 la Serbie (0-2), Embolo a rat\u00e9 un p\u00e9nalty dans le dernier quart d&rsquo;heure de la rencontre. Un fait de jeu qui a terni un peu plus une rencontre plut\u00f4t m\u00e9diocre de sa part et contribu\u00e9 d&rsquo;une certaine mani\u00e8re \u00e0 la d\u00e9faite des siens. Philipp K\u00f6hn \u00e9tait sur le banc. L&rsquo;un des buts serbes a \u00e9t\u00e9 inscrit par l&rsquo;ancien Mon\u00e9gasque Strahinja Pavlovic.<\/p>\n\n\n\n<p>Les Suisses s&rsquo;enfoncent dans le marasme, avec trois d\u00e9faites lors des trois matches qui ont suivi l&rsquo;Euro, en juillet, bons derniers de leur groupe en Ligue des nations avec un z\u00e9ro point\u00e9. S&rsquo;ils veulent \u00e0 tout prix \u00e9viter une rel\u00e9gation dans la ligue inf\u00e9rieure, les hommes de Murat Yakin auront trois rencontres pour renverser la vapeur, dont la premi\u00e8re face au Danemark, mardi (20h45).<\/p>\n\n\n\n<p>Le Maroc d&rsquo;Eliesse Ben Seghir \u00e9tait quant \u00e0 lui en d\u00e9monstration face \u00e0 la R\u00e9publique centrafricaine (5-0) lors des \u00e9liminatoires de la CAN 2025. Le milieu offensif de l&rsquo;ASM \u00e9tait titulaire et a jou\u00e9 65 minutes. S&rsquo;il n&rsquo;a pas \u00e9t\u00e9 directement d\u00e9cisif, il a notamment fait une belle diff\u00e9rence dans son couloir gauche sur le second but. <\/p>\n\n\n\n<p>Les <em>Lions de l&rsquo;Atlas<\/em> dominent leur groupe avec 9 points en trois matches et pourront creuser encore un peu plus l&rsquo;\u00e9cart lors du match retour pr\u00e9vu mardi (21h), m\u00eame s&rsquo;ils sont d\u00e9j\u00e0 qualifi\u00e9s puisque pays h\u00f4te de la prochaine Coupe d&rsquo;Afrique.<\/p>\n\n\n\n<p>Chez les jeunes, deux courts succ\u00e8s pour la France U19 contre la Belgique (3-2), avec Aladji Bamba titulaire, et de la Suisse U18 face \u00e0 la Pologne (1-0), o\u00f9 Sirak Bein a jou\u00e9 9 minutes. La manche retour aura lieu mardi (13h) pour la <em>Nati<\/em> alors que les Bleuets affronteront l&rsquo;Angleterre un peu plus t\u00f4t le m\u00eame jour (12h).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Breel Embolo n&rsquo;a toujours pas r\u00e9ussi \u00e0 marquer cette saison. Muet en club, l&rsquo;attaquant de l&rsquo;AS Monaco l&rsquo;est tout autant en s\u00e9lection, o\u00f9 il a pourtant eu une occasion en or d&rsquo;ouvrir son compteur. Face \u00e0 la Serbie (0-2), Embolo a rat\u00e9 un p\u00e9nalty dans le dernier quart d&rsquo;heure de la rencontre. Un fait de [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[688,86,161,286,77,800,116,888,117,932],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Embolo a rat\u00e9 un p\u00e9nalty avec la Suisse - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2024\/10\/13\/embolo-a-rate-un-penalty-avec-la-suisse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Embolo a rat\u00e9 un p\u00e9nalty avec la Suisse - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Breel Embolo n&rsquo;a toujours pas r\u00e9ussi \u00e0 marquer cette saison. Muet en club, l&rsquo;attaquant de l&rsquo;AS Monaco l&rsquo;est tout autant en s\u00e9lection, o\u00f9 il a pourtant eu une occasion en or d&rsquo;ouvrir son compteur. Face \u00e0 la Serbie (0-2), Embolo a rat\u00e9 un p\u00e9nalty dans le dernier quart d&rsquo;heure de la rencontre. Un fait de [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2024\/10\/13\/embolo-a-rate-un-penalty-avec-la-suisse\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-12T22:21:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-13T14:02:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/06\/embolo-suisse.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/06\/embolo-suisse.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/10\/13\/embolo-a-rate-un-penalty-avec-la-suisse\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/10\/13\/embolo-a-rate-un-penalty-avec-la-suisse\/\",\"name\":\"Embolo a rat\u00e9 un p\u00e9nalty avec la Suisse - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2024-10-12T22:21:37+00:00\",\"dateModified\":\"2024-10-13T14:02:59+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/10\/13\/embolo-a-rate-un-penalty-avec-la-suisse\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2024\/10\/13\/embolo-a-rate-un-penalty-avec-la-suisse\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/10\/13\/embolo-a-rate-un-penalty-avec-la-suisse\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Embolo a rat\u00e9 un p\u00e9nalty avec la Suisse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Embolo a rat\u00e9 un p\u00e9nalty avec la Suisse - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2024\/10\/13\/embolo-a-rate-un-penalty-avec-la-suisse\/","og_locale":"fr_FR","og_type":"article","og_title":"Embolo a rat\u00e9 un p\u00e9nalty avec la Suisse - La Diagonale","og_description":"Breel Embolo n&rsquo;a toujours pas r\u00e9ussi \u00e0 marquer cette saison. Muet en club, l&rsquo;attaquant de l&rsquo;AS Monaco l&rsquo;est tout autant en s\u00e9lection, o\u00f9 il a pourtant eu une occasion en or d&rsquo;ouvrir son compteur. Face \u00e0 la Serbie (0-2), Embolo a rat\u00e9 un p\u00e9nalty dans le dernier quart d&rsquo;heure de la rencontre. Un fait de [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2024\/10\/13\/embolo-a-rate-un-penalty-avec-la-suisse\/","og_site_name":"La Diagonale","article_published_time":"2024-10-12T22:21:37+00:00","article_modified_time":"2024-10-13T14:02:59+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/06\/embolo-suisse.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/06\/embolo-suisse.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/10\/13\/embolo-a-rate-un-penalty-avec-la-suisse\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2024\/10\/13\/embolo-a-rate-un-penalty-avec-la-suisse\/","name":"Embolo a rat\u00e9 un p\u00e9nalty avec la Suisse - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2024-10-12T22:21:37+00:00","dateModified":"2024-10-13T14:02:59+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/10\/13\/embolo-a-rate-un-penalty-avec-la-suisse\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2024\/10\/13\/embolo-a-rate-un-penalty-avec-la-suisse\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/10\/13\/embolo-a-rate-un-penalty-avec-la-suisse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Embolo a rat\u00e9 un p\u00e9nalty avec la Suisse"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/26610"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=26610"}],"version-history":[{"count":6,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/26610\/revisions"}],"predecessor-version":[{"id":26619,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/26610\/revisions\/26619"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=26610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=26610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=26610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}