{"id":27496,"date":"2024-11-17T15:36:08","date_gmt":"2024-11-17T14:36:08","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=27496"},"modified":"2024-11-17T15:36:08","modified_gmt":"2024-11-17T14:36:08","slug":"un-but-pour-bamba-en-equipe-de-france-u19","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2024\/11\/17\/un-but-pour-bamba-en-equipe-de-france-u19\/","title":{"rendered":"Un but pour Bamba en \u00e9quipe de France U19"},"content":{"rendered":"\n\n\n<p>Apr\u00e8s Pape Cabral, auteur d\u2019un doubl\u00e9 il y a quelques jours lors de l\u2019\u00e9crasante victoire contre le Liechtenstein (7-0), c\u2019est cette fois Aladji Bamba qui s\u2019est mu\u00e9 en buteur avec l\u2019\u00e9quipe de France U19. Face au pays de Galles (2-1), le milieu de terrain de l\u2019AS Monaco a inscrit le but \u00e9galisateur de son \u00e9quipe. Cabral \u00e9tait titulaire (77 minutes jou\u00e9es) tandis que Joan Tincres a d\u00e9marr\u00e9 la rencontre sur le banc, entrant dans le temps additionnel.<\/p>\n\n\n\n<p>Les Bleuets auront l\u2019occasion d&rsquo;assurer leur ticket pour le Tour \u00c9lite lors du dernier match de ce premier tour de qualification contre l\u2019\u00c9cosse, mardi (20h30). Un nul leur suffira pour terminer en t\u00eate de leur groupe.<\/p>\n\n\n\n<p>En amical, l\u2019\u00e9quipe de France U20 a conc\u00e9d\u00e9 un match nul contre le Danemark (1-1). Lucas Michal, Sa\u00efmon Bouabr\u00e9 et Mayssam Benama \u00e9taient tous les trois titulaires. Lundi (17h), ils affronteront les \u00c9tats-Unis lors d\u2019une nouvelle rencontre amicale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s Pape Cabral, auteur d\u2019un doubl\u00e9 il y a quelques jours lors de l\u2019\u00e9crasante victoire contre le Liechtenstein (7-0), c\u2019est cette fois Aladji Bamba qui s\u2019est mu\u00e9 en buteur avec l\u2019\u00e9quipe de France U19. Face au pays de Galles (2-1), le milieu de terrain de l\u2019AS Monaco a inscrit le but \u00e9galisateur de son \u00e9quipe. [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[688,86,205,543,453,268,413,116],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un but pour Bamba en \u00e9quipe de France U19 - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2024\/11\/17\/un-but-pour-bamba-en-equipe-de-france-u19\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un but pour Bamba en \u00e9quipe de France U19 - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s Pape Cabral, auteur d\u2019un doubl\u00e9 il y a quelques jours lors de l\u2019\u00e9crasante victoire contre le Liechtenstein (7-0), c\u2019est cette fois Aladji Bamba qui s\u2019est mu\u00e9 en buteur avec l\u2019\u00e9quipe de France U19. Face au pays de Galles (2-1), le milieu de terrain de l\u2019AS Monaco a inscrit le but \u00e9galisateur de son \u00e9quipe. [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2024\/11\/17\/un-but-pour-bamba-en-equipe-de-france-u19\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-17T14:36:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/11\/bamba-edf.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/11\/bamba-edf.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/11\/17\/un-but-pour-bamba-en-equipe-de-france-u19\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/11\/17\/un-but-pour-bamba-en-equipe-de-france-u19\/\",\"name\":\"Un but pour Bamba en \u00e9quipe de France U19 - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2024-11-17T14:36:08+00:00\",\"dateModified\":\"2024-11-17T14:36:08+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/11\/17\/un-but-pour-bamba-en-equipe-de-france-u19\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2024\/11\/17\/un-but-pour-bamba-en-equipe-de-france-u19\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/11\/17\/un-but-pour-bamba-en-equipe-de-france-u19\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un but pour Bamba en \u00e9quipe de France U19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un but pour Bamba en \u00e9quipe de France U19 - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2024\/11\/17\/un-but-pour-bamba-en-equipe-de-france-u19\/","og_locale":"fr_FR","og_type":"article","og_title":"Un but pour Bamba en \u00e9quipe de France U19 - La Diagonale","og_description":"Apr\u00e8s Pape Cabral, auteur d\u2019un doubl\u00e9 il y a quelques jours lors de l\u2019\u00e9crasante victoire contre le Liechtenstein (7-0), c\u2019est cette fois Aladji Bamba qui s\u2019est mu\u00e9 en buteur avec l\u2019\u00e9quipe de France U19. Face au pays de Galles (2-1), le milieu de terrain de l\u2019AS Monaco a inscrit le but \u00e9galisateur de son \u00e9quipe. [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2024\/11\/17\/un-but-pour-bamba-en-equipe-de-france-u19\/","og_site_name":"La Diagonale","article_published_time":"2024-11-17T14:36:08+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/11\/bamba-edf.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/11\/bamba-edf.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/11\/17\/un-but-pour-bamba-en-equipe-de-france-u19\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2024\/11\/17\/un-but-pour-bamba-en-equipe-de-france-u19\/","name":"Un but pour Bamba en \u00e9quipe de France U19 - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2024-11-17T14:36:08+00:00","dateModified":"2024-11-17T14:36:08+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/11\/17\/un-but-pour-bamba-en-equipe-de-france-u19\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2024\/11\/17\/un-but-pour-bamba-en-equipe-de-france-u19\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/11\/17\/un-but-pour-bamba-en-equipe-de-france-u19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Un but pour Bamba en \u00e9quipe de France U19"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/27496"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=27496"}],"version-history":[{"count":1,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/27496\/revisions"}],"predecessor-version":[{"id":27498,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/27496\/revisions\/27498"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=27496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=27496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=27496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}