{"id":27960,"date":"2024-12-04T20:11:48","date_gmt":"2024-12-04T19:11:48","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=27960"},"modified":"2024-12-04T20:12:31","modified_gmt":"2024-12-04T19:12:31","slug":"officiel-magassa-prolonge-jusquen-2029","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2024\/12\/04\/officiel-magassa-prolonge-jusquen-2029\/","title":{"rendered":"Officiel : Magassa prolonge jusqu&rsquo;en 2029"},"content":{"rendered":"\n\n\n<p>L&rsquo;AS Monaco a officialis\u00e9 la prolongation du bail de Soungoutou Magassa pour deux saisons ce mercredi. Le milieu de terrain de 21 ans est d\u00e9sormais li\u00e9 avec le club de la Principaut\u00e9 jusqu&rsquo;en juin 2029. Apr\u00e8s un premier contrat professionnel sign\u00e9 en avril 2021, Magassa avait \u00e9t\u00e9 prolong\u00e9 jusqu&rsquo;en 2027 en avril 2023. Il s&rsquo;agit donc de sa deuxi\u00e8me prolongation avec l&rsquo;ASM.<\/p>\n\n\n\n<p>M\u00e9daill\u00e9 d\u2019argent des Jeux Olympiques cet \u00e9t\u00e9 avec l&rsquo;\u00e9quipe de France, Magassa s&rsquo;est impos\u00e9 comme le troisi\u00e8me choix au milieu de terrain derri\u00e8re Denis Zakaria et Lamine Camara. Cette saison, il a pris part \u00e0 13 rencontres, dont 7 en tant que titulaire, et a inscrit son premier but sous les couleurs mon\u00e9gasques contre Benfica en Ligue des champions. Au total, il a port\u00e9 le maillot \u00e0 la diagonale \u00e0 39 reprises.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;AS Monaco a officialis\u00e9 la prolongation du bail de Soungoutou Magassa pour deux saisons ce mercredi. Le milieu de terrain de 21 ans est d\u00e9sormais li\u00e9 avec le club de la Principaut\u00e9 jusqu&rsquo;en juin 2029. Apr\u00e8s un premier contrat professionnel sign\u00e9 en avril 2021, Magassa avait \u00e9t\u00e9 prolong\u00e9 jusqu&rsquo;en 2027 en avril 2023. Il s&rsquo;agit [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,6],"tags":[86,493,186,147],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Officiel : Magassa prolonge jusqu&#039;en 2029 - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2024\/12\/04\/officiel-magassa-prolonge-jusquen-2029\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Officiel : Magassa prolonge jusqu&#039;en 2029 - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;AS Monaco a officialis\u00e9 la prolongation du bail de Soungoutou Magassa pour deux saisons ce mercredi. Le milieu de terrain de 21 ans est d\u00e9sormais li\u00e9 avec le club de la Principaut\u00e9 jusqu&rsquo;en juin 2029. Apr\u00e8s un premier contrat professionnel sign\u00e9 en avril 2021, Magassa avait \u00e9t\u00e9 prolong\u00e9 jusqu&rsquo;en 2027 en avril 2023. Il s&rsquo;agit [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2024\/12\/04\/officiel-magassa-prolonge-jusquen-2029\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-04T19:11:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-04T19:12:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/12\/magassa-prolongation.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/12\/magassa-prolongation.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/12\/04\/officiel-magassa-prolonge-jusquen-2029\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/12\/04\/officiel-magassa-prolonge-jusquen-2029\/\",\"name\":\"Officiel : Magassa prolonge jusqu'en 2029 - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2024-12-04T19:11:48+00:00\",\"dateModified\":\"2024-12-04T19:12:31+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/12\/04\/officiel-magassa-prolonge-jusquen-2029\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2024\/12\/04\/officiel-magassa-prolonge-jusquen-2029\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/12\/04\/officiel-magassa-prolonge-jusquen-2029\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Officiel : Magassa prolonge jusqu&rsquo;en 2029\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Officiel : Magassa prolonge jusqu'en 2029 - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2024\/12\/04\/officiel-magassa-prolonge-jusquen-2029\/","og_locale":"fr_FR","og_type":"article","og_title":"Officiel : Magassa prolonge jusqu'en 2029 - La Diagonale","og_description":"L&rsquo;AS Monaco a officialis\u00e9 la prolongation du bail de Soungoutou Magassa pour deux saisons ce mercredi. Le milieu de terrain de 21 ans est d\u00e9sormais li\u00e9 avec le club de la Principaut\u00e9 jusqu&rsquo;en juin 2029. Apr\u00e8s un premier contrat professionnel sign\u00e9 en avril 2021, Magassa avait \u00e9t\u00e9 prolong\u00e9 jusqu&rsquo;en 2027 en avril 2023. Il s&rsquo;agit [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2024\/12\/04\/officiel-magassa-prolonge-jusquen-2029\/","og_site_name":"La Diagonale","article_published_time":"2024-12-04T19:11:48+00:00","article_modified_time":"2024-12-04T19:12:31+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/12\/magassa-prolongation.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/12\/magassa-prolongation.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/12\/04\/officiel-magassa-prolonge-jusquen-2029\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2024\/12\/04\/officiel-magassa-prolonge-jusquen-2029\/","name":"Officiel : Magassa prolonge jusqu'en 2029 - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2024-12-04T19:11:48+00:00","dateModified":"2024-12-04T19:12:31+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/12\/04\/officiel-magassa-prolonge-jusquen-2029\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2024\/12\/04\/officiel-magassa-prolonge-jusquen-2029\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/12\/04\/officiel-magassa-prolonge-jusquen-2029\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Officiel : Magassa prolonge jusqu&rsquo;en 2029"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/27960"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=27960"}],"version-history":[{"count":2,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/27960\/revisions"}],"predecessor-version":[{"id":27963,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/27960\/revisions\/27963"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=27960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=27960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=27960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}