{"id":28187,"date":"2024-12-11T09:16:34","date_gmt":"2024-12-11T08:16:34","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=28187"},"modified":"2024-12-11T09:17:30","modified_gmt":"2024-12-11T08:17:30","slug":"scuro-espere-rester-au-dela-de-son-contrat-de-trois-ans","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2024\/12\/11\/scuro-espere-rester-au-dela-de-son-contrat-de-trois-ans\/","title":{"rendered":"Scuro \u00ab esp\u00e8re rester au-del\u00e0 \u00bb de son contrat de trois ans"},"content":{"rendered":"\n<p>Dans son \u00e9dition du jour, <em>L&rsquo;\u00c9quipe <\/em>a consacr\u00e9 un portrait au Directeur g\u00e9n\u00e9ral de l&rsquo;AS Monaco Thiago Scuro. Il a notamment \u00e9t\u00e9 question de son avenir, alors qu&rsquo;Arsenal avait pens\u00e9 \u00e0 lui pour remplacer Edu, son directeur sportif d\u00e9missionnaire. Mais pour le Br\u00e9silien, quitter le club de la Principaut\u00e9 n&rsquo;est pas \u00e0 l&rsquo;ordre du jour. \u00ab <em>J\u2019ai parfois des appels, comme j\u2019avais eu celui de Paul\u00a0(Mitchell)<\/em>. <em>\u00c0 Bragantino, j\u2019avais rempli mes missions, j\u2019\u00e9tais vraiment dispos\u00e9 \u00e0 aller en Europe. Aujourd\u2019hui, quand on me sollicite, je r\u00e9ponds que ce n\u2019est pas le moment. <\/em>\u00bb<\/p>\n\n\n\n<p>Pour Scuro, il y a encore \u00e0 faire \u00e0 Monaco et l&rsquo;id\u00e9e de rester apr\u00e8s son contrat initial de trois saisons, d\u00e9but\u00e9 en juillet 2023, n&rsquo;est pas pour lui d\u00e9plaire : \u00ab <em>On est encore dans la phase o\u00f9 on doit rendre naturel que Monaco se qualifie chaque saison pour la Ligue des champions. On n\u2019est qu\u2019au milieu de quelque chose. Quand je suis arriv\u00e9 ici, mon premier but \u00e9tait de prolonger mon contrat de trois ans. J\u2019esp\u00e8re rester au-del\u00e0. Je n\u2019ai pas d\u2019autre ambition.<\/em> \u00bb\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans son \u00e9dition du jour, L&rsquo;\u00c9quipe a consacr\u00e9 un portrait au Directeur g\u00e9n\u00e9ral de l&rsquo;AS Monaco Thiago Scuro. Il a notamment \u00e9t\u00e9 question de son avenir, alors qu&rsquo;Arsenal avait pens\u00e9 \u00e0 lui pour remplacer Edu, son directeur sportif d\u00e9missionnaire. Mais pour le Br\u00e9silien, quitter le club de la Principaut\u00e9 n&rsquo;est pas \u00e0 l&rsquo;ordre du jour. [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[86,479],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Scuro \u00ab esp\u00e8re rester au-del\u00e0 \u00bb de son contrat de trois ans - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2024\/12\/11\/scuro-espere-rester-au-dela-de-son-contrat-de-trois-ans\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Scuro \u00ab esp\u00e8re rester au-del\u00e0 \u00bb de son contrat de trois ans - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Dans son \u00e9dition du jour, L&rsquo;\u00c9quipe a consacr\u00e9 un portrait au Directeur g\u00e9n\u00e9ral de l&rsquo;AS Monaco Thiago Scuro. Il a notamment \u00e9t\u00e9 question de son avenir, alors qu&rsquo;Arsenal avait pens\u00e9 \u00e0 lui pour remplacer Edu, son directeur sportif d\u00e9missionnaire. Mais pour le Br\u00e9silien, quitter le club de la Principaut\u00e9 n&rsquo;est pas \u00e0 l&rsquo;ordre du jour. [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2024\/12\/11\/scuro-espere-rester-au-dela-de-son-contrat-de-trois-ans\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-11T08:16:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-11T08:17:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/07\/scuro2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/07\/scuro2.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/12\/11\/scuro-espere-rester-au-dela-de-son-contrat-de-trois-ans\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/12\/11\/scuro-espere-rester-au-dela-de-son-contrat-de-trois-ans\/\",\"name\":\"Scuro \u00ab esp\u00e8re rester au-del\u00e0 \u00bb de son contrat de trois ans - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2024-12-11T08:16:34+00:00\",\"dateModified\":\"2024-12-11T08:17:30+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/12\/11\/scuro-espere-rester-au-dela-de-son-contrat-de-trois-ans\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2024\/12\/11\/scuro-espere-rester-au-dela-de-son-contrat-de-trois-ans\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2024\/12\/11\/scuro-espere-rester-au-dela-de-son-contrat-de-trois-ans\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Scuro \u00ab esp\u00e8re rester au-del\u00e0 \u00bb de son contrat de trois ans\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Scuro \u00ab esp\u00e8re rester au-del\u00e0 \u00bb de son contrat de trois ans - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2024\/12\/11\/scuro-espere-rester-au-dela-de-son-contrat-de-trois-ans\/","og_locale":"fr_FR","og_type":"article","og_title":"Scuro \u00ab esp\u00e8re rester au-del\u00e0 \u00bb de son contrat de trois ans - La Diagonale","og_description":"Dans son \u00e9dition du jour, L&rsquo;\u00c9quipe a consacr\u00e9 un portrait au Directeur g\u00e9n\u00e9ral de l&rsquo;AS Monaco Thiago Scuro. Il a notamment \u00e9t\u00e9 question de son avenir, alors qu&rsquo;Arsenal avait pens\u00e9 \u00e0 lui pour remplacer Edu, son directeur sportif d\u00e9missionnaire. Mais pour le Br\u00e9silien, quitter le club de la Principaut\u00e9 n&rsquo;est pas \u00e0 l&rsquo;ordre du jour. [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2024\/12\/11\/scuro-espere-rester-au-dela-de-son-contrat-de-trois-ans\/","og_site_name":"La Diagonale","article_published_time":"2024-12-11T08:16:34+00:00","article_modified_time":"2024-12-11T08:17:30+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/07\/scuro2.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/07\/scuro2.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/12\/11\/scuro-espere-rester-au-dela-de-son-contrat-de-trois-ans\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2024\/12\/11\/scuro-espere-rester-au-dela-de-son-contrat-de-trois-ans\/","name":"Scuro \u00ab esp\u00e8re rester au-del\u00e0 \u00bb de son contrat de trois ans - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2024-12-11T08:16:34+00:00","dateModified":"2024-12-11T08:17:30+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/12\/11\/scuro-espere-rester-au-dela-de-son-contrat-de-trois-ans\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2024\/12\/11\/scuro-espere-rester-au-dela-de-son-contrat-de-trois-ans\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2024\/12\/11\/scuro-espere-rester-au-dela-de-son-contrat-de-trois-ans\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Scuro \u00ab esp\u00e8re rester au-del\u00e0 \u00bb de son contrat de trois ans"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/28187"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=28187"}],"version-history":[{"count":3,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/28187\/revisions"}],"predecessor-version":[{"id":28190,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/28187\/revisions\/28190"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=28187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=28187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=28187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}