{"id":28879,"date":"2025-01-13T21:33:01","date_gmt":"2025-01-13T20:33:01","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=28879"},"modified":"2025-01-13T21:33:02","modified_gmt":"2025-01-13T20:33:02","slug":"biereth-je-me-considere-comme-un-attaquant-a-lancienne","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2025\/01\/13\/biereth-je-me-considere-comme-un-attaquant-a-lancienne\/","title":{"rendered":"Biereth : \u00ab\u00a0Je me consid\u00e8re comme un attaquant \u00e0 l\u2019ancienne\u00a0\u00bb"},"content":{"rendered":"\n\n\n<p>Mika Biereth a \u00e9t\u00e9 pr\u00e9sent\u00e9 \u00e0 la presse ce lundi. L\u2019attaquant danois, n\u00e9 \u00e0 Londres, a affich\u00e9 sa satisfaction de signer pour l\u2019AS Monaco : \u00ab\u00a0<em>Il \u00e9tait temps pour moi de franchir un nouveau cap. L\u2019ambition de l\u2019AS Monaco est grande, et d\u00e8s que j\u2019ai eu connaissance de l\u2019int\u00e9r\u00eat que le Club portait pour moi, j\u2019ai tout de suite voulu venir et je n\u2019avais plus que \u00e7a en t\u00eate ! Je veux poursuivre l\u2019h\u00e9ritage des attaquants pass\u00e9s ici.<\/em>\u00a0\u00bb<\/p>\n\n\n\n<p>Le match amical entre son ancien club du Sturm Graz et Monaco cet \u00e9t\u00e9 lui avait permis de voir le club de la Principaut\u00e9 sous un angle positif : \u00ab\u00a0<em>On a pu voir le niveau de l\u2019AS Monaco qui est une tr\u00e8s bonne \u00e9quipe, mais je voulais surtout gagner et marquer des buts, et c\u2019est ce que j\u2019ai fait sur penalty. Mes premi\u00e8res impressions ont \u00e9t\u00e9 bonnes, j\u2019ai vu une \u00e9quipe impressionnante dans sa mani\u00e8re de jouer, j\u2019ai pu parler avec les joueurs \u00e0 la fin du match et j\u2019ai vu ce c\u00f4t\u00e9 humain tr\u00e8s pr\u00e9sent. C\u2019\u00e9tait l\u2019une des raisons qui m\u2019ont pouss\u00e9 \u00e0 venir ici.<\/em>\u00a0\u00bb\u00a0<\/p>\n\n\n\n<p>S\u2019il appr\u00e9cie Haaland pour sa science du placement et de Drogba pour sa qualit\u00e9 athl\u00e9tique, il a d\u00e9crit le type de joueur qu\u2019il \u00e9tait : \u00ab\u00a0<em>Je me consid\u00e8re comme un attaquant \u00ab\u00a0\u00e0 l\u2019ancienne\u00a0\u00bb, j\u2019adore marquer des buts et trouver la bonne position pour \u00eatre d\u00e9cisif. M\u00eame si je pense que vous n\u2019avez pas du voir des buts \u00ab\u00a0venus d\u2019ailleurs\u00a0\u00bb dans mes highlights sur YouTube (sourire). J\u2019essaie d\u2019\u00eatre le plus r\u00e9gulier possible, un but est un but, et c\u2019est \u00e7a le plus important.<\/em>\u00a0\u00bb<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\"><p>\u00a0\u00ab\u00a0C\u2019est bon de revoir Balo\u2019 (Balogun)\u00a0\u00bb<\/p><\/blockquote>\n\n\n\n<p>\u00c2g\u00e9 de 21 ans, Biereth se sent pr\u00eat \u00e0 affronter la concurrence en Principaut\u00e9 : \u00ab <em>L\u2019AS Monaco est un grand club, donc les places sont ch\u00e8res, mais la hi\u00e9rarchie peut bouger \u00e0 tout moment. Quand vous \u00eates un attaquant, il faut marquer le plus de buts possible et cette comp\u00e9titivit\u00e9 \u00e0 ce poste au sein du club est bonne. Ma d\u00e9cision s\u2019est donc \u00e9galement faite sur cet aspect-l\u00e0.\u00a0<\/em>\u00bb<\/p>\n\n\n\n<p>\u00c0 terme, Folarin Balogun, qui doit encore soigner son \u00e9paule, raison pour laquelle l\u2019ASM l\u2019a sign\u00e9, deviendra un concurrent. Pour l\u2019instant, il reste un joueur qu\u2019il conna\u00eet bien pour l\u2019avoir c\u00f4toy\u00e9 chez les jeunes \u00e0 Arsenal : \u00ab\u00a0<em>C\u2019est bon de revoir Balo\u2019, il m\u2019a souhait\u00e9 la bienvenue au club. Nous avons jou\u00e9 ensemble chez les U21 d\u2019Arsenal, donc on se conna\u00eet bien. Maintenant que nous sommes r\u00e9unis, nous pouvons apprendre des exp\u00e9riences de l\u2019un et de l\u2019autre.<\/em>\u00a0\u00bb<\/p>\n\n\n\n<p class=\"has-text-align-right has-small-font-size\">Source : <em>AS Monaco<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mika Biereth a \u00e9t\u00e9 pr\u00e9sent\u00e9 \u00e0 la presse ce lundi. L\u2019attaquant danois, n\u00e9 \u00e0 Londres, a affich\u00e9 sa satisfaction de signer pour l\u2019AS Monaco : \u00ab\u00a0Il \u00e9tait temps pour moi de franchir un nouveau cap. L\u2019ambition de l\u2019AS Monaco est grande, et d\u00e8s que j\u2019ai eu connaissance de l\u2019int\u00e9r\u00eat que le Club portait pour moi, [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[86,111,965,110],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Biereth : \u00ab\u00a0Je me consid\u00e8re comme un attaquant \u00e0 l\u2019ancienne\u00a0\u00bb - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2025\/01\/13\/biereth-je-me-considere-comme-un-attaquant-a-lancienne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biereth : \u00ab\u00a0Je me consid\u00e8re comme un attaquant \u00e0 l\u2019ancienne\u00a0\u00bb - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Mika Biereth a \u00e9t\u00e9 pr\u00e9sent\u00e9 \u00e0 la presse ce lundi. L\u2019attaquant danois, n\u00e9 \u00e0 Londres, a affich\u00e9 sa satisfaction de signer pour l\u2019AS Monaco : \u00ab\u00a0Il \u00e9tait temps pour moi de franchir un nouveau cap. L\u2019ambition de l\u2019AS Monaco est grande, et d\u00e8s que j\u2019ai eu connaissance de l\u2019int\u00e9r\u00eat que le Club portait pour moi, [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2025\/01\/13\/biereth-je-me-considere-comme-un-attaquant-a-lancienne\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-13T20:33:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-13T20:33:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2025\/01\/IMG_8551.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"430\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2025\/01\/IMG_8551.jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/01\/13\/biereth-je-me-considere-comme-un-attaquant-a-lancienne\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/01\/13\/biereth-je-me-considere-comme-un-attaquant-a-lancienne\/\",\"name\":\"Biereth : \u00ab\u00a0Je me consid\u00e8re comme un attaquant \u00e0 l\u2019ancienne\u00a0\u00bb - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2025-01-13T20:33:01+00:00\",\"dateModified\":\"2025-01-13T20:33:02+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/01\/13\/biereth-je-me-considere-comme-un-attaquant-a-lancienne\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2025\/01\/13\/biereth-je-me-considere-comme-un-attaquant-a-lancienne\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/01\/13\/biereth-je-me-considere-comme-un-attaquant-a-lancienne\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Biereth : \u00ab\u00a0Je me consid\u00e8re comme un attaquant \u00e0 l\u2019ancienne\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Biereth : \u00ab\u00a0Je me consid\u00e8re comme un attaquant \u00e0 l\u2019ancienne\u00a0\u00bb - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2025\/01\/13\/biereth-je-me-considere-comme-un-attaquant-a-lancienne\/","og_locale":"fr_FR","og_type":"article","og_title":"Biereth : \u00ab\u00a0Je me consid\u00e8re comme un attaquant \u00e0 l\u2019ancienne\u00a0\u00bb - La Diagonale","og_description":"Mika Biereth a \u00e9t\u00e9 pr\u00e9sent\u00e9 \u00e0 la presse ce lundi. L\u2019attaquant danois, n\u00e9 \u00e0 Londres, a affich\u00e9 sa satisfaction de signer pour l\u2019AS Monaco : \u00ab\u00a0Il \u00e9tait temps pour moi de franchir un nouveau cap. L\u2019ambition de l\u2019AS Monaco est grande, et d\u00e8s que j\u2019ai eu connaissance de l\u2019int\u00e9r\u00eat que le Club portait pour moi, [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2025\/01\/13\/biereth-je-me-considere-comme-un-attaquant-a-lancienne\/","og_site_name":"La Diagonale","article_published_time":"2025-01-13T20:33:01+00:00","article_modified_time":"2025-01-13T20:33:02+00:00","og_image":[{"width":768,"height":430,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2025\/01\/IMG_8551.jpeg","type":"image\/jpeg"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2025\/01\/IMG_8551.jpeg","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2025\/01\/13\/biereth-je-me-considere-comme-un-attaquant-a-lancienne\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2025\/01\/13\/biereth-je-me-considere-comme-un-attaquant-a-lancienne\/","name":"Biereth : \u00ab\u00a0Je me consid\u00e8re comme un attaquant \u00e0 l\u2019ancienne\u00a0\u00bb - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2025-01-13T20:33:01+00:00","dateModified":"2025-01-13T20:33:02+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2025\/01\/13\/biereth-je-me-considere-comme-un-attaquant-a-lancienne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2025\/01\/13\/biereth-je-me-considere-comme-un-attaquant-a-lancienne\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2025\/01\/13\/biereth-je-me-considere-comme-un-attaquant-a-lancienne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Biereth : \u00ab\u00a0Je me consid\u00e8re comme un attaquant \u00e0 l\u2019ancienne\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/28879"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=28879"}],"version-history":[{"count":1,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/28879\/revisions"}],"predecessor-version":[{"id":28880,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/28879\/revisions\/28880"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=28879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=28879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=28879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}