{"id":29450,"date":"2025-01-31T18:20:19","date_gmt":"2025-01-31T17:20:19","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=29450"},"modified":"2025-01-31T18:20:19","modified_gmt":"2025-01-31T17:20:19","slug":"pour-hutter-pas-de-revanche-a-prendre-contre-benfica","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2025\/01\/31\/pour-hutter-pas-de-revanche-a-prendre-contre-benfica\/","title":{"rendered":"Pour H\u00fctter, \u00ab\u00a0pas de revanche \u00e0 prendre\u00a0\u00bb contre Benfica"},"content":{"rendered":"\n\n\n<p>En conf\u00e9rence de presse, Adi H\u00fctter s\u2019est exprim\u00e9 sur le tirage au sort qui donnera l\u2019occasion \u00e0 l\u2019AS Monaco d\u2019affronter Benfica lors du barrage. Le coach mon\u00e9gasque pr\u00e9f\u00e8re cela que de jouer Paris de mani\u00e8re aussi rapproch\u00e9e : \u00ab\u00a0<em>Je n\u2019avais pas de d\u00e9sir particulier. Mais pour \u00eatre honn\u00eate, jouer cinq fois le Paris Saint-Germain en deux mois, \u00e7a aurait fait beaucoup. Voil\u00e0 pourquoi nous pr\u00e9f\u00e9rons tout de m\u00eame affronter Benfica, car il aurait \u00e9t\u00e9 dommage de tomber sur une \u00e9quipe de notre championnat. Sur le plan sportif ? Benfica est une \u00e9quipe de grande qualit\u00e9, et nous l\u2019avons vu il y a un mois et demi \u00e0 la maison. C\u2019est \u00e9galement un club qui a une grande histoire en Ligue des Champions, et qui l\u2019a d\u2019ailleurs remport\u00e9 \u00e0 deux reprises (1961, 1962, ndlr).<\/em>\u00a0\u00bb<\/p>\n\n\n\n<p>L\u2019Autrichien n\u2019est pas sp\u00e9cialement anim\u00e9 d\u2019un sentiment de revanche apr\u00e8s la rencontre qui avait oppos\u00e9 les deux \u00e9quipes en novembre, remport\u00e9e par la formation portugaise : \u00ab\u00a0<em>Pour moi il n\u2019y a pas de revanche \u00e0 prendre, c\u2019est un barrage aller-retour, et je vois \u00e7a comme une opportunit\u00e9 pour nous de nous qualifier pour le prochain tour de Ligue des Champions. Je pense qu\u2019il y aura un autre arbitre, mais je n\u2019aime pas trop parler de cela. Il est \u00e9vident que la situation \u00e9tait \u00e9trange lors de ce match, sur certaines actions et m\u00eame dans la communication avec les joueurs. Nous recevions des cartons tr\u00e8s vite, mais je pense qu\u2019il n\u2019\u00e9tait pas dans un tr\u00e8s bon jour. Je suis s\u00fbr que ce sera diff\u00e9rent cette fois, m\u00eame si l\u2019arbitre n\u2019\u00e9tait pas coupable de notre d\u00e9faite, car nous aurions d\u00fb mieux d\u00e9fendre. Mais d\u00e9sormais ce sera une autre histoire.<\/em>\u00a0\u00bb<\/p>\n\n\n\n<p class=\"has-text-align-right has-small-font-size\">Source : <em>AS Monaco<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En conf\u00e9rence de presse, Adi H\u00fctter s\u2019est exprim\u00e9 sur le tirage au sort qui donnera l\u2019occasion \u00e0 l\u2019AS Monaco d\u2019affronter Benfica lors du barrage. Le coach mon\u00e9gasque pr\u00e9f\u00e8re cela que de jouer Paris de mani\u00e8re aussi rapproch\u00e9e : \u00ab\u00a0Je n\u2019avais pas de d\u00e9sir particulier. Mais pour \u00eatre honn\u00eate, jouer cinq fois le Paris Saint-Germain en [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[576,86,287,948],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pour H\u00fctter, \u00ab\u00a0pas de revanche \u00e0 prendre\u00a0\u00bb contre Benfica - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2025\/01\/31\/pour-hutter-pas-de-revanche-a-prendre-contre-benfica\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pour H\u00fctter, \u00ab\u00a0pas de revanche \u00e0 prendre\u00a0\u00bb contre Benfica - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"En conf\u00e9rence de presse, Adi H\u00fctter s\u2019est exprim\u00e9 sur le tirage au sort qui donnera l\u2019occasion \u00e0 l\u2019AS Monaco d\u2019affronter Benfica lors du barrage. Le coach mon\u00e9gasque pr\u00e9f\u00e8re cela que de jouer Paris de mani\u00e8re aussi rapproch\u00e9e : \u00ab\u00a0Je n\u2019avais pas de d\u00e9sir particulier. Mais pour \u00eatre honn\u00eate, jouer cinq fois le Paris Saint-Germain en [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2025\/01\/31\/pour-hutter-pas-de-revanche-a-prendre-contre-benfica\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-31T17:20:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/12\/Hutterldcconf.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/12\/Hutterldcconf.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/01\/31\/pour-hutter-pas-de-revanche-a-prendre-contre-benfica\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/01\/31\/pour-hutter-pas-de-revanche-a-prendre-contre-benfica\/\",\"name\":\"Pour H\u00fctter, \u00ab\u00a0pas de revanche \u00e0 prendre\u00a0\u00bb contre Benfica - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2025-01-31T17:20:19+00:00\",\"dateModified\":\"2025-01-31T17:20:19+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/01\/31\/pour-hutter-pas-de-revanche-a-prendre-contre-benfica\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2025\/01\/31\/pour-hutter-pas-de-revanche-a-prendre-contre-benfica\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/01\/31\/pour-hutter-pas-de-revanche-a-prendre-contre-benfica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pour H\u00fctter, \u00ab\u00a0pas de revanche \u00e0 prendre\u00a0\u00bb contre Benfica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pour H\u00fctter, \u00ab\u00a0pas de revanche \u00e0 prendre\u00a0\u00bb contre Benfica - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2025\/01\/31\/pour-hutter-pas-de-revanche-a-prendre-contre-benfica\/","og_locale":"fr_FR","og_type":"article","og_title":"Pour H\u00fctter, \u00ab\u00a0pas de revanche \u00e0 prendre\u00a0\u00bb contre Benfica - La Diagonale","og_description":"En conf\u00e9rence de presse, Adi H\u00fctter s\u2019est exprim\u00e9 sur le tirage au sort qui donnera l\u2019occasion \u00e0 l\u2019AS Monaco d\u2019affronter Benfica lors du barrage. Le coach mon\u00e9gasque pr\u00e9f\u00e8re cela que de jouer Paris de mani\u00e8re aussi rapproch\u00e9e : \u00ab\u00a0Je n\u2019avais pas de d\u00e9sir particulier. Mais pour \u00eatre honn\u00eate, jouer cinq fois le Paris Saint-Germain en [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2025\/01\/31\/pour-hutter-pas-de-revanche-a-prendre-contre-benfica\/","og_site_name":"La Diagonale","article_published_time":"2025-01-31T17:20:19+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/12\/Hutterldcconf.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/12\/Hutterldcconf.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2025\/01\/31\/pour-hutter-pas-de-revanche-a-prendre-contre-benfica\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2025\/01\/31\/pour-hutter-pas-de-revanche-a-prendre-contre-benfica\/","name":"Pour H\u00fctter, \u00ab\u00a0pas de revanche \u00e0 prendre\u00a0\u00bb contre Benfica - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2025-01-31T17:20:19+00:00","dateModified":"2025-01-31T17:20:19+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2025\/01\/31\/pour-hutter-pas-de-revanche-a-prendre-contre-benfica\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2025\/01\/31\/pour-hutter-pas-de-revanche-a-prendre-contre-benfica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2025\/01\/31\/pour-hutter-pas-de-revanche-a-prendre-contre-benfica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Pour H\u00fctter, \u00ab\u00a0pas de revanche \u00e0 prendre\u00a0\u00bb contre Benfica"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/29450"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=29450"}],"version-history":[{"count":1,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/29450\/revisions"}],"predecessor-version":[{"id":29451,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/29450\/revisions\/29451"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=29450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=29450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=29450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}