{"id":29531,"date":"2025-02-01T23:57:14","date_gmt":"2025-02-01T22:57:14","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=29531"},"modified":"2025-02-01T23:57:15","modified_gmt":"2025-02-01T22:57:15","slug":"bellegarde-pour-remplacer-magassa","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2025\/02\/01\/bellegarde-pour-remplacer-magassa\/","title":{"rendered":"Bellegarde pour remplacer Magassa ?"},"content":{"rendered":"\n\n\n<p> Ce samedi, une rumeur faisait \u00e9tat <a href=\"https:\/\/www.ladiagonale.net\/index.php\/2025\/02\/01\/wolverhampton-aurait-fait-une-offre-pour-magassa\/\" target=\"_blank\" rel=\"noreferrer noopener\">d\u2019une offre de Wolverhmapton pour Soungoutou Magassa<\/a>. Si l\u2019AS Monaco n\u2019avait <em>a priori<\/em> pas pr\u00e9vu de vendre son milieu de terrain, elle n\u2019aurait visiblement pas totalement ferm\u00e9 la porte aux n\u00e9gociations. Et dans celles-ci, il aurait \u00e9t\u00e9 question d\u2019un \u00e9change avec Jeanricner Bellegarde. Selon <em>Foot Mercato<\/em>, l\u2019ancien Strasbourgeois de 26 ans pourrait en effet faire le chemin inverse et retrouver les pelouses de Ligue 1, qu\u2019il avait quitt\u00e9es \u00e0 l\u2019\u00e9t\u00e9 2023.<\/p>\n\n\n\n<p>Soungoutou Magassa, li\u00e9 \u00e0 l\u2019ASM jusqu\u2019en 2029, aurait une valeur estim\u00e9e entre 15 et 20 millions d\u2019euros et susciterait aussi l\u2019int\u00e9r\u00eat de l\u2019Atl\u00e9tico de Madrid. Il a pris part \u00e0 24 rencontres cette saison. De son c\u00f4t\u00e9, Bellegarde est sous contrat avec les <em>Wolves<\/em> jusqu\u2019en 2028 et a jou\u00e9 \u00e9galement 24 matches cette saison.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce samedi, une rumeur faisait \u00e9tat d\u2019une offre de Wolverhmapton pour Soungoutou Magassa. Si l\u2019AS Monaco n\u2019avait a priori pas pr\u00e9vu de vendre son milieu de terrain, elle n\u2019aurait visiblement pas totalement ferm\u00e9 la porte aux n\u00e9gociations. Et dans celles-ci, il aurait \u00e9t\u00e9 question d\u2019un \u00e9change avec Jeanricner Bellegarde. Selon Foot Mercato, l\u2019ancien Strasbourgeois de [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[86,988,111,147,110],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bellegarde pour remplacer Magassa ? - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2025\/02\/01\/bellegarde-pour-remplacer-magassa\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bellegarde pour remplacer Magassa ? - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Ce samedi, une rumeur faisait \u00e9tat d\u2019une offre de Wolverhmapton pour Soungoutou Magassa. Si l\u2019AS Monaco n\u2019avait a priori pas pr\u00e9vu de vendre son milieu de terrain, elle n\u2019aurait visiblement pas totalement ferm\u00e9 la porte aux n\u00e9gociations. Et dans celles-ci, il aurait \u00e9t\u00e9 question d\u2019un \u00e9change avec Jeanricner Bellegarde. Selon Foot Mercato, l\u2019ancien Strasbourgeois de [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2025\/02\/01\/bellegarde-pour-remplacer-magassa\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-01T22:57:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-01T22:57:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2025\/02\/Bellegarde.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2025\/02\/Bellegarde.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/02\/01\/bellegarde-pour-remplacer-magassa\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/02\/01\/bellegarde-pour-remplacer-magassa\/\",\"name\":\"Bellegarde pour remplacer Magassa ? - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2025-02-01T22:57:14+00:00\",\"dateModified\":\"2025-02-01T22:57:15+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/02\/01\/bellegarde-pour-remplacer-magassa\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2025\/02\/01\/bellegarde-pour-remplacer-magassa\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/02\/01\/bellegarde-pour-remplacer-magassa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bellegarde pour remplacer Magassa ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bellegarde pour remplacer Magassa ? - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2025\/02\/01\/bellegarde-pour-remplacer-magassa\/","og_locale":"fr_FR","og_type":"article","og_title":"Bellegarde pour remplacer Magassa ? - La Diagonale","og_description":"Ce samedi, une rumeur faisait \u00e9tat d\u2019une offre de Wolverhmapton pour Soungoutou Magassa. Si l\u2019AS Monaco n\u2019avait a priori pas pr\u00e9vu de vendre son milieu de terrain, elle n\u2019aurait visiblement pas totalement ferm\u00e9 la porte aux n\u00e9gociations. Et dans celles-ci, il aurait \u00e9t\u00e9 question d\u2019un \u00e9change avec Jeanricner Bellegarde. Selon Foot Mercato, l\u2019ancien Strasbourgeois de [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2025\/02\/01\/bellegarde-pour-remplacer-magassa\/","og_site_name":"La Diagonale","article_published_time":"2025-02-01T22:57:14+00:00","article_modified_time":"2025-02-01T22:57:15+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2025\/02\/Bellegarde.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2025\/02\/Bellegarde.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2025\/02\/01\/bellegarde-pour-remplacer-magassa\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2025\/02\/01\/bellegarde-pour-remplacer-magassa\/","name":"Bellegarde pour remplacer Magassa ? - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2025-02-01T22:57:14+00:00","dateModified":"2025-02-01T22:57:15+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2025\/02\/01\/bellegarde-pour-remplacer-magassa\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2025\/02\/01\/bellegarde-pour-remplacer-magassa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2025\/02\/01\/bellegarde-pour-remplacer-magassa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Bellegarde pour remplacer Magassa ?"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/29531"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=29531"}],"version-history":[{"count":1,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/29531\/revisions"}],"predecessor-version":[{"id":29533,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/29531\/revisions\/29533"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=29531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=29531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=29531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}