{"id":29873,"date":"2025-02-17T01:52:15","date_gmt":"2025-02-17T00:52:15","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=29873"},"modified":"2025-02-17T01:52:16","modified_gmt":"2025-02-17T00:52:16","slug":"le-deplacement-a-angers-fixe-au-15-mars","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2025\/02\/17\/le-deplacement-a-angers-fixe-au-15-mars\/","title":{"rendered":"Le d\u00e9placement \u00e0 Angers fix\u00e9 au 15 mars"},"content":{"rendered":"\n\n\n<p>La programmation de la 26<sup>e<\/sup> journ\u00e9e a \u00e9t\u00e9 d\u00e9voil\u00e9e par la LFP. Monaco se rendra \u00e0 Angers pour prendre sa revanche apr\u00e8s le non match r\u00e9alis\u00e9 lors de l&rsquo;aller (0-1). La rencontre a \u00e9t\u00e9 fix\u00e9e au samedi 15 mars et d\u00e9butera \u00e0 19 heures. Sa diffusion sera op\u00e9r\u00e9e par <em>DAZN<\/em>. <\/p>\n\n\n\n<p>Pour l&rsquo;ASM, il faudra esp\u00e9rer que cette rencontre suive une autre de Ligue des champions, en l&rsquo;occurrence le 8<sup>e<\/sup> de finale retour de la comp\u00e9tition, car cela serait synonyme de qualification face \u00e0 Benfica, mardi, \u00e0 l&rsquo;occasion de la phase de barrage.<\/p>\n\n\n\n<h3>La programmation compl\u00e8te de la 26<sup>e<\/sup> journ\u00e9e <\/h3>\n\n\n\n<p>Vendredi 14 mars 2025 \u00e0 20h45 sur DAZN<br>OGC Nice \u2013 AJ Auxerre<\/p>\n\n\n\n<p>Samedi 15 mars 2025 \u00e0 17h00 sur beIN SPORTS 1<br>FC Nantes \u2013 LOSC Lille<\/p>\n\n\n\n<p><strong>Samedi 15 mars 2025 \u00e0 19h00 sur DAZN<br>Angers SCO \u2013 AS Monaco<\/strong><\/p>\n\n\n\n<p>Samedi 15 mars 2025 \u00e0 21h05 sur DAZN<br>RC Lens \u2013 Stade Rennais FC<\/p>\n\n\n\n<p>Dimanche 16 mars 2025 \u00e0 15h00 sur DAZN<br>Olympique Lyonnais \u2013 Havre AC<\/p>\n\n\n\n<p>Dimanche 16 mars 2025 \u00e0 17h15 sur DAZN<br>RC Strasbourg Alsace \u2013 Toulouse FC<br>Stade Brestois 29 \u2013 Stade de Reims<br>Montpellier H\u00e9rault SC \u2013 AS Saint-\u00c9tienne<\/p>\n\n\n\n<p>Dimanche 16 mars 2025 \u00e0 20h45 sur DAZN<br>Paris Saint-Germain \u2013 Olympique de Marseille<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La programmation de la 26e journ\u00e9e a \u00e9t\u00e9 d\u00e9voil\u00e9e par la LFP. Monaco se rendra \u00e0 Angers pour prendre sa revanche apr\u00e8s le non match r\u00e9alis\u00e9 lors de l&rsquo;aller (0-1). La rencontre a \u00e9t\u00e9 fix\u00e9e au samedi 15 mars et d\u00e9butera \u00e0 19 heures. Sa diffusion sera op\u00e9r\u00e9e par DAZN. Pour l&rsquo;ASM, il faudra esp\u00e9rer [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[475,86,896,94,172],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le d\u00e9placement \u00e0 Angers fix\u00e9 au 15 mars - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2025\/02\/17\/le-deplacement-a-angers-fixe-au-15-mars\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le d\u00e9placement \u00e0 Angers fix\u00e9 au 15 mars - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"La programmation de la 26e journ\u00e9e a \u00e9t\u00e9 d\u00e9voil\u00e9e par la LFP. Monaco se rendra \u00e0 Angers pour prendre sa revanche apr\u00e8s le non match r\u00e9alis\u00e9 lors de l&rsquo;aller (0-1). La rencontre a \u00e9t\u00e9 fix\u00e9e au samedi 15 mars et d\u00e9butera \u00e0 19 heures. Sa diffusion sera op\u00e9r\u00e9e par DAZN. Pour l&rsquo;ASM, il faudra esp\u00e9rer [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2025\/02\/17\/le-deplacement-a-angers-fixe-au-15-mars\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-17T00:52:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-17T00:52:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/09\/prog.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/09\/prog.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/02\/17\/le-deplacement-a-angers-fixe-au-15-mars\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/02\/17\/le-deplacement-a-angers-fixe-au-15-mars\/\",\"name\":\"Le d\u00e9placement \u00e0 Angers fix\u00e9 au 15 mars - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2025-02-17T00:52:15+00:00\",\"dateModified\":\"2025-02-17T00:52:16+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/02\/17\/le-deplacement-a-angers-fixe-au-15-mars\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2025\/02\/17\/le-deplacement-a-angers-fixe-au-15-mars\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/02\/17\/le-deplacement-a-angers-fixe-au-15-mars\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le d\u00e9placement \u00e0 Angers fix\u00e9 au 15 mars\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le d\u00e9placement \u00e0 Angers fix\u00e9 au 15 mars - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2025\/02\/17\/le-deplacement-a-angers-fixe-au-15-mars\/","og_locale":"fr_FR","og_type":"article","og_title":"Le d\u00e9placement \u00e0 Angers fix\u00e9 au 15 mars - La Diagonale","og_description":"La programmation de la 26e journ\u00e9e a \u00e9t\u00e9 d\u00e9voil\u00e9e par la LFP. Monaco se rendra \u00e0 Angers pour prendre sa revanche apr\u00e8s le non match r\u00e9alis\u00e9 lors de l&rsquo;aller (0-1). La rencontre a \u00e9t\u00e9 fix\u00e9e au samedi 15 mars et d\u00e9butera \u00e0 19 heures. Sa diffusion sera op\u00e9r\u00e9e par DAZN. Pour l&rsquo;ASM, il faudra esp\u00e9rer [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2025\/02\/17\/le-deplacement-a-angers-fixe-au-15-mars\/","og_site_name":"La Diagonale","article_published_time":"2025-02-17T00:52:15+00:00","article_modified_time":"2025-02-17T00:52:16+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/09\/prog.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/09\/prog.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2025\/02\/17\/le-deplacement-a-angers-fixe-au-15-mars\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2025\/02\/17\/le-deplacement-a-angers-fixe-au-15-mars\/","name":"Le d\u00e9placement \u00e0 Angers fix\u00e9 au 15 mars - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2025-02-17T00:52:15+00:00","dateModified":"2025-02-17T00:52:16+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2025\/02\/17\/le-deplacement-a-angers-fixe-au-15-mars\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2025\/02\/17\/le-deplacement-a-angers-fixe-au-15-mars\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2025\/02\/17\/le-deplacement-a-angers-fixe-au-15-mars\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Le d\u00e9placement \u00e0 Angers fix\u00e9 au 15 mars"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/29873"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=29873"}],"version-history":[{"count":1,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/29873\/revisions"}],"predecessor-version":[{"id":29874,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/29873\/revisions\/29874"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=29873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=29873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=29873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}