{"id":30541,"date":"2025-03-25T08:53:00","date_gmt":"2025-03-25T07:53:00","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=30541"},"modified":"2025-03-25T04:06:27","modified_gmt":"2025-03-25T03:06:27","slug":"hutter-dire-que-je-ne-suis-pas-tres-bon-en-communication-cest-me-donner-un-coup-derriere-la-nuque","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2025\/03\/25\/hutter-dire-que-je-ne-suis-pas-tres-bon-en-communication-cest-me-donner-un-coup-derriere-la-nuque\/","title":{"rendered":"H\u00fctter : \u00ab\u00a0Dire que je ne suis pas tr\u00e8s bon en communication, c&rsquo;est me donner un coup derri\u00e8re la nuque\u00a0\u00bb"},"content":{"rendered":"\n\n\n<p>Dans le long entretien <a href=\"https:\/\/www.ladiagonale.net\/index.php\/2025\/03\/24\/hutter-a-la-presse-de-la-pression-vous-men-avez-mis-dans-vos-articles\/\" target=\"_blank\" rel=\"noreferrer noopener\">qu&rsquo;il a accord\u00e9 \u00e0<em> L&rsquo;\u00c9quipe<\/em><\/a>, Adi H\u00fctter a d\u00e9fendu son bilan \u00e0 la t\u00eate de l&rsquo;AS Monaco, mais il a aussi accept\u00e9 d&rsquo;\u00e9voquer son management. Sans aller jusqu&rsquo;\u00e0 dire qu&rsquo;il a pu \u00eatre contest\u00e9 en interne, l&rsquo;Autrichien a pu faire certains choix qui ont fait l&rsquo;objet d&rsquo;interrogations et d&rsquo;incompr\u00e9hensions dans le vestiaire mon\u00e9gasque, selon certains bruits remont\u00e9s par des agents de joueurs. \u00ab&nbsp;<em>Je sais que les agents ne sont pas heureux quand leurs joueurs ne sont pas sur le terrain<\/em>, a r\u00e9pondu H\u00fctter. <em>Dans un monde id\u00e9al, j&rsquo;aimerais voir chaque joueur dix ou quinze minutes tous les jours. Mais c&rsquo;est impossible. Je peux comprendre que les joueurs peuvent attendre un peu plus, mais quand vous jouez tous les trois jours, ce n&rsquo;est pas \u00e9vident d&rsquo;avoir du temps pour chacun.<\/em> \u00bb<\/p>\n\n\n\n<p>La question de la communication, ou plut\u00f4t du manque de communication, en particulier avec les jeunes joueurs, semble constituer un des points d&rsquo;achoppement. Le technicien mon\u00e9gasque a paru touch\u00e9 par cette critique : \u00ab&nbsp;<em>Pour moi, \u00e7a n&rsquo;a aucune importance si un joueur est jeune, exp\u00e9riment\u00e9 ou entre les deux. Par la force des choses, vous parlez plus avec vos leaders, mais il faut voir le nombre de fois o\u00f9 je parle \u00e0 Eliesse (Ben Seghir) ou Maghnes (Akliouche). Et il y a des joueurs qui ne veulent pas trop parler. D&rsquo;autres qui veulent plus savoir les choses, avec qui cela prend plus de temps. Apr\u00e8s, oui, on peut toujours faire mieux dans son travail. Mais j&rsquo;ai l&rsquo;impression qu&rsquo;en mati\u00e8re de communication, j&rsquo;ai fait du mieux possible. (&#8230;) Dire que je ne suis pas tr\u00e8s bon dans la communication, c&rsquo;est me donner un coup derri\u00e8re la nuque, parce que je pense que l&rsquo;une de mes forces, c&rsquo;est justement de communiquer avec les joueurs.<\/em>&nbsp;\u00bb<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\"><p>\u00ab <em>Se plaindre ne sert \u00e0 rien<\/em> \u00bb<\/p><\/blockquote>\n\n\n\n<p>L&rsquo;ancien entra\u00eeneur de Salzbourg et du Borussia M\u00f6nchengladbach ne semble pas avoir boulevers\u00e9 sa m\u00e9thode et sa fa\u00e7on de g\u00e9rer son groupe : \u00ab&nbsp;<em>Peut-\u00eatre que cette ann\u00e9e, je suis un peu plus doux. Franchement, je ne sais pas\u2026 C&rsquo;est difficile de dire si j&rsquo;ai chang\u00e9 mon management. Il faudrait le demander aux autres personnes au club. J&rsquo;ai l&rsquo;impression que je fais toujours la m\u00eame chose.<\/em>&nbsp;\u00bb Cette saison, il n&rsquo;a en tout cas pas h\u00e9sit\u00e9 \u00e0 critiquer Caio Henrique pour ses mauvaises performances : \u00ab&nbsp;<em>Tous les joueurs ne sont pas les m\u00eames, mais tous les joueurs sont des \u00eatres humains. Caio Henrique a un peu de mal. Apr\u00e8s sa blessure, \u00e7a a pris trop de temps. Mais sur les 7 derniers matches, il a d\u00e9livr\u00e9 4 passes d\u00e9cisives. J&rsquo;ai le sentiment qu&rsquo;il est de retour \u00e0 son meilleur niveau.<\/em> \u00bb<\/p>\n\n\n\n<p>Et d&rsquo;expliquer ce qu&rsquo;il attendait de ses joueurs, \u00e0 savoir plus de travail et moins de dol\u00e9ances : \u00ab\u00a0<em>De quoi parle-t-on, l\u00e0\u00a0? De performance. Si un joueur joue moins, c&rsquo;est qu&rsquo;il joue moins bien. Je suis l\u00e0 pour valoriser tous les autres joueurs s&rsquo;ils s&rsquo;entra\u00eenent bien et font de bons matches. En tant qu&rsquo;entra\u00eeneur, j&rsquo;ai une vue d&rsquo;ensemble, alors que les joueurs n&rsquo;ont parfois qu&rsquo;une photo r\u00e9duite de la situation. J&rsquo;ai \u00e9t\u00e9 un professionnel pendant vingt ans. J&rsquo;ai aussi \u00e9t\u00e9 sur le banc parce que mon coach n&rsquo;\u00e9tait pas satisfait de moi. Mais j&rsquo;ai travaill\u00e9 dur, pour revenir, et c&rsquo;est ce que j&rsquo;attends de mes joueurs. Se plaindre ne sert \u00e0 rien. Sois performant, fais tout ton possible sur le terrain, \u00e0 l&rsquo;entra\u00eenement, en match, et on verra.<\/em>\u00a0\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le long entretien qu&rsquo;il a accord\u00e9 \u00e0 L&rsquo;\u00c9quipe, Adi H\u00fctter a d\u00e9fendu son bilan \u00e0 la t\u00eate de l&rsquo;AS Monaco, mais il a aussi accept\u00e9 d&rsquo;\u00e9voquer son management. Sans aller jusqu&rsquo;\u00e0 dire qu&rsquo;il a pu \u00eatre contest\u00e9 en interne, l&rsquo;Autrichien a pu faire certains choix qui ont fait l&rsquo;objet d&rsquo;interrogations et d&rsquo;incompr\u00e9hensions dans le [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[576,86],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>H\u00fctter : \u00ab\u00a0Dire que je ne suis pas tr\u00e8s bon en communication, c&#039;est me donner un coup derri\u00e8re la nuque\u00a0\u00bb - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2025\/03\/25\/hutter-dire-que-je-ne-suis-pas-tres-bon-en-communication-cest-me-donner-un-coup-derriere-la-nuque\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"H\u00fctter : \u00ab\u00a0Dire que je ne suis pas tr\u00e8s bon en communication, c&#039;est me donner un coup derri\u00e8re la nuque\u00a0\u00bb - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Dans le long entretien qu&rsquo;il a accord\u00e9 \u00e0 L&rsquo;\u00c9quipe, Adi H\u00fctter a d\u00e9fendu son bilan \u00e0 la t\u00eate de l&rsquo;AS Monaco, mais il a aussi accept\u00e9 d&rsquo;\u00e9voquer son management. Sans aller jusqu&rsquo;\u00e0 dire qu&rsquo;il a pu \u00eatre contest\u00e9 en interne, l&rsquo;Autrichien a pu faire certains choix qui ont fait l&rsquo;objet d&rsquo;interrogations et d&rsquo;incompr\u00e9hensions dans le [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2025\/03\/25\/hutter-dire-que-je-ne-suis-pas-tres-bon-en-communication-cest-me-donner-un-coup-derriere-la-nuque\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-25T07:53:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-25T03:06:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/12\/HutterBS.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/12\/HutterBS.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/03\/25\/hutter-dire-que-je-ne-suis-pas-tres-bon-en-communication-cest-me-donner-un-coup-derriere-la-nuque\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/03\/25\/hutter-dire-que-je-ne-suis-pas-tres-bon-en-communication-cest-me-donner-un-coup-derriere-la-nuque\/\",\"name\":\"H\u00fctter : \u00ab\u00a0Dire que je ne suis pas tr\u00e8s bon en communication, c'est me donner un coup derri\u00e8re la nuque\u00a0\u00bb - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2025-03-25T07:53:00+00:00\",\"dateModified\":\"2025-03-25T03:06:27+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/03\/25\/hutter-dire-que-je-ne-suis-pas-tres-bon-en-communication-cest-me-donner-un-coup-derriere-la-nuque\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2025\/03\/25\/hutter-dire-que-je-ne-suis-pas-tres-bon-en-communication-cest-me-donner-un-coup-derriere-la-nuque\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/03\/25\/hutter-dire-que-je-ne-suis-pas-tres-bon-en-communication-cest-me-donner-un-coup-derriere-la-nuque\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"H\u00fctter : \u00ab\u00a0Dire que je ne suis pas tr\u00e8s bon en communication, c&rsquo;est me donner un coup derri\u00e8re la nuque\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"H\u00fctter : \u00ab\u00a0Dire que je ne suis pas tr\u00e8s bon en communication, c'est me donner un coup derri\u00e8re la nuque\u00a0\u00bb - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2025\/03\/25\/hutter-dire-que-je-ne-suis-pas-tres-bon-en-communication-cest-me-donner-un-coup-derriere-la-nuque\/","og_locale":"fr_FR","og_type":"article","og_title":"H\u00fctter : \u00ab\u00a0Dire que je ne suis pas tr\u00e8s bon en communication, c'est me donner un coup derri\u00e8re la nuque\u00a0\u00bb - La Diagonale","og_description":"Dans le long entretien qu&rsquo;il a accord\u00e9 \u00e0 L&rsquo;\u00c9quipe, Adi H\u00fctter a d\u00e9fendu son bilan \u00e0 la t\u00eate de l&rsquo;AS Monaco, mais il a aussi accept\u00e9 d&rsquo;\u00e9voquer son management. Sans aller jusqu&rsquo;\u00e0 dire qu&rsquo;il a pu \u00eatre contest\u00e9 en interne, l&rsquo;Autrichien a pu faire certains choix qui ont fait l&rsquo;objet d&rsquo;interrogations et d&rsquo;incompr\u00e9hensions dans le [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2025\/03\/25\/hutter-dire-que-je-ne-suis-pas-tres-bon-en-communication-cest-me-donner-un-coup-derriere-la-nuque\/","og_site_name":"La Diagonale","article_published_time":"2025-03-25T07:53:00+00:00","article_modified_time":"2025-03-25T03:06:27+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/12\/HutterBS.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2024\/12\/HutterBS.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2025\/03\/25\/hutter-dire-que-je-ne-suis-pas-tres-bon-en-communication-cest-me-donner-un-coup-derriere-la-nuque\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2025\/03\/25\/hutter-dire-que-je-ne-suis-pas-tres-bon-en-communication-cest-me-donner-un-coup-derriere-la-nuque\/","name":"H\u00fctter : \u00ab\u00a0Dire que je ne suis pas tr\u00e8s bon en communication, c'est me donner un coup derri\u00e8re la nuque\u00a0\u00bb - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2025-03-25T07:53:00+00:00","dateModified":"2025-03-25T03:06:27+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2025\/03\/25\/hutter-dire-que-je-ne-suis-pas-tres-bon-en-communication-cest-me-donner-un-coup-derriere-la-nuque\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2025\/03\/25\/hutter-dire-que-je-ne-suis-pas-tres-bon-en-communication-cest-me-donner-un-coup-derriere-la-nuque\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2025\/03\/25\/hutter-dire-que-je-ne-suis-pas-tres-bon-en-communication-cest-me-donner-un-coup-derriere-la-nuque\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"H\u00fctter : \u00ab\u00a0Dire que je ne suis pas tr\u00e8s bon en communication, c&rsquo;est me donner un coup derri\u00e8re la nuque\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/30541"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=30541"}],"version-history":[{"count":5,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/30541\/revisions"}],"predecessor-version":[{"id":30550,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/30541\/revisions\/30550"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=30541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=30541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=30541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}