{"id":30751,"date":"2025-04-01T20:32:16","date_gmt":"2025-04-01T18:32:16","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=30751"},"modified":"2026-04-10T02:56:51","modified_gmt":"2026-04-10T00:56:51","slug":"deux-monegasques-en-lice-pour-le-prix-marc-vivien-foe","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2025\/04\/01\/deux-monegasques-en-lice-pour-le-prix-marc-vivien-foe\/","title":{"rendered":"Deux Mon\u00e9gasques en lice pour le prix Marc-Vivien Fo\u00e9"},"content":{"rendered":"\n\n\n<p>L&rsquo;AS Monaco n&rsquo;aura pas une, mais deux chances de remporter le Prix Marc-Vivien Fo\u00e9, organis\u00e9 par <em>RFI<\/em> et <em>France 24,<\/em> et qui r\u00e9compense le meilleur footballeur africain du championnat de France. Eliesse Ben Seghir et Lamine Camara font partie de la liste des 12 joueurs nomm\u00e9s, et le nom du vainqueur sera annonc\u00e9 le 12 mai.<\/p>\n\n\n\n<p>Pour Eliesse Ben Seghir, il s&rsquo;agit de sa premi\u00e8re nomination, lui qui a choisi de repr\u00e9senter le Maroc en mars 2024. C&rsquo;est en revanche la seconde pour Lamine Camara, qui avait d\u00e9j\u00e0 \u00e9t\u00e9 retenu lorsqu&rsquo;il jouait \u00e0 Metz la saison pass\u00e9e. Le S\u00e9n\u00e9galais ne l&rsquo;avait pas emport\u00e9 puisque c&rsquo;\u00e9tait le Marseillais et ancien Mon\u00e9gasque, Pierre-Emerick Aubameyang, qui avait remport\u00e9 ce troph\u00e9e. S\u00e9lectionn\u00e9 en 2024, Wilfried Singo n&rsquo;est cette fois pas dans la liste.<\/p>\n\n\n\n<p class=\"has-text-align-center has-cyan-bluish-gray-background-color has-background\"><strong>La liste des nomm\u00e9s<\/strong><br><br><strong>Eliesse Ben Seghir (Maroc\/Monaco)<\/strong><br><strong>Lamine Camara (S\u00e9n\u00e9gal\/Monaco)<\/strong><br>Achraf Hakimi (Maroc\/Paris SG)<br>Himad Abdelli (Alg\u00e9rie\/Angers)<br>Yahia Fofana (C\u00f4te d&rsquo;Ivoire\/Angers)<br>Amine Gouiri (Alg\u00e9rie\/Rennes-Marseille)<br>Habib Diarra (S\u00e9n\u00e9gal\/Strasbourg)<br>Evann Guessand (C\u00f4te d&rsquo;Ivoire\/Nice)<br>Moussa Niakhat\u00e9 (S\u00e9n\u00e9gal\/Lyon)<br>Moses Simon (Nigeria\/Nantes)<br>Abdoulaye Tour\u00e9 (Guin\u00e9e\/Le Havre)<br>Hamed Junior Traor\u00e9 (C\u00f4te d&rsquo;Ivoire\/Auxerre)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;AS Monaco n&rsquo;aura pas une, mais deux chances de remporter le Prix Marc-Vivien Fo\u00e9, organis\u00e9 par RFI et France 24, et qui r\u00e9compense le meilleur footballeur africain du championnat de France. Eliesse Ben Seghir et Lamine Camara font partie de la liste des 12 joueurs nomm\u00e9s, et le nom du vainqueur sera annonc\u00e9 le 12 [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[86,286,894,94,540],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Deux Mon\u00e9gasques en lice pour le prix Marc-Vivien Fo\u00e9 - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2025\/04\/01\/deux-monegasques-en-lice-pour-le-prix-marc-vivien-foe\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deux Mon\u00e9gasques en lice pour le prix Marc-Vivien Fo\u00e9 - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;AS Monaco n&rsquo;aura pas une, mais deux chances de remporter le Prix Marc-Vivien Fo\u00e9, organis\u00e9 par RFI et France 24, et qui r\u00e9compense le meilleur footballeur africain du championnat de France. Eliesse Ben Seghir et Lamine Camara font partie de la liste des 12 joueurs nomm\u00e9s, et le nom du vainqueur sera annonc\u00e9 le 12 [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2025\/04\/01\/deux-monegasques-en-lice-pour-le-prix-marc-vivien-foe\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-01T18:32:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-10T00:56:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2025\/02\/Camara-ldc.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2025\/02\/Camara-ldc.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/04\/01\/deux-monegasques-en-lice-pour-le-prix-marc-vivien-foe\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/04\/01\/deux-monegasques-en-lice-pour-le-prix-marc-vivien-foe\/\",\"name\":\"Deux Mon\u00e9gasques en lice pour le prix Marc-Vivien Fo\u00e9 - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2025-04-01T18:32:16+00:00\",\"dateModified\":\"2026-04-10T00:56:51+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/04\/01\/deux-monegasques-en-lice-pour-le-prix-marc-vivien-foe\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2025\/04\/01\/deux-monegasques-en-lice-pour-le-prix-marc-vivien-foe\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/04\/01\/deux-monegasques-en-lice-pour-le-prix-marc-vivien-foe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deux Mon\u00e9gasques en lice pour le prix Marc-Vivien Fo\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deux Mon\u00e9gasques en lice pour le prix Marc-Vivien Fo\u00e9 - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2025\/04\/01\/deux-monegasques-en-lice-pour-le-prix-marc-vivien-foe\/","og_locale":"fr_FR","og_type":"article","og_title":"Deux Mon\u00e9gasques en lice pour le prix Marc-Vivien Fo\u00e9 - La Diagonale","og_description":"L&rsquo;AS Monaco n&rsquo;aura pas une, mais deux chances de remporter le Prix Marc-Vivien Fo\u00e9, organis\u00e9 par RFI et France 24, et qui r\u00e9compense le meilleur footballeur africain du championnat de France. Eliesse Ben Seghir et Lamine Camara font partie de la liste des 12 joueurs nomm\u00e9s, et le nom du vainqueur sera annonc\u00e9 le 12 [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2025\/04\/01\/deux-monegasques-en-lice-pour-le-prix-marc-vivien-foe\/","og_site_name":"La Diagonale","article_published_time":"2025-04-01T18:32:16+00:00","article_modified_time":"2026-04-10T00:56:51+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2025\/02\/Camara-ldc.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2025\/02\/Camara-ldc.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2025\/04\/01\/deux-monegasques-en-lice-pour-le-prix-marc-vivien-foe\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2025\/04\/01\/deux-monegasques-en-lice-pour-le-prix-marc-vivien-foe\/","name":"Deux Mon\u00e9gasques en lice pour le prix Marc-Vivien Fo\u00e9 - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2025-04-01T18:32:16+00:00","dateModified":"2026-04-10T00:56:51+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2025\/04\/01\/deux-monegasques-en-lice-pour-le-prix-marc-vivien-foe\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2025\/04\/01\/deux-monegasques-en-lice-pour-le-prix-marc-vivien-foe\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2025\/04\/01\/deux-monegasques-en-lice-pour-le-prix-marc-vivien-foe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Deux Mon\u00e9gasques en lice pour le prix Marc-Vivien Fo\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/30751"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=30751"}],"version-history":[{"count":3,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/30751\/revisions"}],"predecessor-version":[{"id":37728,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/30751\/revisions\/37728"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=30751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=30751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=30751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}