{"id":35009,"date":"2025-11-02T22:24:53","date_gmt":"2025-11-02T21:24:53","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=35009"},"modified":"2025-11-02T22:24:53","modified_gmt":"2025-11-02T21:24:53","slug":"les-u17-battus-au-cavigal","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2025\/11\/02\/les-u17-battus-au-cavigal\/","title":{"rendered":"Les U17 battus au Cavigal"},"content":{"rendered":"\n<p>Mauvaise semaine pour la reprise de l\u2019Academy. Si <a href=\"https:\/\/www.ladiagonale.net\/index.php\/2025\/11\/02\/les-u19-battus-par-toulouse\/\" target=\"_blank\" rel=\"noreferrer noopener\">les U19 ont \u00e9t\u00e9 battus par Toulouse<\/a> samedi, les U17 de l\u2019AS Monaco ont eux aussi essuy\u00e9 un revers lors de la 10<sup>e<\/sup> journ\u00e9e de championnat. Contre le Cavigal de Nice, les joueurs de Manu Dos Santos se sont inclin\u00e9s d\u2019une courte t\u00eate (0-1). Les Rouge et Blanc ont \u00e9t\u00e9 surpris au retour des vestiaires (46<sup>e<\/sup>) et n\u2019ont pas r\u00e9ussi \u00e0 revenir dans la partie.<\/p>\n\n\n\n<p>L\u2019ASM occupe toujours le 7<sup>e<\/sup> rang dans sa poule mais voit son matelas sur la zone rouge se r\u00e9duire, tandis que l\u2019\u00e9cart avec les deux premi\u00e8res places, synonymes de phase finale, se creuse. Dimanche prochain, les U17 recevront l\u2019\u00e9quipe qui les suit \u00e0 une longueur derri\u00e8re au classement, Lyon-La Duch\u00e8re.<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Mauvaise semaine pour la reprise de l\u2019Academy. Si les U19 ont \u00e9t\u00e9 battus par Toulouse samedi, les U17 de l\u2019AS Monaco ont eux aussi essuy\u00e9 un revers lors de la 10e journ\u00e9e de championnat. Contre le Cavigal de Nice, les joueurs de Manu Dos Santos se sont inclin\u00e9s d\u2019une courte t\u00eate (0-1). Les Rouge et [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1110,6],"tags":[76,86,130],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les U17 battus au Cavigal - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2025\/11\/02\/les-u17-battus-au-cavigal\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les U17 battus au Cavigal - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Mauvaise semaine pour la reprise de l\u2019Academy. Si les U19 ont \u00e9t\u00e9 battus par Toulouse samedi, les U17 de l\u2019AS Monaco ont eux aussi essuy\u00e9 un revers lors de la 10e journ\u00e9e de championnat. Contre le Cavigal de Nice, les joueurs de Manu Dos Santos se sont inclin\u00e9s d\u2019une courte t\u00eate (0-1). Les Rouge et [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2025\/11\/02\/les-u17-battus-au-cavigal\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-02T21:24:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2025\/09\/Petit-U17.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2025\/09\/Petit-U17.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/11\/02\/les-u17-battus-au-cavigal\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/11\/02\/les-u17-battus-au-cavigal\/\",\"name\":\"Les U17 battus au Cavigal - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2025-11-02T21:24:53+00:00\",\"dateModified\":\"2025-11-02T21:24:53+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/11\/02\/les-u17-battus-au-cavigal\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2025\/11\/02\/les-u17-battus-au-cavigal\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/11\/02\/les-u17-battus-au-cavigal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les U17 battus au Cavigal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les U17 battus au Cavigal - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2025\/11\/02\/les-u17-battus-au-cavigal\/","og_locale":"fr_FR","og_type":"article","og_title":"Les U17 battus au Cavigal - La Diagonale","og_description":"Mauvaise semaine pour la reprise de l\u2019Academy. Si les U19 ont \u00e9t\u00e9 battus par Toulouse samedi, les U17 de l\u2019AS Monaco ont eux aussi essuy\u00e9 un revers lors de la 10e journ\u00e9e de championnat. Contre le Cavigal de Nice, les joueurs de Manu Dos Santos se sont inclin\u00e9s d\u2019une courte t\u00eate (0-1). Les Rouge et [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2025\/11\/02\/les-u17-battus-au-cavigal\/","og_site_name":"La Diagonale","article_published_time":"2025-11-02T21:24:53+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2025\/09\/Petit-U17.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2025\/09\/Petit-U17.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2025\/11\/02\/les-u17-battus-au-cavigal\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2025\/11\/02\/les-u17-battus-au-cavigal\/","name":"Les U17 battus au Cavigal - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2025-11-02T21:24:53+00:00","dateModified":"2025-11-02T21:24:53+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2025\/11\/02\/les-u17-battus-au-cavigal\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2025\/11\/02\/les-u17-battus-au-cavigal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2025\/11\/02\/les-u17-battus-au-cavigal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Les U17 battus au Cavigal"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/35009"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=35009"}],"version-history":[{"count":1,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/35009\/revisions"}],"predecessor-version":[{"id":35010,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/35009\/revisions\/35010"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=35009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=35009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=35009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}