{"id":35827,"date":"2025-12-18T14:48:32","date_gmt":"2025-12-18T13:48:32","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=35827"},"modified":"2025-12-18T14:48:33","modified_gmt":"2025-12-18T13:48:33","slug":"monaco-oppose-a-saint-etienne-en-gambardella","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2025\/12\/18\/monaco-oppose-a-saint-etienne-en-gambardella\/","title":{"rendered":"Monaco oppos\u00e9 \u00e0 Saint-\u00c9tienne en Gambardella"},"content":{"rendered":"\n<p>Les U18 de l\u2019AS Monaco ont d\u00e9couvert ce jeudi midi leur premier adversaire en Coupe Gambardella. Exempt\u00e9s du 1<sup>er<\/sup> tour f\u00e9d\u00e9ral qui s\u2019est tenu le week-end dernier, les Mon\u00e9gasques feront leur entr\u00e9e dans la comp\u00e9tition directement au stade des 32<sup>es<\/sup> de finale, qui se d\u00e9rouleront le week-end des 10 et 11 janvier 2026. Et pour d\u00e9buter, ils n\u2019ont pas \u00e9t\u00e9 g\u00e2t\u00e9s puisqu\u2019ils se rendront \u00e0 Saint-\u00c9tienne.<\/p>\n\n\n\n<p>Un adversaire que les hommes de Fr\u00e9d\u00e9ric Barilaro et Manu Dos Santos connaissent bien, puisque les U19 comme les U17 les rencontrent r\u00e9guli\u00e8rement en Championnat, y compris cette saison. Dans la poule D du championnat U19, les Verts occupent le 7<sup>e<\/sup> rang, loin des Mon\u00e9gasques, leaders. En U17, ils sont plus loin, 9<sup>es<\/sup>, \u00e0 sept longueurs des Rouge et Blanc mais dans une cat\u00e9gorie comme dans l\u2019autre, l\u2019ASM n\u2019a pas r\u00e9ussi \u00e0 les battre <em>(2-2 en U19, 0-1 en U17)<\/em>.<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Les U18 de l\u2019AS Monaco ont d\u00e9couvert ce jeudi midi leur premier adversaire en Coupe Gambardella. Exempt\u00e9s du 1er tour f\u00e9d\u00e9ral qui s\u2019est tenu le week-end dernier, les Mon\u00e9gasques feront leur entr\u00e9e dans la comp\u00e9tition directement au stade des 32es de finale, qui se d\u00e9rouleront le week-end des 10 et 11 janvier 2026. Et pour [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1110,4,6],"tags":[76,86,321,952],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Monaco oppos\u00e9 \u00e0 Saint-\u00c9tienne en Gambardella - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2025\/12\/18\/monaco-oppose-a-saint-etienne-en-gambardella\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Monaco oppos\u00e9 \u00e0 Saint-\u00c9tienne en Gambardella - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Les U18 de l\u2019AS Monaco ont d\u00e9couvert ce jeudi midi leur premier adversaire en Coupe Gambardella. Exempt\u00e9s du 1er tour f\u00e9d\u00e9ral qui s\u2019est tenu le week-end dernier, les Mon\u00e9gasques feront leur entr\u00e9e dans la comp\u00e9tition directement au stade des 32es de finale, qui se d\u00e9rouleront le week-end des 10 et 11 janvier 2026. Et pour [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2025\/12\/18\/monaco-oppose-a-saint-etienne-en-gambardella\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-18T13:48:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-18T13:48:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2025\/12\/Ajroud-sainte\u0301.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2025\/12\/Ajroud-sainte\u0301.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/12\/18\/monaco-oppose-a-saint-etienne-en-gambardella\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/12\/18\/monaco-oppose-a-saint-etienne-en-gambardella\/\",\"name\":\"Monaco oppos\u00e9 \u00e0 Saint-\u00c9tienne en Gambardella - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2025-12-18T13:48:32+00:00\",\"dateModified\":\"2025-12-18T13:48:33+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/12\/18\/monaco-oppose-a-saint-etienne-en-gambardella\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2025\/12\/18\/monaco-oppose-a-saint-etienne-en-gambardella\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2025\/12\/18\/monaco-oppose-a-saint-etienne-en-gambardella\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Monaco oppos\u00e9 \u00e0 Saint-\u00c9tienne en Gambardella\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Monaco oppos\u00e9 \u00e0 Saint-\u00c9tienne en Gambardella - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2025\/12\/18\/monaco-oppose-a-saint-etienne-en-gambardella\/","og_locale":"fr_FR","og_type":"article","og_title":"Monaco oppos\u00e9 \u00e0 Saint-\u00c9tienne en Gambardella - La Diagonale","og_description":"Les U18 de l\u2019AS Monaco ont d\u00e9couvert ce jeudi midi leur premier adversaire en Coupe Gambardella. Exempt\u00e9s du 1er tour f\u00e9d\u00e9ral qui s\u2019est tenu le week-end dernier, les Mon\u00e9gasques feront leur entr\u00e9e dans la comp\u00e9tition directement au stade des 32es de finale, qui se d\u00e9rouleront le week-end des 10 et 11 janvier 2026. Et pour [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2025\/12\/18\/monaco-oppose-a-saint-etienne-en-gambardella\/","og_site_name":"La Diagonale","article_published_time":"2025-12-18T13:48:32+00:00","article_modified_time":"2025-12-18T13:48:33+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2025\/12\/Ajroud-sainte\u0301.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2025\/12\/Ajroud-sainte\u0301.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2025\/12\/18\/monaco-oppose-a-saint-etienne-en-gambardella\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2025\/12\/18\/monaco-oppose-a-saint-etienne-en-gambardella\/","name":"Monaco oppos\u00e9 \u00e0 Saint-\u00c9tienne en Gambardella - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2025-12-18T13:48:32+00:00","dateModified":"2025-12-18T13:48:33+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2025\/12\/18\/monaco-oppose-a-saint-etienne-en-gambardella\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2025\/12\/18\/monaco-oppose-a-saint-etienne-en-gambardella\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2025\/12\/18\/monaco-oppose-a-saint-etienne-en-gambardella\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Monaco oppos\u00e9 \u00e0 Saint-\u00c9tienne en Gambardella"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/35827"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=35827"}],"version-history":[{"count":1,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/35827\/revisions"}],"predecessor-version":[{"id":35829,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/35827\/revisions\/35829"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=35827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=35827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=35827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}