{"id":36826,"date":"2026-02-07T22:10:04","date_gmt":"2026-02-07T21:10:04","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=36826"},"modified":"2026-02-07T22:10:05","modified_gmt":"2026-02-07T21:10:05","slug":"le-groupe-monegasque-faes-de-retour","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2026\/02\/07\/le-groupe-monegasque-faes-de-retour\/","title":{"rendered":"Le groupe mon\u00e9gasque : Faes de retour"},"content":{"rendered":"\n\n\n<p>C&rsquo;est une nouvelle qui va sans doute faire plaisir \u00e0 S\u00e9bastien Pocognoli : Wout Faes a \u00e9t\u00e9 jug\u00e9 op\u00e9rationnel pour le derby contre Nice, dimanche, \u00e0 l&rsquo;issue de la s\u00e9ance d&rsquo;entra\u00eenement du jour et peut donc r\u00e9int\u00e9grer le groupe de l&rsquo;AS Monaco. Le d\u00e9fenseur central belge va pouvoir remplumer un secteur d\u00e9fensif exsangue depuis plusieurs semaines.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" width=\"680\" height=\"680\" src=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2026\/02\/HAkojXlXIAAZ9s5.png\" alt=\"\" class=\"wp-image-36827\" srcset=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2026\/02\/HAkojXlXIAAZ9s5.png 680w, https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2026\/02\/HAkojXlXIAAZ9s5-300x300.png 300w, https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2026\/02\/HAkojXlXIAAZ9s5-150x150.png 150w, https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2026\/02\/HAkojXlXIAAZ9s5-128x128.png 128w, https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2026\/02\/HAkojXlXIAAZ9s5-32x32.png 32w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><\/figure>\n\n\n\n<p><em>Absents : <\/em>Fati, Ouattara, Hradecky, Dier, Salisu, Pogba, Cabral, Minamino (bless\u00e9s), Mawissa (reprise), Tour\u00e9 (choix).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>C&rsquo;est une nouvelle qui va sans doute faire plaisir \u00e0 S\u00e9bastien Pocognoli : Wout Faes a \u00e9t\u00e9 jug\u00e9 op\u00e9rationnel pour le derby contre Nice, dimanche, \u00e0 l&rsquo;issue de la s\u00e9ance d&rsquo;entra\u00eenement du jour et peut donc r\u00e9int\u00e9grer le groupe de l&rsquo;AS Monaco. Le d\u00e9fenseur central belge va pouvoir remplumer un secteur d\u00e9fensif exsangue depuis plusieurs [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,6,1000],"tags":[86,225,94,774],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le groupe mon\u00e9gasque : Faes de retour - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2026\/02\/07\/le-groupe-monegasque-faes-de-retour\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le groupe mon\u00e9gasque : Faes de retour - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"C&rsquo;est une nouvelle qui va sans doute faire plaisir \u00e0 S\u00e9bastien Pocognoli : Wout Faes a \u00e9t\u00e9 jug\u00e9 op\u00e9rationnel pour le derby contre Nice, dimanche, \u00e0 l&rsquo;issue de la s\u00e9ance d&rsquo;entra\u00eenement du jour et peut donc r\u00e9int\u00e9grer le groupe de l&rsquo;AS Monaco. Le d\u00e9fenseur central belge va pouvoir remplumer un secteur d\u00e9fensif exsangue depuis plusieurs [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2026\/02\/07\/le-groupe-monegasque-faes-de-retour\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-07T21:10:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-07T21:10:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2026\/02\/Faes-lorient.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2026\/02\/Faes-lorient.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2026\/02\/07\/le-groupe-monegasque-faes-de-retour\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2026\/02\/07\/le-groupe-monegasque-faes-de-retour\/\",\"name\":\"Le groupe mon\u00e9gasque : Faes de retour - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2026-02-07T21:10:04+00:00\",\"dateModified\":\"2026-02-07T21:10:05+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2026\/02\/07\/le-groupe-monegasque-faes-de-retour\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2026\/02\/07\/le-groupe-monegasque-faes-de-retour\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2026\/02\/07\/le-groupe-monegasque-faes-de-retour\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le groupe mon\u00e9gasque : Faes de retour\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le groupe mon\u00e9gasque : Faes de retour - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2026\/02\/07\/le-groupe-monegasque-faes-de-retour\/","og_locale":"fr_FR","og_type":"article","og_title":"Le groupe mon\u00e9gasque : Faes de retour - La Diagonale","og_description":"C&rsquo;est une nouvelle qui va sans doute faire plaisir \u00e0 S\u00e9bastien Pocognoli : Wout Faes a \u00e9t\u00e9 jug\u00e9 op\u00e9rationnel pour le derby contre Nice, dimanche, \u00e0 l&rsquo;issue de la s\u00e9ance d&rsquo;entra\u00eenement du jour et peut donc r\u00e9int\u00e9grer le groupe de l&rsquo;AS Monaco. Le d\u00e9fenseur central belge va pouvoir remplumer un secteur d\u00e9fensif exsangue depuis plusieurs [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2026\/02\/07\/le-groupe-monegasque-faes-de-retour\/","og_site_name":"La Diagonale","article_published_time":"2026-02-07T21:10:04+00:00","article_modified_time":"2026-02-07T21:10:05+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2026\/02\/Faes-lorient.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2026\/02\/Faes-lorient.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2026\/02\/07\/le-groupe-monegasque-faes-de-retour\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2026\/02\/07\/le-groupe-monegasque-faes-de-retour\/","name":"Le groupe mon\u00e9gasque : Faes de retour - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2026-02-07T21:10:04+00:00","dateModified":"2026-02-07T21:10:05+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2026\/02\/07\/le-groupe-monegasque-faes-de-retour\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2026\/02\/07\/le-groupe-monegasque-faes-de-retour\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2026\/02\/07\/le-groupe-monegasque-faes-de-retour\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Le groupe mon\u00e9gasque : Faes de retour"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/36826"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=36826"}],"version-history":[{"count":1,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/36826\/revisions"}],"predecessor-version":[{"id":36828,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/36826\/revisions\/36828"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=36826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=36826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=36826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}