{"id":39577,"date":"2026-07-17T18:28:01","date_gmt":"2026-07-17T16:28:01","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=39577"},"modified":"2026-07-17T18:45:09","modified_gmt":"2026-07-17T16:45:09","slug":"un-dernier-match-amical-contre-coventry","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2026\/07\/17\/un-dernier-match-amical-contre-coventry\/","title":{"rendered":"Un dernier match amical contre Coventry"},"content":{"rendered":"\n<p>Entre le 8 et le 14 ao\u00fbt, l&rsquo;AS Monaco mettra les voiles du c\u00f4t\u00e9 de l&rsquo;Angleterre et prendra ses quartiers au St. George&rsquo;s Park, lieu d&rsquo;entra\u00eenement de la s\u00e9lection anglaise, pour un stage de sept jours. Celui-ci d\u00e9butera par une rencontre de prestige le 9 contre Liverpool, \u00e0 Anfield, et comme on pouvait s&rsquo;y attendre, il se terminera par un dernier match de pr\u00e9paration, le 14 (20h30), contre Coventry City.<\/p>\n\n\n\n<p>Les Rouge et Blanc avaient d\u00e9j\u00e0 affront\u00e9 cet adversaire la saison pass\u00e9e, et gr\u00e2ce \u00e0 un tripl\u00e9 de Maghnes Akliouche, ils avaient lamin\u00e9 (5-0) celui qui allait finir champion de <em>Championship<\/em> et qui \u00e9voluera donc en <em>Premier League<\/em> \u00e0 compter de cette saison. Cela porte \u00e0 six le nombre de rencontres amicales que disputera l&rsquo;ASM durant sa pr\u00e9paration. La premi\u00e8re aura lieu ce samedi, contre l&rsquo;AS Saint-Priest (10h30).<\/p>\n\n\n\n<div class=\"sportspress\"><div class=\"sp-template sp-template-event-list\">\n\t\t\t<h4 class=\"sp-table-caption\">Amicaux 2026-2027<\/h4>\n\t\t<div class=\"sp-table-wrapper\">\n\t\t<table class=\"sp-event-list sp-event-list-format-title sp-data-table\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t sp-paginated-table\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t sp-sortable-table\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t  sp-responsive-table eventlist_6a97aef1ce23d\t\t\t\t\t\t\t\t\t\t\t\t\t sp-scrollable-table \" data-sp-rows=\"75\">\n\t\t\t<thead>\n\t\t\t\t<tr>\n\t\t\t\t\t<th class=\"data-date\">Date<\/th><th class=\"data-event\">Rencontre<\/th><th class=\"data-time\">Heure<\/th><th class=\"data-results\">R\u00e9sultats<\/th><th style=\"display:none;\" class=\"data-venue\">Lieu de la rencontre<\/th><th class=\"data-day\">Jour de match<\/th>\t\t\t\t<\/tr>\n\t\t\t<\/thead>\n\t\t\t<tbody>\n\t\t\t\t<tr class=\"sp-row sp-post alternate sp-row-no-0\" itemscope itemtype=\"http:\/\/schema.org\/SportsEvent\"><td class=\"data-date\" itemprop=\"startDate\" content=\"2026-07-18T10:30+02:00\" data-label=\"Date\"><a href=\"https:\/\/www.ladiagonale.net\/index.php\/event\/monaco-saint-priest\/\" itemprop=\"url\"><date>2026-07-18 10:30:40<\/date>18 juillet 2026<\/a><\/td><td class=\"data-event\" data-label=\"Rencontre\"><a href=\"https:\/\/www.ladiagonale.net\/index.php\/event\/monaco-saint-priest\/\"> Monaco \u2014 Saint-Priest<\/a><\/td><td class=\"data-time ok\" data-label=\"Heure\"><a href=\"https:\/\/www.ladiagonale.net\/index.php\/event\/monaco-saint-priest\/\" itemprop=\"url\"><date>&nbsp;10:30:40<\/date>10h30<\/a><\/td><td class=\"data-results\" data-label=\"R\u00e9sultats\"><a href=\"https:\/\/www.ladiagonale.net\/index.php\/event\/monaco-saint-priest\/\" itemprop=\"url\">5 - 2<\/a><\/td><td style=\"display:none;\" class=\"data-venue\" data-label=\"Lieu de la rencontre\" itemprop=\"location\" itemscope itemtype=\"http:\/\/schema.org\/Place\"><div itemprop=\"address\" itemscope itemtype=\"http:\/\/schema.org\/PostalAddress\">N\/C<\/div><\/td><td class=\"data-day\" data-label=\"Jour de match\">18\/07\/2026<\/td><\/tr><tr class=\"sp-row sp-post sp-row-no-1\" itemscope itemtype=\"http:\/\/schema.org\/SportsEvent\"><td class=\"data-date\" itemprop=\"startDate\" content=\"2026-07-25T20:30+02:00\" data-label=\"Date\"><a href=\"https:\/\/www.ladiagonale.net\/index.php\/event\/sporting-portugal-monaco\/\" itemprop=\"url\"><date>2026-07-25 20:30:53<\/date>25 juillet 2026<\/a><\/td><td class=\"data-event\" data-label=\"Rencontre\"><a href=\"https:\/\/www.ladiagonale.net\/index.php\/event\/sporting-portugal-monaco\/\"> Sporting Portugal \u2014 Monaco<\/a><\/td><td class=\"data-time ok\" data-label=\"Heure\"><a href=\"https:\/\/www.ladiagonale.net\/index.php\/event\/sporting-portugal-monaco\/\" itemprop=\"url\"><date>&nbsp;20:30:53<\/date>20h30<\/a><\/td><td class=\"data-results\" data-label=\"R\u00e9sultats\"><a href=\"https:\/\/www.ladiagonale.net\/index.php\/event\/sporting-portugal-monaco\/\" itemprop=\"url\">2 - 0<\/a><\/td><td style=\"display:none;\" class=\"data-venue\" data-label=\"Lieu de la rencontre\" itemprop=\"location\" itemscope itemtype=\"http:\/\/schema.org\/Place\"><div itemprop=\"address\" itemscope itemtype=\"http:\/\/schema.org\/PostalAddress\">N\/C<\/div><\/td><td class=\"data-day\" data-label=\"Jour de match\">25\/07\/2026<\/td><\/tr><tr class=\"sp-row sp-post alternate sp-row-no-2\" itemscope itemtype=\"http:\/\/schema.org\/SportsEvent\"><td class=\"data-date\" itemprop=\"startDate\" content=\"2026-07-31T17:00+02:00\" data-label=\"Date\"><a href=\"https:\/\/www.ladiagonale.net\/index.php\/event\/monaco-cercle-bruges-3\/\" itemprop=\"url\"><date>2026-07-31 17:00:44<\/date>31 juillet 2026<\/a><\/td><td class=\"data-event\" data-label=\"Rencontre\"><a href=\"https:\/\/www.ladiagonale.net\/index.php\/event\/monaco-cercle-bruges-3\/\"> Monaco \u2014 Cercle Bruges<\/a><\/td><td class=\"data-time ok\" data-label=\"Heure\"><a href=\"https:\/\/www.ladiagonale.net\/index.php\/event\/monaco-cercle-bruges-3\/\" itemprop=\"url\"><date>&nbsp;17:00:44<\/date>17h00<\/a><\/td><td class=\"data-results\" data-label=\"R\u00e9sultats\"><a href=\"https:\/\/www.ladiagonale.net\/index.php\/event\/monaco-cercle-bruges-3\/\" itemprop=\"url\">2 - 2<\/a><\/td><td style=\"display:none;\" class=\"data-venue\" data-label=\"Lieu de la rencontre\" itemprop=\"location\" itemscope itemtype=\"http:\/\/schema.org\/Place\"><div itemprop=\"address\" itemscope itemtype=\"http:\/\/schema.org\/PostalAddress\">N\/C<\/div><\/td><td class=\"data-day\" data-label=\"Jour de match\">31\/07\/2026<\/td><\/tr><tr class=\"sp-row sp-post sp-row-no-3\" itemscope itemtype=\"http:\/\/schema.org\/SportsEvent\"><td class=\"data-date\" itemprop=\"startDate\" content=\"2026-08-06T20:00+02:00\" data-label=\"Date\"><a href=\"https:\/\/www.ladiagonale.net\/index.php\/event\/monaco-getafe\/\" itemprop=\"url\"><date>2026-08-06 20:00:22<\/date>6 ao\u00fbt 2026<\/a><\/td><td class=\"data-event\" data-label=\"Rencontre\"><a href=\"https:\/\/www.ladiagonale.net\/index.php\/event\/monaco-getafe\/\"> Monaco \u2014 Getafe<\/a><\/td><td class=\"data-time ok\" data-label=\"Heure\"><a href=\"https:\/\/www.ladiagonale.net\/index.php\/event\/monaco-getafe\/\" itemprop=\"url\"><date>&nbsp;20:00:22<\/date>20h00<\/a><\/td><td class=\"data-results\" data-label=\"R\u00e9sultats\"><a href=\"https:\/\/www.ladiagonale.net\/index.php\/event\/monaco-getafe\/\" itemprop=\"url\">1 - 0<\/a><\/td><td style=\"display:none;\" class=\"data-venue\" data-label=\"Lieu de la rencontre\" itemprop=\"location\" itemscope itemtype=\"http:\/\/schema.org\/Place\"><div itemprop=\"address\" itemscope itemtype=\"http:\/\/schema.org\/PostalAddress\">N\/C<\/div><\/td><td class=\"data-day\" data-label=\"Jour de match\">06\/08\/2027<\/td><\/tr><tr class=\"sp-row sp-post alternate sp-row-no-4\" itemscope itemtype=\"http:\/\/schema.org\/SportsEvent\"><td class=\"data-date\" itemprop=\"startDate\" content=\"2026-08-09T15:30+02:00\" data-label=\"Date\"><a href=\"https:\/\/www.ladiagonale.net\/index.php\/event\/liverpool-monaco\/\" itemprop=\"url\"><date>2026-08-09 15:30:22<\/date>9 ao\u00fbt 2026<\/a><\/td><td class=\"data-event\" data-label=\"Rencontre\"><a href=\"https:\/\/www.ladiagonale.net\/index.php\/event\/liverpool-monaco\/\"> Liverpool \u2014 Monaco<\/a><\/td><td class=\"data-time ok\" data-label=\"Heure\"><a href=\"https:\/\/www.ladiagonale.net\/index.php\/event\/liverpool-monaco\/\" itemprop=\"url\"><date>&nbsp;15:30:22<\/date>15h30<\/a><\/td><td class=\"data-results\" data-label=\"R\u00e9sultats\"><a href=\"https:\/\/www.ladiagonale.net\/index.php\/event\/liverpool-monaco\/\" itemprop=\"url\">2 - 3<\/a><\/td><td style=\"display:none;\" class=\"data-venue\" data-label=\"Lieu de la rencontre\" itemprop=\"location\" itemscope itemtype=\"http:\/\/schema.org\/Place\"><div itemprop=\"address\" itemscope itemtype=\"http:\/\/schema.org\/PostalAddress\">N\/C<\/div><\/td><td class=\"data-day\" data-label=\"Jour de match\">09\/08\/2026<\/td><\/tr><tr class=\"sp-row sp-post sp-row-no-5\" itemscope itemtype=\"http:\/\/schema.org\/SportsEvent\"><td class=\"data-date\" itemprop=\"startDate\" content=\"2026-08-14T20:30+02:00\" data-label=\"Date\"><a href=\"https:\/\/www.ladiagonale.net\/index.php\/event\/coventry-city-monaco-2\/\" itemprop=\"url\"><date>2026-08-14 20:30:41<\/date>14 ao\u00fbt 2026<\/a><\/td><td class=\"data-event\" data-label=\"Rencontre\"><a href=\"https:\/\/www.ladiagonale.net\/index.php\/event\/coventry-city-monaco-2\/\"> Coventry City \u2014 Monaco<\/a><\/td><td class=\"data-time ok\" data-label=\"Heure\"><a href=\"https:\/\/www.ladiagonale.net\/index.php\/event\/coventry-city-monaco-2\/\" itemprop=\"url\"><date>&nbsp;20:30:41<\/date>20h30<\/a><\/td><td class=\"data-results\" data-label=\"R\u00e9sultats\"><a href=\"https:\/\/www.ladiagonale.net\/index.php\/event\/coventry-city-monaco-2\/\" itemprop=\"url\">2 - 0<\/a><\/td><td style=\"display:none;\" class=\"data-venue\" data-label=\"Lieu de la rencontre\" itemprop=\"location\" itemscope itemtype=\"http:\/\/schema.org\/Place\"><div itemprop=\"address\" itemscope itemtype=\"http:\/\/schema.org\/PostalAddress\">N\/C<\/div><\/td><td class=\"data-day\" data-label=\"Jour de match\">14\/08\/2026<\/td><\/tr>\t\t\t<\/tbody>\n\t\t<\/table>\n\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre le 8 et le 14 ao\u00fbt, l&rsquo;AS Monaco mettra les voiles du c\u00f4t\u00e9 de l&rsquo;Angleterre et prendra ses quartiers au St. George&rsquo;s Park, lieu d&rsquo;entra\u00eenement de la s\u00e9lection anglaise, pour un stage de sept jours. Celui-ci d\u00e9butera par une rencontre de prestige le 9 contre Liverpool, \u00e0 Anfield, et comme on pouvait s&rsquo;y attendre, [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[87,86,592],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un dernier match amical contre Coventry - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2026\/07\/17\/un-dernier-match-amical-contre-coventry\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un dernier match amical contre Coventry - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Entre le 8 et le 14 ao\u00fbt, l&rsquo;AS Monaco mettra les voiles du c\u00f4t\u00e9 de l&rsquo;Angleterre et prendra ses quartiers au St. George&rsquo;s Park, lieu d&rsquo;entra\u00eenement de la s\u00e9lection anglaise, pour un stage de sept jours. Celui-ci d\u00e9butera par une rencontre de prestige le 9 contre Liverpool, \u00e0 Anfield, et comme on pouvait s&rsquo;y attendre, [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2026\/07\/17\/un-dernier-match-amical-contre-coventry\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-17T16:28:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-17T16:45:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2025\/07\/Akliouche-cov.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2025\/07\/Akliouche-cov.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2026\/07\/17\/un-dernier-match-amical-contre-coventry\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2026\/07\/17\/un-dernier-match-amical-contre-coventry\/\",\"name\":\"Un dernier match amical contre Coventry - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2026-07-17T16:28:01+00:00\",\"dateModified\":\"2026-07-17T16:45:09+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2026\/07\/17\/un-dernier-match-amical-contre-coventry\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2026\/07\/17\/un-dernier-match-amical-contre-coventry\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2026\/07\/17\/un-dernier-match-amical-contre-coventry\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un dernier match amical contre Coventry\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un dernier match amical contre Coventry - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2026\/07\/17\/un-dernier-match-amical-contre-coventry\/","og_locale":"fr_FR","og_type":"article","og_title":"Un dernier match amical contre Coventry - La Diagonale","og_description":"Entre le 8 et le 14 ao\u00fbt, l&rsquo;AS Monaco mettra les voiles du c\u00f4t\u00e9 de l&rsquo;Angleterre et prendra ses quartiers au St. George&rsquo;s Park, lieu d&rsquo;entra\u00eenement de la s\u00e9lection anglaise, pour un stage de sept jours. Celui-ci d\u00e9butera par une rencontre de prestige le 9 contre Liverpool, \u00e0 Anfield, et comme on pouvait s&rsquo;y attendre, [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2026\/07\/17\/un-dernier-match-amical-contre-coventry\/","og_site_name":"La Diagonale","article_published_time":"2026-07-17T16:28:01+00:00","article_modified_time":"2026-07-17T16:45:09+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2025\/07\/Akliouche-cov.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2025\/07\/Akliouche-cov.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2026\/07\/17\/un-dernier-match-amical-contre-coventry\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2026\/07\/17\/un-dernier-match-amical-contre-coventry\/","name":"Un dernier match amical contre Coventry - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2026-07-17T16:28:01+00:00","dateModified":"2026-07-17T16:45:09+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2026\/07\/17\/un-dernier-match-amical-contre-coventry\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2026\/07\/17\/un-dernier-match-amical-contre-coventry\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2026\/07\/17\/un-dernier-match-amical-contre-coventry\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Un dernier match amical contre Coventry"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/39577"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=39577"}],"version-history":[{"count":2,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/39577\/revisions"}],"predecessor-version":[{"id":39580,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/39577\/revisions\/39580"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=39577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=39577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=39577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}