{"id":39644,"date":"2026-07-18T13:03:57","date_gmt":"2026-07-18T11:03:57","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=39644"},"modified":"2026-07-20T18:48:14","modified_gmt":"2026-07-20T16:48:14","slug":"monaco-en-maitrise-face-a-saint-priest-pour-son-premier-match-amical-5-2","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2026\/07\/18\/monaco-en-maitrise-face-a-saint-priest-pour-son-premier-match-amical-5-2\/","title":{"rendered":"Monaco en ma\u00eetrise face \u00e0 Saint-Priest pour son premier match amical (5-2)"},"content":{"rendered":"\n<p>L\u2019AS Monaco a largement domin\u00e9 l\u2019AS Saint-Priest (5-2), samedi matin, pour son premier match amical dans cette pr\u00e9paration estivale. Les Rouge et Blanc, sous la houlette de Filipe Luis, ont dispos\u00e9 de leur adverse, pensionnaire de National 1, sans \u00eatre r\u00e9ellement inqui\u00e9t\u00e9s gr\u00e2ce \u00e0 des r\u00e9alisations d\u2019Eric Dier, Aleksandr Golovin, un doubl\u00e9 de Paris Brunner et un but contre son camp. Ils ont cependant conc\u00e9d\u00e9 deux buts cons\u00e9cutifs \u00e0 des erreurs.<\/p>\n\n\n\n<p>C\u2019est en 3-4-3 que les Mon\u00e9gasques ont \u00e9volu\u00e9 dans cette partie, et aussi avec quelques recrues dans le premier onze du technicien br\u00e9silien. Flanqu\u00e9 du n\u00b020, Flavio Nazinho prenait place dans le couloir gauche, avec devant lui Mathys Detourbet, avec le n\u00b07. S&rsquo;ils se sont montr\u00e9s plut\u00f4t en jambes, ce sont sur des coups de pied arr\u00eat\u00e9s que les joueurs de la Principaut\u00e9 ont fait la diff\u00e9rence au cours du premier acte. Dier a marqu\u00e9 en reprenant de pr\u00e8s un ballon qui tra\u00eenait apr\u00e8s un coup franc, tandis que Golovin est all\u00e9 chercher la lucarne sur un coup franc direct.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Deux buts conc\u00e9d\u00e9s sur des erreurs<\/h3>\n\n\n\n<p>Il a fallu attendre la reprise, avec un onze totalement remani\u00e9 et un Paul Pogba capitaine, pour voir le premier but dans le jeu. Brunner, servi dans la profondeur par Edan Diop, a inscrit le troisi\u00e8me but mon\u00e9gasque d\u00e8s le retour des vestiaires. Dans les secondes qui ont suivi, l&rsquo;international U20 allemand a r\u00e9cidiv\u00e9, cette fois sur un exploit personnel. Le dernier but mon\u00e9gasque, cons\u00e9cutif \u00e0 un centre d&rsquo;Oumar Konat\u00e9, parfaitement trouv\u00e9 par Aymen Assab, a \u00e9t\u00e9 inscrit contre son camp. <\/p>\n\n\n\n<p>Entre-temps, les Rhodaniens avaient r\u00e9duit l&rsquo;\u00e9cart une premi\u00e8re fois \u00e0 la suite d&rsquo;une passe mal assur\u00e9e de Sadibou San\u00e9 vers Yann Lienard, qui a tout de m\u00eame rat\u00e9 sa sortie. Le dernier but de la partie a \u00e9t\u00e9 pour le club partenaire de l&rsquo;ASM, avec un ballon cette fois mal repouss\u00e9 par le gardien mon\u00e9gasque.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/www.ladiagonale.net\/index.php\/event\/monaco-saint-priest\/\" target=\"_blank\" rel=\"noreferrer noopener\">Voir la feuille de match<\/a><\/p>\n\n\n\n<p>Outre les mondialistes (Zakaria, Akliouche, Balogun, Camara) et les joueurs en phase de reprise (Minamino, Salisu), plusieurs joueurs manquaient \u00e0 l&rsquo;appel. Parmi eux, Ansu Fati, Vanderson, Philipp K\u00f6hn, Jordan Teze ou encore Stanis Idumbo.<\/p>\n\n\n\n<p>Pour sa prochaine rencontre, la pente s&rsquo;\u00e9l\u00e8vera rapidement puisque Monaco affrontera le Sporting Portugal dans le cadre du troph\u00e9e amical <em>Cinco Violino<\/em>s. La rencontre aura lieu le 25 juillet (20h30).<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>L\u2019AS Monaco a largement domin\u00e9 l\u2019AS Saint-Priest (5-2), samedi matin, pour son premier match amical dans cette pr\u00e9paration estivale. Les Rouge et Blanc, sous la houlette de Filipe Luis, ont dispos\u00e9 de leur adverse, pensionnaire de National 1, sans \u00eatre r\u00e9ellement inqui\u00e9t\u00e9s gr\u00e2ce \u00e0 des r\u00e9alisations d\u2019Eric Dier, Aleksandr Golovin, un doubl\u00e9 de Paris Brunner [&#8230;]\n","protected":false},"author":2,"featured_media":39682,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,6],"tags":[87,86,592],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Monaco en ma\u00eetrise face \u00e0 Saint-Priest pour son premier match amical (5-2) - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2026\/07\/18\/monaco-en-maitrise-face-a-saint-priest-pour-son-premier-match-amical-5-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Monaco en ma\u00eetrise face \u00e0 Saint-Priest pour son premier match amical (5-2) - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"L\u2019AS Monaco a largement domin\u00e9 l\u2019AS Saint-Priest (5-2), samedi matin, pour son premier match amical dans cette pr\u00e9paration estivale. Les Rouge et Blanc, sous la houlette de Filipe Luis, ont dispos\u00e9 de leur adverse, pensionnaire de National 1, sans \u00eatre r\u00e9ellement inqui\u00e9t\u00e9s gr\u00e2ce \u00e0 des r\u00e9alisations d\u2019Eric Dier, Aleksandr Golovin, un doubl\u00e9 de Paris Brunner [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2026\/07\/18\/monaco-en-maitrise-face-a-saint-priest-pour-son-premier-match-amical-5-2\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-18T11:03:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-20T16:48:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2026\/07\/Mawissa-ASSP.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2026\/07\/Mawissa-ASSP.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2026\/07\/18\/monaco-en-maitrise-face-a-saint-priest-pour-son-premier-match-amical-5-2\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2026\/07\/18\/monaco-en-maitrise-face-a-saint-priest-pour-son-premier-match-amical-5-2\/\",\"name\":\"Monaco en ma\u00eetrise face \u00e0 Saint-Priest pour son premier match amical (5-2) - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2026-07-18T11:03:57+00:00\",\"dateModified\":\"2026-07-20T16:48:14+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2026\/07\/18\/monaco-en-maitrise-face-a-saint-priest-pour-son-premier-match-amical-5-2\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2026\/07\/18\/monaco-en-maitrise-face-a-saint-priest-pour-son-premier-match-amical-5-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2026\/07\/18\/monaco-en-maitrise-face-a-saint-priest-pour-son-premier-match-amical-5-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Monaco en ma\u00eetrise face \u00e0 Saint-Priest pour son premier match amical (5-2)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Monaco en ma\u00eetrise face \u00e0 Saint-Priest pour son premier match amical (5-2) - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2026\/07\/18\/monaco-en-maitrise-face-a-saint-priest-pour-son-premier-match-amical-5-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Monaco en ma\u00eetrise face \u00e0 Saint-Priest pour son premier match amical (5-2) - La Diagonale","og_description":"L\u2019AS Monaco a largement domin\u00e9 l\u2019AS Saint-Priest (5-2), samedi matin, pour son premier match amical dans cette pr\u00e9paration estivale. Les Rouge et Blanc, sous la houlette de Filipe Luis, ont dispos\u00e9 de leur adverse, pensionnaire de National 1, sans \u00eatre r\u00e9ellement inqui\u00e9t\u00e9s gr\u00e2ce \u00e0 des r\u00e9alisations d\u2019Eric Dier, Aleksandr Golovin, un doubl\u00e9 de Paris Brunner [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2026\/07\/18\/monaco-en-maitrise-face-a-saint-priest-pour-son-premier-match-amical-5-2\/","og_site_name":"La Diagonale","article_published_time":"2026-07-18T11:03:57+00:00","article_modified_time":"2026-07-20T16:48:14+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2026\/07\/Mawissa-ASSP.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2026\/07\/Mawissa-ASSP.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2026\/07\/18\/monaco-en-maitrise-face-a-saint-priest-pour-son-premier-match-amical-5-2\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2026\/07\/18\/monaco-en-maitrise-face-a-saint-priest-pour-son-premier-match-amical-5-2\/","name":"Monaco en ma\u00eetrise face \u00e0 Saint-Priest pour son premier match amical (5-2) - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2026-07-18T11:03:57+00:00","dateModified":"2026-07-20T16:48:14+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2026\/07\/18\/monaco-en-maitrise-face-a-saint-priest-pour-son-premier-match-amical-5-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2026\/07\/18\/monaco-en-maitrise-face-a-saint-priest-pour-son-premier-match-amical-5-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2026\/07\/18\/monaco-en-maitrise-face-a-saint-priest-pour-son-premier-match-amical-5-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Monaco en ma\u00eetrise face \u00e0 Saint-Priest pour son premier match amical (5-2)"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/39644"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=39644"}],"version-history":[{"count":6,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/39644\/revisions"}],"predecessor-version":[{"id":39659,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/39644\/revisions\/39659"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media\/39682"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=39644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=39644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=39644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}