{"id":4165,"date":"2022-08-20T00:00:00","date_gmt":"2022-08-19T22:00:00","guid":{"rendered":"https:\/\/www.ladiagonale.net\/index.php\/2022\/08\/20\/asm-rcl-les-prestations-individuelles\/"},"modified":"2022-08-20T00:00:00","modified_gmt":"2022-08-19T22:00:00","slug":"asm-rcl-les-prestations-individuelles","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2022\/08\/20\/asm-rcl-les-prestations-individuelles\/","title":{"rendered":"ASM-RCL : Les prestations individuelles"},"content":{"rendered":"<p>N\u00dcBEL : Sa responsabilit\u00e9 n\u2019est pas engag\u00e9e sur les deux premiers buts, mais il n\u2019a pas su \u00eatre d\u00e9cisif, au contraire de son homologue lensois. En revanche, il ne ferme pas bien l\u2019angle sur la frappe de Sa\u00efd et encaisse un but largement \u00e9vitable. Sur p\u00e9nalty, il n\u2019est d\u00e9finitivement pas dans son \u00e9l\u00e9ment.<\/p>\n<p>VANDERSON : Le Br\u00e9silien s\u2019est souvent agac\u00e9 pendant le match des d\u00e9cisions arbitrales. Nerveux, il a \u00e9t\u00e9 pris en d\u00e9faut \u00e0 deux reprises sur les deux premiers buts adverses, surtout sur le deuxi\u00e8me o\u00f9 il semble mal juger la trajectoire du ballon. Offensivement, il ne semble pas se trouver avec Diatta. Une mauvaise prestation sanctionn\u00e9e par une expulsion pour un deuxi\u00e8me avertissement (72e).<\/p>\n<p>DISASI : Difficile de juger la performance de Disasi, qui a \u00e9t\u00e9 tr\u00e8s peu sollicit\u00e9 dans les duels et qui n\u2019est pas impliqu\u00e9 sur les buts de Lens. Mais il a sembl\u00e9 un peu plus sur le fil du rasoir cette fois, notamment physiquement.<\/p>\n<p>BADIASHILE : Le d\u00e9fenseur central \u00e9tait titularis\u00e9 pour la premi\u00e8re fois de la saison et a redonn\u00e9 de l\u2019espoir aux siens avec sa r\u00e9duction de l\u2019\u00e9cart en fin de premi\u00e8re p\u00e9riode. Sur les buts lensois, il n\u2019est pas vraiment fautif, comme Disasi. Il a \u00e9galement remport\u00e9 tous ses duels a\u00e9riens.<\/p>\n<p>C. HENRIQUE : Ses mont\u00e9es n\u2019ont pas fait beaucoup de d\u00e9g\u00e2ts et ses centres ont souvent \u00e9t\u00e9 approximatifs. Il a essay\u00e9 de s\u2019appliquer sur les coups de pieds arr\u00eat\u00e9s et a d\u00e9livr\u00e9 une passe d\u00e9cisive \u00e0 Badiashile. Remplac\u00e9 par JAKOBS, qui a jou\u00e9 en piston lorsque Monaco a jou\u00e9 avec une d\u00e9fense \u00e0 trois mais n\u2019a pas apport\u00e9 grand chose.<\/p>\n<p>MATAZO : Le milieu de terrain belge a fait p\u00e2le figure face au bloc lensois. Tout simplement d\u00e9pass\u00e9 sur les sorties de balle desSang et Or*, il n\u2019a jamais su combler efficacement les trous au milieu de terrain. \u00c0 son entr\u00e9e en jeu, CAMARA s\u2019est tout de suite montr\u00e9 plus disponible pour donner des solutions \u00e0 ses d\u00e9fenseurs. Et il n\u2019a pas h\u00e9sit\u00e9 \u00e0 s\u2019engager dans les duels.<\/p>\n<p>J. LUCAS : On le sait, le Br\u00e9silien n\u2019est pas franchement \u00e0 son aise lorsqu\u2019il s\u2019agit d\u2019aller au duel mais ce n\u2019est pas lui qui a \u00e9t\u00e9 le plus en difficult\u00e9 dans ce domaine. Avec le ballon, il a su parfois trouver de bonnes ouvertures mais cela reste encore insuffisant. SARR a pris sa place pour faire le troisi\u00e8me d\u00e9fenseur central en fin de match<\/p>\n<p>DIATTA : Le S\u00e9n\u00e9galais a un peu plus cherch\u00e9 a provoquer balle au pied et a mis de la vitesse dans son jeu. Mais il s\u2019est souvent montr\u00e9 un peu trop brouillon et un peu trop gourmand. <\/p>\n<p>MINAMINO : Il a su se trouver dans de bonnes positions \u00e0 plusieurs reprises et a obtenu une grosse occasion en premi\u00e8re p\u00e9riode. M\u00eame s\u2019il est vif, il manque encore de justesse sur le plan technique et ne semble pas encore au niveau physiquement. GOLOVIN a essay\u00e9 d\u2019apporter un peu plus par son toucher de balle mais sans r\u00e9ellement peser.<\/p>\n<p>BEN YEDDER : Le capitaine mon\u00e9gasque s\u2019est souvent compliqu\u00e9 la vie. Son manque d\u2019efficacit\u00e9 s\u2019explique aussi par ses trop nombreuses touches de balle et il mettait parfois trop de temps pour armer ses frappes. <\/p>\n<p>EMBOLO : Malheureux sur le p\u00e9nalty qu\u2019il conc\u00e8de alors que le contact semblait l\u00e9ger. Il met Minamino dans une bonne position en premi\u00e8re p\u00e9riode mais le reste du match a \u00e9t\u00e9 plus compliqu\u00e9 pour lui, bien pris dans par la d\u00e9fense lensoise.<\/p>\n<p>Photo :AS Monaco*<\/p>\n","protected":false},"excerpt":{"rendered":"<p>N\u00dcBEL : Sa responsabilit\u00e9 n\u2019est pas engag\u00e9e sur les deux premiers buts, mais il n\u2019a pas su \u00eatre d\u00e9cisif, au contraire de son homologue lensois. En revanche, il ne ferme pas bien l\u2019angle sur la frappe de Sa\u00efd et encaisse un but largement \u00e9vitable. Sur p\u00e9nalty, il n\u2019est d\u00e9finitivement pas dans son \u00e9l\u00e9ment. VANDERSON : [&#8230;]\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASM-RCL : Les prestations individuelles - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/08\/20\/asm-rcl-les-prestations-individuelles\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASM-RCL : Les prestations individuelles - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"N\u00dcBEL : Sa responsabilit\u00e9 n\u2019est pas engag\u00e9e sur les deux premiers buts, mais il n\u2019a pas su \u00eatre d\u00e9cisif, au contraire de son homologue lensois. En revanche, il ne ferme pas bien l\u2019angle sur la frappe de Sa\u00efd et encaisse un but largement \u00e9vitable. Sur p\u00e9nalty, il n\u2019est d\u00e9finitivement pas dans son \u00e9l\u00e9ment. VANDERSON : [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/08\/20\/asm-rcl-les-prestations-individuelles\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-19T22:00:00+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/08\/20\/asm-rcl-les-prestations-individuelles\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/08\/20\/asm-rcl-les-prestations-individuelles\/\",\"name\":\"ASM-RCL : Les prestations individuelles - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2022-08-19T22:00:00+00:00\",\"dateModified\":\"2022-08-19T22:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/03fa041acd51875ece8bf97a37252a4d\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/08\/20\/asm-rcl-les-prestations-individuelles\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2022\/08\/20\/asm-rcl-les-prestations-individuelles\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/08\/20\/asm-rcl-les-prestations-individuelles\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASM-RCL : Les prestations individuelles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/03fa041acd51875ece8bf97a37252a4d\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/894b9daaf19cc759b072b6bb09cac5f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/894b9daaf19cc759b072b6bb09cac5f2?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/v2.ladiagonale.net\"],\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASM-RCL : Les prestations individuelles - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2022\/08\/20\/asm-rcl-les-prestations-individuelles\/","og_locale":"fr_FR","og_type":"article","og_title":"ASM-RCL : Les prestations individuelles - La Diagonale","og_description":"N\u00dcBEL : Sa responsabilit\u00e9 n\u2019est pas engag\u00e9e sur les deux premiers buts, mais il n\u2019a pas su \u00eatre d\u00e9cisif, au contraire de son homologue lensois. En revanche, il ne ferme pas bien l\u2019angle sur la frappe de Sa\u00efd et encaisse un but largement \u00e9vitable. Sur p\u00e9nalty, il n\u2019est d\u00e9finitivement pas dans son \u00e9l\u00e9ment. VANDERSON : [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/08\/20\/asm-rcl-les-prestations-individuelles\/","og_site_name":"La Diagonale","article_published_time":"2022-08-19T22:00:00+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/08\/20\/asm-rcl-les-prestations-individuelles\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/08\/20\/asm-rcl-les-prestations-individuelles\/","name":"ASM-RCL : Les prestations individuelles - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2022-08-19T22:00:00+00:00","dateModified":"2022-08-19T22:00:00+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/03fa041acd51875ece8bf97a37252a4d"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/08\/20\/asm-rcl-les-prestations-individuelles\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2022\/08\/20\/asm-rcl-les-prestations-individuelles\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/08\/20\/asm-rcl-les-prestations-individuelles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"ASM-RCL : Les prestations individuelles"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/03fa041acd51875ece8bf97a37252a4d","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/894b9daaf19cc759b072b6bb09cac5f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/894b9daaf19cc759b072b6bb09cac5f2?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/v2.ladiagonale.net"],"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/4165"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=4165"}],"version-history":[{"count":0,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/4165\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=4165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=4165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=4165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}