{"id":428,"date":"2022-01-01T14:38:00","date_gmt":"2022-01-01T13:38:00","guid":{"rendered":"https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/01\/mitchell-vanderson-un-defenseur-tres-dynamique\/"},"modified":"2022-07-26T14:31:41","modified_gmt":"2022-07-26T12:31:41","slug":"mitchell-vanderson-un-defenseur-tres-dynamique","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/01\/mitchell-vanderson-un-defenseur-tres-dynamique\/","title":{"rendered":"Mitchell : \u00ab Vanderson, un d\u00e9fenseur tr\u00e8s dynamique \u00bb"},"content":{"rendered":"<p>Paul Mitchell, le directeur sportif de l&rsquo;AS Monaco, s&rsquo;est f\u00e9licit\u00e9 de la signature du br\u00e9silien Vanderson pour les cinq prochaines saisons : \u00ab*Nous sommes tr\u00e8s heureux d\u2019accueillir Vanderson \u00e0 l\u2019AS Monaco.*\u00bb Mitchell a \u00e9galement r\u00e9v\u00e9l\u00e9 quelques caract\u00e9ristiques du joueur, qui s&rsquo;apparentent \u00e0 celles du lat\u00e9ral moderne : \u00ab*C\u2019est un d\u00e9fenseur tr\u00e8s dynamique et tourn\u00e9 vers l\u2019avant, g\u00e9n\u00e9reux dans l\u2019effort, capable d\u2019apporter ses qualit\u00e9s techniques dans la moiti\u00e9 de terrain adverse et de se montrer d\u00e9cisif*\u00bb, a-t-il d\u00e9clar\u00e9.<\/p>\n<p>Paul Mitchell a \u00e9galement soulign\u00e9 et justifi\u00e9 le choix de Vanderson de rejoindre l&rsquo;ASM plut\u00f4t qu&rsquo;un autre club : \u00ab*Vanderson est un jeune joueur talentueux et ambitieux, qui a fait le choix de Monaco malgr\u00e9 l\u2019int\u00e9r\u00eat de plusieurs clubs de premier plan. Nous sommes convaincus qu\u2019il trouvera ici l\u2019environnement id\u00e9al pour permettre d\u2019exprimer pleinement son potentiel tout en apportant une valeur ajout\u00e9e \u00e0 un groupe comp\u00e9titif.*\u00bb<\/p>\n<p>Photo : *AS Monaco*<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Paul Mitchell, le directeur sportif de l&rsquo;AS Monaco, s&rsquo;est f\u00e9licit\u00e9 de la signature du br\u00e9silien Vanderson pour les cinq prochaines saisons : \u00ab*Nous sommes tr\u00e8s heureux d\u2019accueillir Vanderson \u00e0 l\u2019AS Monaco.*\u00bb Mitchell a \u00e9galement r\u00e9v\u00e9l\u00e9 quelques caract\u00e9ristiques du joueur, qui s&rsquo;apparentent \u00e0 celles du lat\u00e9ral moderne : \u00ab*C\u2019est un d\u00e9fenseur tr\u00e8s dynamique et tourn\u00e9 vers [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mitchell : \u00ab Vanderson, un d\u00e9fenseur tr\u00e8s dynamique \u00bb - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/01\/mitchell-vanderson-un-defenseur-tres-dynamique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mitchell : \u00ab Vanderson, un d\u00e9fenseur tr\u00e8s dynamique \u00bb - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Paul Mitchell, le directeur sportif de l&rsquo;AS Monaco, s&rsquo;est f\u00e9licit\u00e9 de la signature du br\u00e9silien Vanderson pour les cinq prochaines saisons : \u00ab*Nous sommes tr\u00e8s heureux d\u2019accueillir Vanderson \u00e0 l\u2019AS Monaco.*\u00bb Mitchell a \u00e9galement r\u00e9v\u00e9l\u00e9 quelques caract\u00e9ristiques du joueur, qui s&rsquo;apparentent \u00e0 celles du lat\u00e9ral moderne : \u00ab*C\u2019est un d\u00e9fenseur tr\u00e8s dynamique et tourn\u00e9 vers [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/01\/mitchell-vanderson-un-defenseur-tres-dynamique\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-01T13:38:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-26T12:31:41+00:00\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/01\/mitchell-vanderson-un-defenseur-tres-dynamique\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/01\/mitchell-vanderson-un-defenseur-tres-dynamique\/\",\"name\":\"Mitchell : \u00ab Vanderson, un d\u00e9fenseur tr\u00e8s dynamique \u00bb - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2022-01-01T13:38:00+00:00\",\"dateModified\":\"2022-07-26T12:31:41+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/01\/mitchell-vanderson-un-defenseur-tres-dynamique\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/01\/mitchell-vanderson-un-defenseur-tres-dynamique\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/01\/mitchell-vanderson-un-defenseur-tres-dynamique\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mitchell : \u00ab Vanderson, un d\u00e9fenseur tr\u00e8s dynamique \u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mitchell : \u00ab Vanderson, un d\u00e9fenseur tr\u00e8s dynamique \u00bb - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/01\/mitchell-vanderson-un-defenseur-tres-dynamique\/","og_locale":"fr_FR","og_type":"article","og_title":"Mitchell : \u00ab Vanderson, un d\u00e9fenseur tr\u00e8s dynamique \u00bb - La Diagonale","og_description":"Paul Mitchell, le directeur sportif de l&rsquo;AS Monaco, s&rsquo;est f\u00e9licit\u00e9 de la signature du br\u00e9silien Vanderson pour les cinq prochaines saisons : \u00ab*Nous sommes tr\u00e8s heureux d\u2019accueillir Vanderson \u00e0 l\u2019AS Monaco.*\u00bb Mitchell a \u00e9galement r\u00e9v\u00e9l\u00e9 quelques caract\u00e9ristiques du joueur, qui s&rsquo;apparentent \u00e0 celles du lat\u00e9ral moderne : \u00ab*C\u2019est un d\u00e9fenseur tr\u00e8s dynamique et tourn\u00e9 vers [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/01\/mitchell-vanderson-un-defenseur-tres-dynamique\/","og_site_name":"La Diagonale","article_published_time":"2022-01-01T13:38:00+00:00","article_modified_time":"2022-07-26T12:31:41+00:00","author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/01\/mitchell-vanderson-un-defenseur-tres-dynamique\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/01\/mitchell-vanderson-un-defenseur-tres-dynamique\/","name":"Mitchell : \u00ab Vanderson, un d\u00e9fenseur tr\u00e8s dynamique \u00bb - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2022-01-01T13:38:00+00:00","dateModified":"2022-07-26T12:31:41+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/01\/mitchell-vanderson-un-defenseur-tres-dynamique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/01\/mitchell-vanderson-un-defenseur-tres-dynamique\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/01\/mitchell-vanderson-un-defenseur-tres-dynamique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Mitchell : \u00ab Vanderson, un d\u00e9fenseur tr\u00e8s dynamique \u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/428"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=428"}],"version-history":[{"count":1,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/428\/revisions"}],"predecessor-version":[{"id":2387,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/428\/revisions\/2387"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}