{"id":4350,"date":"2022-09-12T00:00:00","date_gmt":"2022-09-11T22:00:00","guid":{"rendered":"https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/12\/monaco-montre-les-dents\/"},"modified":"2023-12-14T19:00:52","modified_gmt":"2023-12-14T18:00:52","slug":"monaco-montre-les-dents","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/12\/monaco-montre-les-dents\/","title":{"rendered":"Monaco montre les dents"},"content":{"rendered":"\n\n\n<p><strong>Enfin ! Monaco tient son premier succ\u00e8s de la saison sur son terrain. Face \u00e0 Lyon, l\u2019ASM a su montrer un visage plus conqu\u00e9rant et plus enthousiasmant que celui contre Nice et Belgrade. Le r\u00e9sultat confirme que le collectif rouge et blanc monte en puissance et cela lui permet de se replacer au classement.<\/strong><\/p>\n\n\n\n<div class=\"wp-container-1 wp-block-group has-cyan-bluish-gray-background-color has-background\"><div class=\"wp-block-group__inner-container\">\n<h3 class=\"has-text-align-center\">La feuille de match<\/h3>\n\n\n\n<p><strong>Buts :<\/strong> Badiashile (55<sup>e<\/sup>), Maripan (63<sup>e<\/sup>) pour Monaco ; Toko-Ekambi (81<sup>e<\/sup>) pour Lyon.<\/p>\n\n\n\n<p><strong>Avertissements :<\/strong> Golovin (86<sup>e<\/sup>) pour Monaco ; Lukeba (65<sup>e<\/sup>), Lacazette (79<sup>e<\/sup>) pour Lyon.<\/p>\n\n\n\n<p><strong>AS Monaco :<\/strong> N\u00fcbel &#8211; Disasi, Maripan (Sarr, 68<sup>e<\/sup>), Badiashile \u2013 Vanderson (Aguilar, 72<sup>e<\/sup>), Fofana, Camara, C. Henrique \u2013 Diatta (G. Martins, 86<sup>e<\/sup>), Golovin (Jakobs, 86<sup>e<\/sup>), Embolo (Ben Yedder, 86<sup>e<\/sup>).<\/p>\n\n\n\n<p><strong>O. Lyonnais :<\/strong> Lopes &#8211; Gusto, Thiago Mendes (Cherki, 75<sup>e<\/sup>), Lukeba, Tagliafico \u2013 Lepenant (Reine-Adela\u00efde, 75<sup>e<\/sup>), Tolisso (Faivre, 83<sup>e<\/sup>), Caqueret (Demb\u00e9l\u00e9, 62<sup>e<\/sup>) &#8211; Tet\u00ea, Toko Ekambi, Lacazette.<\/p>\n<\/div><\/div>\n\n\n\n<h3>Le match<\/h3>\n\n\n\n<p>Plusieurs jours avant la rencontre, il \u00e9tait question que Wissam Ben Yedder soit titulaire et accompagn\u00e9 de Breel Embolo. Mais Philippe Clement avait temp\u00e9r\u00e9 les attentes en conf\u00e9rence de presse au sujet de son duo d\u2019attaquants. Et il s\u2019est finalement pass\u00e9 de l\u2019international fran\u00e7ais au coup d\u2019envoi pour aligner seulement Embolo, soutenu par Golovin et Diatta. Pour cette rencontre face \u00e0 l\u2019OL, l\u2019entra\u00eeneur belge a une fois de plus reconduit son syst\u00e8me en 3-4-3, avec lequel il semble d\u00e9sormais pr\u00eat \u00e0 avancer, notamment pour trouver des solutions sur l\u2019animation offensive. Du mieux, justement, on en a vu, m\u00eame si cette \u00e9quipe as\u00e9miste semble encore h\u00e9sitante dans la construction du jeu. C\u2019est finalement sur les phases arr\u00eat\u00e9es qu\u2019elle a fait la d\u00e9cision, comme c\u2019est souvent le cas cette saison.<\/p>\n\n\n\n<p>Les Rouge et Blanc se sont aussi retrouv\u00e9s dans une position qu\u2019ils affectionnent, celle qui consiste \u00e0 laisse le ballon \u00e0 leur adversaire et \u00e0 piquer en transition. Ils ont poursuivi le travail de sape en allant presser haut le bloc lyonnais et se sont finalement procur\u00e9 un plus grand nombre de situations au cours de la premi\u00e8re p\u00e9riode, notamment avec le poteau trouv\u00e9 par Diatta (15<sup>e<\/sup>), sur un centre ajust\u00e9 par Golovin, qui n\u2019\u00e9tait pas attaqu\u00e9. Dans la foul\u00e9e, Embolo ne parvenait pas \u00e0 ajuster sa t\u00eate (16<sup>e<\/sup>). Lyon a r\u00e9agi, par l\u2019interm\u00e9diaire de son capitaine Lacazette mais N\u00fcbel s\u2019est interpos\u00e9 (21<sup>e<\/sup>). Si l\u2019ASM a proc\u00e9d\u00e9 en transitions, l\u2019OL \u00e9tait \u00e9galement dangereux dans ces phases de jeu, et les combinaisons entre leurs lat\u00e9raux et leurs ailiers pour apporter le surnombre ont souvent fait des d\u00e9g\u00e2ts. Tet\u00ea a d\u2019ailleurs failli en profiter mais il n&rsquo;est pas parvenu \u00e0 trouver le cadre (43<sup>e<\/sup>).<\/p>\n\n\n\n<p>Les Lyonnais reprendront mieux la seconde p\u00e9riode et Lacazette, encore lui, s\u2019est avanc\u00e9 pour d\u00e9fier N\u00fcbel. Le portier allemand a contraint le capitaine des Gones au mutisme dans cette rencontre (53<sup>e<\/sup>). Monaco r\u00e9agit et sur un bon corner de Caio Henrique, Badiashile se lib\u00e8re du marquage de Thiago Mendes et trompe Lopes de la t\u00eate (55<sup>e<\/sup>). Quelques minutes plus tard, Maripan fait le break pour l\u2019ASM, sur un nouveau caviar de Caio Henrique, mais sur coup franc cette fois (63<sup>e<\/sup>). Coup dur pour les Lyonnais qui vont attaquer tous azimuts pour revenir dans la partie. C\u2019est paradoxalement \u00e0 cet instant que Monaco va prendre le contr\u00f4le du cuir sans toutefois parvenir \u00e0 \u00e9viter de se faire peur. Lyon r\u00e9duit la marque par Toko-Ekambi (81<sup>e<\/sup>) et Demb\u00e9l\u00e9 rate son face-\u00e0-face en allumant N\u00fcbel pleine t\u00eate (90<sup>e<\/sup>). M\u00eame si les Rouge et Blanc ont eu quelques frayeurs, ils ont tenu jusqu\u2019au bout et accrochent leur premier succ\u00e8s \u00e0 domicile. Esp\u00e9rons que ce soit le premier d\u2019une longue s\u00e9rie.<\/p>\n\n\n\n<h3>La stat<\/h3>\n\n\n\n<h2 class=\"has-text-align-center\">2<\/h2>\n\n\n\n<p>Caio Henrique a d\u00e9livr\u00e9 un doubl\u00e9 de passes d\u00e9cisives pour la deuxi\u00e8me fois de sa carri\u00e8re en Ligue 1, apr\u00e8s septembre 2021 \u00e0 Clermont. Depuis d\u00e9but avril, c\u2019est sa septi\u00e8me offrande en championnat.<\/p>\n\n\n\n<p>Source : <em>Opta<\/em><\/p>\n\n\n\n<h3>La d\u00e9claration<\/h3>\n\n\n\n<p>Philippe Clement : \u00ab <em>La performance collective est meilleure par rapport \u00e0 la semaine derni\u00e8re par exemple, m\u00eame si ce n\u2019est pas encore parfait. Je pense que tous ceux qui ont regard\u00e9 ce match ont pris du plaisir avec deux \u00e9quipes qui voulaient l\u2019emporter.<\/em> \u00bb<\/p>\n\n\n\n<p>Photo : AS Monaco<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Enfin ! Monaco tient son premier succ\u00e8s de la saison sur son terrain. Face \u00e0 Lyon, l\u2019ASM a su montrer un visage plus conqu\u00e9rant et plus enthousiasmant que celui contre Nice et Belgrade. Le r\u00e9sultat confirme que le collectif rouge et blanc monte en puissance et cela lui permet de se replacer au classement. La [&#8230;]\n","protected":false},"author":1,"featured_media":18904,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,6],"tags":[86,94,729],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Monaco montre les dents - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/12\/monaco-montre-les-dents\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Monaco montre les dents - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Enfin ! Monaco tient son premier succ\u00e8s de la saison sur son terrain. Face \u00e0 Lyon, l\u2019ASM a su montrer un visage plus conqu\u00e9rant et plus enthousiasmant que celui contre Nice et Belgrade. Le r\u00e9sultat confirme que le collectif rouge et blanc monte en puissance et cela lui permet de se replacer au classement. La [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/12\/monaco-montre-les-dents\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-11T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-14T18:00:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/12\/OL22.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/12\/monaco-montre-les-dents\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/12\/monaco-montre-les-dents\/\",\"name\":\"Monaco montre les dents - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2022-09-11T22:00:00+00:00\",\"dateModified\":\"2023-12-14T18:00:52+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/03fa041acd51875ece8bf97a37252a4d\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/12\/monaco-montre-les-dents\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/12\/monaco-montre-les-dents\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/12\/monaco-montre-les-dents\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Monaco montre les dents\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/03fa041acd51875ece8bf97a37252a4d\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/894b9daaf19cc759b072b6bb09cac5f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/894b9daaf19cc759b072b6bb09cac5f2?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/v2.ladiagonale.net\"],\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Monaco montre les dents - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/12\/monaco-montre-les-dents\/","og_locale":"fr_FR","og_type":"article","og_title":"Monaco montre les dents - La Diagonale","og_description":"Enfin ! Monaco tient son premier succ\u00e8s de la saison sur son terrain. Face \u00e0 Lyon, l\u2019ASM a su montrer un visage plus conqu\u00e9rant et plus enthousiasmant que celui contre Nice et Belgrade. Le r\u00e9sultat confirme que le collectif rouge et blanc monte en puissance et cela lui permet de se replacer au classement. La [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/12\/monaco-montre-les-dents\/","og_site_name":"La Diagonale","article_published_time":"2022-09-11T22:00:00+00:00","article_modified_time":"2023-12-14T18:00:52+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/12\/OL22.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/12\/monaco-montre-les-dents\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/12\/monaco-montre-les-dents\/","name":"Monaco montre les dents - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2022-09-11T22:00:00+00:00","dateModified":"2023-12-14T18:00:52+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/03fa041acd51875ece8bf97a37252a4d"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/12\/monaco-montre-les-dents\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/12\/monaco-montre-les-dents\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/12\/monaco-montre-les-dents\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Monaco montre les dents"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/03fa041acd51875ece8bf97a37252a4d","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/894b9daaf19cc759b072b6bb09cac5f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/894b9daaf19cc759b072b6bb09cac5f2?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/v2.ladiagonale.net"],"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/4350"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=4350"}],"version-history":[{"count":1,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/4350\/revisions"}],"predecessor-version":[{"id":18906,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/4350\/revisions\/18906"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media\/18904"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=4350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=4350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=4350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}