{"id":4418,"date":"2022-09-19T00:00:00","date_gmt":"2022-09-18T22:00:00","guid":{"rendered":"https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/19\/ligue-1-8e-journee-monaco-retrouve-le-top-5\/"},"modified":"2022-09-19T00:00:00","modified_gmt":"2022-09-18T22:00:00","slug":"ligue-1-8e-journee-monaco-retrouve-le-top-5","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/19\/ligue-1-8e-journee-monaco-retrouve-le-top-5\/","title":{"rendered":"Ligue 1 &#8211; 8e journ\u00e9e : Monaco retrouve le top 5"},"content":{"rendered":"<p>Pour cette 8e journ\u00e9e de Ligue 1, c\u2019est l\u2019AS Monaco qui a fait la bonne affaire en battant Reims (0-3). Les Mon\u00e9gasques se replacent id\u00e9alement au moment o\u00f9 d\u00e9bute la premi\u00e8re tr\u00eave internationale de la saison puisqu\u2019ils r\u00e9int\u00e8grent le top 5 du classement et passent devant Lyon. Les Mon\u00e9gasques comptent 14 points et refont leur retard par rapport aux \u00e9quipes de devant, hormis le PSG.<\/p>\n<p>Paris a justement battu Lyon (0-1) et les joueurs de Galtier comptent 22 points. Il se d\u00e9tachent quelque peu de Marseille, qui a conc\u00e9d\u00e9 le match nul sur sa pelouse contre Rennes (1-1). Toujours invaincus, les hommes de Tudor totalisent 20 points, soit six de plus que l\u2019ASM. Derri\u00e8re, suit le FC Lorient qui n\u2019en finit plus de surprendre gr\u00e2ce \u00e0 son succ\u00e8s \u00e0 Auxerre (1-3). Les Merlus poss\u00e8dent 19 points. Lens perd une place, suite \u00e0 son match contre Nantes (0-0) mais garde une avance de quatre points sur l\u2019ASM.<\/p>\n<p>Si Monaco a d\u00e9pass\u00e9 Lyon, il a \u00e9galement d\u00e9pass\u00e9 Rennes au classement. Lille reste un point derri\u00e8re apr\u00e8s un succ\u00e8s convaincant contre Toulouse. En revanche, Nice ne parvient pas \u00e0 d\u00e9coller. Les rivaux de la C\u00f4te d\u2019Azur se sont inclin\u00e9s contre Angers (0-1) mais ils ont sign\u00e9 un record, avec l\u2019expulsion la plus rapide de l\u2019histoire de la Ligue 1. En effet, Todibo a re\u00e7u un carton rouge au bout de neuf secondes de jeu. <\/p>\n<p> Les r\u00e9sultats complets<\/p>\n<p>Auxerre 1-3 Lorient<br \/>\nMontpellier 2-1 Strasbourg<br \/>\nLille 2-1 Toulouse<br \/>\nReims 0-3 Monaco<br \/>\nBrest 0-1 Ajaccio<br \/>\nClermont 1-3 Troyes<br \/>\nMarseille 1-1 Rennes<br \/>\nNice 0-1 Angers<br \/>\nNantes 0-0 Lens<br \/>\nLyon 0-1 Paris<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour cette 8e journ\u00e9e de Ligue 1, c\u2019est l\u2019AS Monaco qui a fait la bonne affaire en battant Reims (0-3). Les Mon\u00e9gasques se replacent id\u00e9alement au moment o\u00f9 d\u00e9bute la premi\u00e8re tr\u00eave internationale de la saison puisqu\u2019ils r\u00e9int\u00e8grent le top 5 du classement et passent devant Lyon. Les Mon\u00e9gasques comptent 14 points et refont leur [&#8230;]\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ligue 1 - 8e journ\u00e9e : Monaco retrouve le top 5 - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/19\/ligue-1-8e-journee-monaco-retrouve-le-top-5\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ligue 1 - 8e journ\u00e9e : Monaco retrouve le top 5 - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Pour cette 8e journ\u00e9e de Ligue 1, c\u2019est l\u2019AS Monaco qui a fait la bonne affaire en battant Reims (0-3). Les Mon\u00e9gasques se replacent id\u00e9alement au moment o\u00f9 d\u00e9bute la premi\u00e8re tr\u00eave internationale de la saison puisqu\u2019ils r\u00e9int\u00e8grent le top 5 du classement et passent devant Lyon. Les Mon\u00e9gasques comptent 14 points et refont leur [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/19\/ligue-1-8e-journee-monaco-retrouve-le-top-5\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-18T22:00:00+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/19\/ligue-1-8e-journee-monaco-retrouve-le-top-5\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/19\/ligue-1-8e-journee-monaco-retrouve-le-top-5\/\",\"name\":\"Ligue 1 - 8e journ\u00e9e : Monaco retrouve le top 5 - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2022-09-18T22:00:00+00:00\",\"dateModified\":\"2022-09-18T22:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/03fa041acd51875ece8bf97a37252a4d\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/19\/ligue-1-8e-journee-monaco-retrouve-le-top-5\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/19\/ligue-1-8e-journee-monaco-retrouve-le-top-5\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/19\/ligue-1-8e-journee-monaco-retrouve-le-top-5\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ligue 1 &#8211; 8e journ\u00e9e : Monaco retrouve le top 5\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/03fa041acd51875ece8bf97a37252a4d\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/894b9daaf19cc759b072b6bb09cac5f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/894b9daaf19cc759b072b6bb09cac5f2?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/v2.ladiagonale.net\"],\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ligue 1 - 8e journ\u00e9e : Monaco retrouve le top 5 - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/19\/ligue-1-8e-journee-monaco-retrouve-le-top-5\/","og_locale":"fr_FR","og_type":"article","og_title":"Ligue 1 - 8e journ\u00e9e : Monaco retrouve le top 5 - La Diagonale","og_description":"Pour cette 8e journ\u00e9e de Ligue 1, c\u2019est l\u2019AS Monaco qui a fait la bonne affaire en battant Reims (0-3). Les Mon\u00e9gasques se replacent id\u00e9alement au moment o\u00f9 d\u00e9bute la premi\u00e8re tr\u00eave internationale de la saison puisqu\u2019ils r\u00e9int\u00e8grent le top 5 du classement et passent devant Lyon. Les Mon\u00e9gasques comptent 14 points et refont leur [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/19\/ligue-1-8e-journee-monaco-retrouve-le-top-5\/","og_site_name":"La Diagonale","article_published_time":"2022-09-18T22:00:00+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/19\/ligue-1-8e-journee-monaco-retrouve-le-top-5\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/19\/ligue-1-8e-journee-monaco-retrouve-le-top-5\/","name":"Ligue 1 - 8e journ\u00e9e : Monaco retrouve le top 5 - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2022-09-18T22:00:00+00:00","dateModified":"2022-09-18T22:00:00+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/03fa041acd51875ece8bf97a37252a4d"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/19\/ligue-1-8e-journee-monaco-retrouve-le-top-5\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/19\/ligue-1-8e-journee-monaco-retrouve-le-top-5\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/09\/19\/ligue-1-8e-journee-monaco-retrouve-le-top-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Ligue 1 &#8211; 8e journ\u00e9e : Monaco retrouve le top 5"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/03fa041acd51875ece8bf97a37252a4d","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/894b9daaf19cc759b072b6bb09cac5f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/894b9daaf19cc759b072b6bb09cac5f2?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/v2.ladiagonale.net"],"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/4418"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=4418"}],"version-history":[{"count":0,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/4418\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=4418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=4418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=4418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}