{"id":562,"date":"2022-01-30T23:45:14","date_gmt":"2022-01-30T22:45:14","guid":{"rendered":"https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/30\/monaco-sest-fait-peur-2-4\/"},"modified":"2022-07-26T14:30:38","modified_gmt":"2022-07-26T12:30:38","slug":"monaco-sest-fait-peur-2-4","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/30\/monaco-sest-fait-peur-2-4\/","title":{"rendered":"Monaco s\u2019est fait peur (2-4)"},"content":{"rendered":"<p>**Si l\u2019ASM a finalement r\u00e9ussi \u00e0 conserver son avance de la premi\u00e8re p\u00e9riode, les hommes de Philippe Clement ont trembl\u00e9 en seconde p\u00e9riode pour arracher leur ticket pour les quarts de finale de la Coupe de France.**<\/p>\n<p>**Le match :** <\/p>\n<p>La rencontre a id\u00e9alement commenc\u00e9 pour les Mon\u00e9gasques. Si Mannone a \u00e9t\u00e9 le premier \u00e0 se mettre en valeur, en s\u2019interposant devant Fofana (6e) et Kakuta (8e), les joueurs de champs ont ensuite pris le relais. D\u2019abord, sur un centre au cordeau de Caio Henrique, Wissam Ben Yedder s\u2019est gliss\u00e9 entre deux d\u00e9fenseurs lensois pour reprendre le ballon de la t\u00eate et tromper Jean-Louis Leca (18e). Quelques minutes apr\u00e8s, Jean Lucas a inscrit son premier but de la saison sur un service de Gelson Martins (26e). Les As\u00e9mistes ont m\u00eame alourdi la marque sur un bon mouvement collectif qui a permis \u00e0 Jean Lucas de trouver Sofiane Diop au second poteau (28e). Fort d\u2019une belle avance, l\u2019ASM aurait pu encore aggraver le score mais c\u2019est finalement Lens qui marque avant le retour aux vestiaires par Sa\u00efd (45e).<\/p>\n<p>Un but qui va transformer les *Sang et Or* d\u00e8s l\u2019entame de la seconde p\u00e9riode. Dans le m\u00eame temps, les hommes de Philippe Clement ont sembl\u00e9 \u00eatre rest\u00e9s aux vestiaires. Sur une passe en profondeur de Fofana, Kalimuendo a fix\u00e9 Caio Henrique et Chrislain Matsima avant d\u2019armer une frappe qui a fini dans le petit filet de Mannone (53e). Monaco aurait pu se donner de l\u2019air mais Diop a rat\u00e9 l\u2019immanquable face \u00e0 Leca (58e). Une seconde p\u00e9riode o\u00f9 Monaco va courber l\u2019\u00e9chine sans rompre. Les Lensois ont souvent mis Mannone \u00e0 contribution sur des frappes lointaines mais le gardien italien s\u2019est montr\u00e9 impeccable par la suite. Le temps fort des nordistes pass\u00e9, Monaco a parachev\u00e9 son succ\u00e8s avec un quatri\u00e8me but, le deuxi\u00e8me pour Wissam Ben Yedder, sur un service de Tchouam\u00e9ni.<\/p>\n<p>**La Stat :**<\/p>\n<p>*61*<\/p>\n<p>Wissam Ben Yedder a inscrit son 60e et 61e but avec l\u2019AS Monaco. Il n\u2019est plus qu\u2019\u00e0 cinq buts d\u2019int\u00e9grer le top 10 des meilleurs buteurs de l\u2019histoire du club. <\/p>\n<p>**La d\u00e9claration :**<\/p>\n<p>Aur\u00e9lien Tchouam\u00e9ni : *On savait que si on arrivait \u00e0 trouver de la verticalit\u00e9 \u00e0 la r\u00e9cup\u00e9ration, on pouvait les mettre en difficult\u00e9. Les quatre buts sont venus de contre-attaques, \u00e7a veut dire qu\u2019on a bien respect\u00e9 le plan*<\/p>\n","protected":false},"excerpt":{"rendered":"<p>**Si l\u2019ASM a finalement r\u00e9ussi \u00e0 conserver son avance de la premi\u00e8re p\u00e9riode, les hommes de Philippe Clement ont trembl\u00e9 en seconde p\u00e9riode pour arracher leur ticket pour les quarts de finale de la Coupe de France.** **Le match :** La rencontre a id\u00e9alement commenc\u00e9 pour les Mon\u00e9gasques. Si Mannone a \u00e9t\u00e9 le premier \u00e0 [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Monaco s\u2019est fait peur (2-4) - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/30\/monaco-sest-fait-peur-2-4\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Monaco s\u2019est fait peur (2-4) - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"**Si l\u2019ASM a finalement r\u00e9ussi \u00e0 conserver son avance de la premi\u00e8re p\u00e9riode, les hommes de Philippe Clement ont trembl\u00e9 en seconde p\u00e9riode pour arracher leur ticket pour les quarts de finale de la Coupe de France.** **Le match :** La rencontre a id\u00e9alement commenc\u00e9 pour les Mon\u00e9gasques. Si Mannone a \u00e9t\u00e9 le premier \u00e0 [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/30\/monaco-sest-fait-peur-2-4\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-30T22:45:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-26T12:30:38+00:00\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/30\/monaco-sest-fait-peur-2-4\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/30\/monaco-sest-fait-peur-2-4\/\",\"name\":\"Monaco s\u2019est fait peur (2-4) - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2022-01-30T22:45:14+00:00\",\"dateModified\":\"2022-07-26T12:30:38+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/30\/monaco-sest-fait-peur-2-4\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/30\/monaco-sest-fait-peur-2-4\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/30\/monaco-sest-fait-peur-2-4\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Monaco s\u2019est fait peur (2-4)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Monaco s\u2019est fait peur (2-4) - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/30\/monaco-sest-fait-peur-2-4\/","og_locale":"fr_FR","og_type":"article","og_title":"Monaco s\u2019est fait peur (2-4) - La Diagonale","og_description":"**Si l\u2019ASM a finalement r\u00e9ussi \u00e0 conserver son avance de la premi\u00e8re p\u00e9riode, les hommes de Philippe Clement ont trembl\u00e9 en seconde p\u00e9riode pour arracher leur ticket pour les quarts de finale de la Coupe de France.** **Le match :** La rencontre a id\u00e9alement commenc\u00e9 pour les Mon\u00e9gasques. Si Mannone a \u00e9t\u00e9 le premier \u00e0 [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/30\/monaco-sest-fait-peur-2-4\/","og_site_name":"La Diagonale","article_published_time":"2022-01-30T22:45:14+00:00","article_modified_time":"2022-07-26T12:30:38+00:00","author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/30\/monaco-sest-fait-peur-2-4\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/30\/monaco-sest-fait-peur-2-4\/","name":"Monaco s\u2019est fait peur (2-4) - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2022-01-30T22:45:14+00:00","dateModified":"2022-07-26T12:30:38+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/30\/monaco-sest-fait-peur-2-4\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/30\/monaco-sest-fait-peur-2-4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/01\/30\/monaco-sest-fait-peur-2-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Monaco s\u2019est fait peur (2-4)"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/562"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=562"}],"version-history":[{"count":1,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/562\/revisions"}],"predecessor-version":[{"id":2253,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/562\/revisions\/2253"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}