{"id":6008,"date":"2022-10-25T01:00:05","date_gmt":"2022-10-24T23:00:05","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=6008"},"modified":"2022-10-25T01:00:30","modified_gmt":"2022-10-24T23:00:30","slug":"la-semaine-des-pretes-majecki-decisif","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2022\/10\/25\/la-semaine-des-pretes-majecki-decisif\/","title":{"rendered":"La semaine des pr\u00eat\u00e9s : Majecki d\u00e9cisif"},"content":{"rendered":"\n\n\n<p>Le Cercle Bruges commence \u00e0 aller mieux. Deux matchs de championnat ont \u00e9t\u00e9 disput\u00e9s dans la semaine qui s&rsquo;est \u00e9coul\u00e9e et le club satellite de l\u2019ASM a fait un carton plein avec deux victoires. La premi\u00e8re en milieu de semaine contre Seraing (0-1) avec un but de l\u2019ancien Mon\u00e9gasque Boris Popovic d\u2019une tr\u00e8s belle reprise de vol\u00e9e. Majecki a pass\u00e9 une soir\u00e9e plut\u00f4t tranquille avec seulement deux arr\u00eats \u00e0 effectuer. Marcelin n\u2019a pas pris part \u00e0 cette rencontre.<\/p>\n\n\n\n<p>Il y a eu en revanche bien plus \u00e0 dire pour la deuxi\u00e8me rencontre, celle du week-end, contre Charleroi. Le Cercle Bruges s\u2019est impos\u00e9 plus largement (4-1) mais a toutefois conc\u00e9d\u00e9 deux p\u00e9naltys pour deux mains dans la surface. Le premier par Popovic que Majecki a r\u00e9ussi \u00e0 repousser et le second par Marcelin, qui a en plus \u00e9cop\u00e9 d\u2019un carton jaune. Sur ce dernier, Majecki n\u2019a pas r\u00e9ussi \u00e0 s\u2019interposer.<\/p>\n\n\n\n<p>L\u2019Espanyol Barcelone de Benjamin Lecomte a aussi disput\u00e9 deux rencontres de <em>Liga<\/em> mais avec nettement moins de r\u00e9ussite que le Cercle Bruges. Les Catalans se sont d\u2019abord inclin\u00e9s contre Osasuna (1-0) et Lecomte a permis \u00e0 son \u00e9quipe de rester longtemps dans la course avec quatre arr\u00eats. Il a eu aussi un brin de r\u00e9ussite en voyant une tentative adverse repouss\u00e9e par la barre transversale alors qu&rsquo;il \u00e9tait battu. Le portier fran\u00e7ais n\u2019a pas \u00e9t\u00e9 en mesure de r\u00e9it\u00e9rer cette performance face \u00e0 la lanterne rouge Elche (2-2), en \u00e9tant loin d\u2019\u00eatre irr\u00e9prochable sur les deux buts conc\u00e9d\u00e9s.<\/p>\n\n\n\n<p>Ce lundi, Anthony Musaba a enfin pu avoir un peu plus de temps de jeu avec Metz face au Havre puisqu\u2019il est entr\u00e9 \u00e0 la 68e minute alors que son \u00e9quipe perdait d\u00e9j\u00e0 (2-0). L\u2019ailier n\u00e9erlandais n\u2019a pas pu raviver l\u2019espoir des Messins mais il en \u00e9tait tout proche puisqu\u2019il a trouv\u00e9 le poteau apr\u00e8s un petit festival dans la surface adverse.<\/p>\n\n\n\n<p>Pel\u00e9 a jou\u00e9 57 minutes avec Famalicao contre Pa\u00e7os de Ferreira pour un succ\u00e8s (2-1). Mais le milieu de terrain n\u2019a pas beaucoup pes\u00e9 sur cette rencontre. Avec l\u2019\u00e9quipe r\u00e9serve de Valence, Tiago Ribeiro est entr\u00e9 dans les cinq derni\u00e8res minutes du temps r\u00e9glementaire lors de la d\u00e9faite \u00e0 Ibiza (1-0). Matsima est rest\u00e9 sur le banc avec Lorient et Zagr\u00e9 n\u2019\u00e9tait pas dans le groupe pour les deux matchs de la semaine d\u2019Utrecht.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Cercle Bruges commence \u00e0 aller mieux. Deux matchs de championnat ont \u00e9t\u00e9 disput\u00e9s dans la semaine qui s&rsquo;est \u00e9coul\u00e9e et le club satellite de l\u2019ASM a fait un carton plein avec deux victoires. La premi\u00e8re en milieu de semaine contre Seraing (0-1) avec un but de l\u2019ancien Mon\u00e9gasque Boris Popovic d\u2019une tr\u00e8s belle reprise [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[86,219],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La semaine des pr\u00eat\u00e9s : Majecki d\u00e9cisif - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/10\/25\/la-semaine-des-pretes-majecki-decisif\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La semaine des pr\u00eat\u00e9s : Majecki d\u00e9cisif - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Le Cercle Bruges commence \u00e0 aller mieux. Deux matchs de championnat ont \u00e9t\u00e9 disput\u00e9s dans la semaine qui s&rsquo;est \u00e9coul\u00e9e et le club satellite de l\u2019ASM a fait un carton plein avec deux victoires. La premi\u00e8re en milieu de semaine contre Seraing (0-1) avec un but de l\u2019ancien Mon\u00e9gasque Boris Popovic d\u2019une tr\u00e8s belle reprise [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/10\/25\/la-semaine-des-pretes-majecki-decisif\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-24T23:00:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-24T23:00:30+00:00\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/10\/25\/la-semaine-des-pretes-majecki-decisif\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/10\/25\/la-semaine-des-pretes-majecki-decisif\/\",\"name\":\"La semaine des pr\u00eat\u00e9s : Majecki d\u00e9cisif - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2022-10-24T23:00:05+00:00\",\"dateModified\":\"2022-10-24T23:00:30+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/10\/25\/la-semaine-des-pretes-majecki-decisif\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2022\/10\/25\/la-semaine-des-pretes-majecki-decisif\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/10\/25\/la-semaine-des-pretes-majecki-decisif\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La semaine des pr\u00eat\u00e9s : Majecki d\u00e9cisif\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La semaine des pr\u00eat\u00e9s : Majecki d\u00e9cisif - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2022\/10\/25\/la-semaine-des-pretes-majecki-decisif\/","og_locale":"fr_FR","og_type":"article","og_title":"La semaine des pr\u00eat\u00e9s : Majecki d\u00e9cisif - La Diagonale","og_description":"Le Cercle Bruges commence \u00e0 aller mieux. Deux matchs de championnat ont \u00e9t\u00e9 disput\u00e9s dans la semaine qui s&rsquo;est \u00e9coul\u00e9e et le club satellite de l\u2019ASM a fait un carton plein avec deux victoires. La premi\u00e8re en milieu de semaine contre Seraing (0-1) avec un but de l\u2019ancien Mon\u00e9gasque Boris Popovic d\u2019une tr\u00e8s belle reprise [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/10\/25\/la-semaine-des-pretes-majecki-decisif\/","og_site_name":"La Diagonale","article_published_time":"2022-10-24T23:00:05+00:00","article_modified_time":"2022-10-24T23:00:30+00:00","author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/10\/25\/la-semaine-des-pretes-majecki-decisif\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/10\/25\/la-semaine-des-pretes-majecki-decisif\/","name":"La semaine des pr\u00eat\u00e9s : Majecki d\u00e9cisif - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2022-10-24T23:00:05+00:00","dateModified":"2022-10-24T23:00:30+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/10\/25\/la-semaine-des-pretes-majecki-decisif\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2022\/10\/25\/la-semaine-des-pretes-majecki-decisif\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/10\/25\/la-semaine-des-pretes-majecki-decisif\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"La semaine des pr\u00eat\u00e9s : Majecki d\u00e9cisif"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/6008"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=6008"}],"version-history":[{"count":2,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/6008\/revisions"}],"predecessor-version":[{"id":6010,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/6008\/revisions\/6010"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=6008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=6008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=6008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}