{"id":6539,"date":"2022-11-06T07:00:00","date_gmt":"2022-11-06T06:00:00","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=6539"},"modified":"2022-11-06T03:28:05","modified_gmt":"2022-11-06T02:28:05","slug":"les-compositions-selon-la-presse-volland-va-t-il-debuter","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2022\/11\/06\/les-compositions-selon-la-presse-volland-va-t-il-debuter\/","title":{"rendered":"Les compositions selon la presse : Volland va-t-il d\u00e9buter ?"},"content":{"rendered":"\n\n\n<p>En conf\u00e9rence de presse, Philippe Clement a m\u00e9nag\u00e9 le suspense concernant l&rsquo;attaquant qui accompagnera Wissam Ben Yedder ce dimanche (15h) contre Toulouse. Auteur d&rsquo;un tripl\u00e9 contre Belgrade jeudi, Kevin Volland n&rsquo;est pas forc\u00e9ment parti pour \u00eatre titulaire : \u00ab\u00a0<em>Je dois parler \u00e0 mon staff apr\u00e8s l\u2019entra\u00eenement et ce soir pour voir s\u2019il peut encha\u00eener et prendre les bonnes d\u00e9cisions<\/em>\u00a0\u00bb, a d\u00e9clar\u00e9 le Belge samedi. <em>Nice-Matin<\/em> voit Volland d\u00e9buter la rencontre mais <em>L&rsquo;\u00c9quipe<\/em> pense qu&rsquo;Embolo sera align\u00e9. <\/p>\n\n\n\n<p>Sur l&rsquo;aile droite, Akliouche et Diatta seraient en concurrence pour d\u00e9marrer.<\/p>\n\n\n\n<p><strong>Le onze mon\u00e9gasque selon <em>L\u2019\u00c9quipe<\/em> :<\/strong> N\u00fcbel &#8211; Vanderson, Disasi, Maripan, C. Henrique &#8211; Akliouche, Fofana, Camara, Golovin &#8211; Embolo, Ben Yedder (cap.).<\/p>\n\n\n\n<p><strong>Le onze mon\u00e9gasque selon <em>Nice-Matin<\/em> :<\/strong> N\u00fcbel &#8211; Vanderson, Disasi, Maripan, C. Henrique &#8211; Diatta, Fofana, Camara, Golovin &#8211; Volland, Ben Yedder (cap.).<\/p>\n\n\n\n<p>Avec un groupe au complet, Philippe Montanier peut aligner son onze-type. Nicolaisen et Ratao sont de retour dans le groupe et les deux quotidiens pressentent qu&rsquo;ils d\u00e9buteront la rencontre.<\/p>\n\n\n\n<p><strong>Le onze toulousain selon <em>L\u2019\u00c9quipe<\/em> :<\/strong> Dup\u00e9 &#8211; Keben, Rouault, Nicolaisen, Sylla &#8211; Dejaegere (cap.), Spierings, van den Boomen &#8211; Ratao, Aboukhal, Birmancevic.<\/p>\n\n\n\n<p><strong>Le onze toulousain selon <em>Nice-Matin<\/em> :<\/strong> Dup\u00e9 &#8211; Keben, Rouault, Nicolaisen, Sylla &#8211; Dejaegere (cap.), Spierings, van den Boomen &#8211; Ratao, Aboukhal, Birmancevic.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En conf\u00e9rence de presse, Philippe Clement a m\u00e9nag\u00e9 le suspense concernant l&rsquo;attaquant qui accompagnera Wissam Ben Yedder ce dimanche (15h) contre Toulouse. Auteur d&rsquo;un tripl\u00e9 contre Belgrade jeudi, Kevin Volland n&rsquo;est pas forc\u00e9ment parti pour \u00eatre titulaire : \u00ab\u00a0Je dois parler \u00e0 mon staff apr\u00e8s l\u2019entra\u00eenement et ce soir pour voir s\u2019il peut encha\u00eener et [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[86,213,94,230],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les compositions selon la presse : Volland va-t-il d\u00e9buter ? - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/11\/06\/les-compositions-selon-la-presse-volland-va-t-il-debuter\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les compositions selon la presse : Volland va-t-il d\u00e9buter ? - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"En conf\u00e9rence de presse, Philippe Clement a m\u00e9nag\u00e9 le suspense concernant l&rsquo;attaquant qui accompagnera Wissam Ben Yedder ce dimanche (15h) contre Toulouse. Auteur d&rsquo;un tripl\u00e9 contre Belgrade jeudi, Kevin Volland n&rsquo;est pas forc\u00e9ment parti pour \u00eatre titulaire : \u00ab\u00a0Je dois parler \u00e0 mon staff apr\u00e8s l\u2019entra\u00eenement et ce soir pour voir s\u2019il peut encha\u00eener et [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/11\/06\/les-compositions-selon-la-presse-volland-va-t-il-debuter\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-06T06:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-06T02:28:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/11\/volland.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/11\/volland.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/11\/06\/les-compositions-selon-la-presse-volland-va-t-il-debuter\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/11\/06\/les-compositions-selon-la-presse-volland-va-t-il-debuter\/\",\"name\":\"Les compositions selon la presse : Volland va-t-il d\u00e9buter ? - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2022-11-06T06:00:00+00:00\",\"dateModified\":\"2022-11-06T02:28:05+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/11\/06\/les-compositions-selon-la-presse-volland-va-t-il-debuter\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2022\/11\/06\/les-compositions-selon-la-presse-volland-va-t-il-debuter\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/11\/06\/les-compositions-selon-la-presse-volland-va-t-il-debuter\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les compositions selon la presse : Volland va-t-il d\u00e9buter ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les compositions selon la presse : Volland va-t-il d\u00e9buter ? - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2022\/11\/06\/les-compositions-selon-la-presse-volland-va-t-il-debuter\/","og_locale":"fr_FR","og_type":"article","og_title":"Les compositions selon la presse : Volland va-t-il d\u00e9buter ? - La Diagonale","og_description":"En conf\u00e9rence de presse, Philippe Clement a m\u00e9nag\u00e9 le suspense concernant l&rsquo;attaquant qui accompagnera Wissam Ben Yedder ce dimanche (15h) contre Toulouse. Auteur d&rsquo;un tripl\u00e9 contre Belgrade jeudi, Kevin Volland n&rsquo;est pas forc\u00e9ment parti pour \u00eatre titulaire : \u00ab\u00a0Je dois parler \u00e0 mon staff apr\u00e8s l\u2019entra\u00eenement et ce soir pour voir s\u2019il peut encha\u00eener et [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/11\/06\/les-compositions-selon-la-presse-volland-va-t-il-debuter\/","og_site_name":"La Diagonale","article_published_time":"2022-11-06T06:00:00+00:00","article_modified_time":"2022-11-06T02:28:05+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/11\/volland.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/11\/volland.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/11\/06\/les-compositions-selon-la-presse-volland-va-t-il-debuter\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/11\/06\/les-compositions-selon-la-presse-volland-va-t-il-debuter\/","name":"Les compositions selon la presse : Volland va-t-il d\u00e9buter ? - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2022-11-06T06:00:00+00:00","dateModified":"2022-11-06T02:28:05+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/11\/06\/les-compositions-selon-la-presse-volland-va-t-il-debuter\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2022\/11\/06\/les-compositions-selon-la-presse-volland-va-t-il-debuter\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/11\/06\/les-compositions-selon-la-presse-volland-va-t-il-debuter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Les compositions selon la presse : Volland va-t-il d\u00e9buter ?"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/6539"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=6539"}],"version-history":[{"count":3,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/6539\/revisions"}],"predecessor-version":[{"id":6544,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/6539\/revisions\/6544"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=6539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=6539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=6539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}