{"id":7233,"date":"2022-11-29T21:56:06","date_gmt":"2022-11-29T20:56:06","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=7233"},"modified":"2022-12-01T12:23:53","modified_gmt":"2022-12-01T11:23:53","slug":"jesper-daland-sentraine-avec-lasm","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2022\/11\/29\/jesper-daland-sentraine-avec-lasm\/","title":{"rendered":"Jesper Daland s&rsquo;entra\u00eene avec l&rsquo;ASM"},"content":{"rendered":"\n\n\n<p>L&rsquo;AS Monaco a pris ses quartiers \u00e0 Benidorm, dans l\u2019agglom\u00e9ration de Valence en Espagne ce mardi, et a notamment retrouv\u00e9 le Cercle Bruges qui s&rsquo;y trouvait d\u00e9j\u00e0 depuis la veille. Sur les diff\u00e9rentes photos post\u00e9es sur les r\u00e9seaux sociaux des joueurs as\u00e9mistes, on a pu notamment remarquer la pr\u00e9sence de Jesper Daland (22 ans), athl\u00e9tique d\u00e9fenseur central norv\u00e9gien du Cercle Bruges et international Espoirs (<em>13 s\u00e9lections<\/em>).<\/p>\n\n\n\n<p>Si la pr\u00e9sence de Daland dans les rangs mon\u00e9gasques n&rsquo;a pas \u00e9t\u00e9 pr\u00e9cis\u00e9e officiellement par le club de la Principaut\u00e9, ni par le Cercle, celle-ci se place tr\u00e8s probablement dans la cadre de la mutualisation des comp\u00e9tences entre les deux clubs. Thomas Didillon en avait notamment b\u00e9n\u00e9fici\u00e9 \u00e0 l&rsquo;intersaison avant d&rsquo;\u00eatre pr\u00eat\u00e9 pour une saison sur le Rocher. Dans l&rsquo;autre sens, <a href=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/06\/15\/cinq-joueurs-de-las-monaco-au-cercle-bruges\/\">cinq joueurs avaient \u00e9t\u00e9 observ\u00e9s<\/a> pendant un mois avec le groupe brugeois. <\/p>\n\n\n\n<p>Daland profite aussi de l&rsquo;absence de Beno\u00eet Badiashile, annonc\u00e9 dans le groupe du stage mais dont <em>Nice-Matin<\/em> avait r\u00e9v\u00e9l\u00e9 qu&rsquo;il avait eu droit \u00e0 une semaine de repos suppl\u00e9mentaire en raison de sa convocation avec les Espoirs au d\u00e9but de la tr\u00eave internationale.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" width=\"1074\" height=\"665\" src=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/11\/IMG_8D681604D516-1.jpeg\" alt=\"\" class=\"wp-image-7234\"\/><figcaption>Jesper Daland, debout au centre sur le photo<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;AS Monaco a pris ses quartiers \u00e0 Benidorm, dans l\u2019agglom\u00e9ration de Valence en Espagne ce mardi, et a notamment retrouv\u00e9 le Cercle Bruges qui s&rsquo;y trouvait d\u00e9j\u00e0 depuis la veille. Sur les diff\u00e9rentes photos post\u00e9es sur les r\u00e9seaux sociaux des joueurs as\u00e9mistes, on a pu notamment remarquer la pr\u00e9sence de Jesper Daland (22 ans), athl\u00e9tique [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[86,212,330,297],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Jesper Daland s&#039;entra\u00eene avec l&#039;ASM - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/11\/29\/jesper-daland-sentraine-avec-lasm\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jesper Daland s&#039;entra\u00eene avec l&#039;ASM - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;AS Monaco a pris ses quartiers \u00e0 Benidorm, dans l\u2019agglom\u00e9ration de Valence en Espagne ce mardi, et a notamment retrouv\u00e9 le Cercle Bruges qui s&rsquo;y trouvait d\u00e9j\u00e0 depuis la veille. Sur les diff\u00e9rentes photos post\u00e9es sur les r\u00e9seaux sociaux des joueurs as\u00e9mistes, on a pu notamment remarquer la pr\u00e9sence de Jesper Daland (22 ans), athl\u00e9tique [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/11\/29\/jesper-daland-sentraine-avec-lasm\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-29T20:56:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-01T11:23:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/11\/daland.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/11\/daland.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/11\/29\/jesper-daland-sentraine-avec-lasm\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/11\/29\/jesper-daland-sentraine-avec-lasm\/\",\"name\":\"Jesper Daland s'entra\u00eene avec l'ASM - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2022-11-29T20:56:06+00:00\",\"dateModified\":\"2022-12-01T11:23:53+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/11\/29\/jesper-daland-sentraine-avec-lasm\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2022\/11\/29\/jesper-daland-sentraine-avec-lasm\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/11\/29\/jesper-daland-sentraine-avec-lasm\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jesper Daland s&rsquo;entra\u00eene avec l&rsquo;ASM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jesper Daland s'entra\u00eene avec l'ASM - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2022\/11\/29\/jesper-daland-sentraine-avec-lasm\/","og_locale":"fr_FR","og_type":"article","og_title":"Jesper Daland s'entra\u00eene avec l'ASM - La Diagonale","og_description":"L&rsquo;AS Monaco a pris ses quartiers \u00e0 Benidorm, dans l\u2019agglom\u00e9ration de Valence en Espagne ce mardi, et a notamment retrouv\u00e9 le Cercle Bruges qui s&rsquo;y trouvait d\u00e9j\u00e0 depuis la veille. Sur les diff\u00e9rentes photos post\u00e9es sur les r\u00e9seaux sociaux des joueurs as\u00e9mistes, on a pu notamment remarquer la pr\u00e9sence de Jesper Daland (22 ans), athl\u00e9tique [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/11\/29\/jesper-daland-sentraine-avec-lasm\/","og_site_name":"La Diagonale","article_published_time":"2022-11-29T20:56:06+00:00","article_modified_time":"2022-12-01T11:23:53+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/11\/daland.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/11\/daland.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/11\/29\/jesper-daland-sentraine-avec-lasm\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/11\/29\/jesper-daland-sentraine-avec-lasm\/","name":"Jesper Daland s'entra\u00eene avec l'ASM - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2022-11-29T20:56:06+00:00","dateModified":"2022-12-01T11:23:53+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/11\/29\/jesper-daland-sentraine-avec-lasm\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2022\/11\/29\/jesper-daland-sentraine-avec-lasm\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/11\/29\/jesper-daland-sentraine-avec-lasm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Jesper Daland s&rsquo;entra\u00eene avec l&rsquo;ASM"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/7233"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=7233"}],"version-history":[{"count":7,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/7233\/revisions"}],"predecessor-version":[{"id":7273,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/7233\/revisions\/7273"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=7233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=7233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=7233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}