{"id":7770,"date":"2022-12-26T09:00:00","date_gmt":"2022-12-26T08:00:00","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=7770"},"modified":"2022-12-26T18:17:39","modified_gmt":"2022-12-26T17:17:39","slug":"labbe-deschamps-une-enceinte-hostile-pour-las-monaco","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2022\/12\/26\/labbe-deschamps-une-enceinte-hostile-pour-las-monaco\/","title":{"rendered":"L\u2019Abb\u00e9-Deschamps, une enceinte hostile pour Monaco"},"content":{"rendered":"\n\n\n<p>Monaco a d\u00e9j\u00e0 affront\u00e9 Auxerre dans son stade \u00e0 31 reprises dans le cadre de la Ligue 1 et cela s\u2019est rarement bien pass\u00e9 puisque les Rouge et Blanc n\u2019y ont empoch\u00e9 que cinq succ\u00e8s. Bourguignons et Mon\u00e9gasques ont partag\u00e9 les points \u00e0 12 reprises tandis que l\u2019AJA s\u2019est impos\u00e9e 14 fois. Entre mars 2001 et Janvier 2011, le club de la Principaut\u00e9 n\u2019a glan\u00e9 qu\u2019une seule victoire sur onze d\u00e9placements.<\/p>\n\n\n\n<p>La derni\u00e8re rencontre de Ligue 1 qui s\u2019est tenue en Bourgogne avait notamment \u00e9t\u00e9 la premi\u00e8re pour le retour de Laurent Banide, qui venait de succ\u00e9der \u00e0 Guy Lacombe apr\u00e8s une piteuse \u00e9limination mon\u00e9gasque en 32es de finale de la Coupe de France contre Chamb\u00e9ry, modeste club de CFA 2. L\u2019ASM avait fait match nul (1-1), Adriano r\u00e9pondant \u00e0 Quercia. En revanche, Monaco et Auxerre se retrouveront deux saisons plus tard en Ligue 2, lors de la saison 2012-2013, et l\u2019ASM avait pris les trois points (0-2).<\/p>\n\n\n\n<p><strong>Les cinq derni\u00e8res confrontations en Ligue 1 au stade de l\u2019Abb\u00e9-Deschamps<\/strong><\/p>\n\n\n\n<ul><li>2010-2011 (20e journ\u00e9e) : 1-1<\/li><li>2009-2010 (14e journ\u00e9e) : 2-0<\/li><li>2008-2009 (16e journ\u00e9e) : 0-1<\/li><li>2007-2008 (19e journ\u00e9e) : 1-0<\/li><li>2006-2007 (5e journ\u00e9e) : 2-1<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Monaco a d\u00e9j\u00e0 affront\u00e9 Auxerre dans son stade \u00e0 31 reprises dans le cadre de la Ligue 1 et cela s\u2019est rarement bien pass\u00e9 puisque les Rouge et Blanc n\u2019y ont empoch\u00e9 que cinq succ\u00e8s. Bourguignons et Mon\u00e9gasques ont partag\u00e9 les points \u00e0 12 reprises tandis que l\u2019AJA s\u2019est impos\u00e9e 14 fois. Entre mars 2001 [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[86,353,261,94],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L\u2019Abb\u00e9-Deschamps, une enceinte hostile pour Monaco - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/12\/26\/labbe-deschamps-une-enceinte-hostile-pour-las-monaco\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019Abb\u00e9-Deschamps, une enceinte hostile pour Monaco - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Monaco a d\u00e9j\u00e0 affront\u00e9 Auxerre dans son stade \u00e0 31 reprises dans le cadre de la Ligue 1 et cela s\u2019est rarement bien pass\u00e9 puisque les Rouge et Blanc n\u2019y ont empoch\u00e9 que cinq succ\u00e8s. Bourguignons et Mon\u00e9gasques ont partag\u00e9 les points \u00e0 12 reprises tandis que l\u2019AJA s\u2019est impos\u00e9e 14 fois. Entre mars 2001 [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/12\/26\/labbe-deschamps-une-enceinte-hostile-pour-las-monaco\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-26T08:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-26T17:17:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/12\/ajaasm.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/12\/ajaasm.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/12\/26\/labbe-deschamps-une-enceinte-hostile-pour-las-monaco\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/12\/26\/labbe-deschamps-une-enceinte-hostile-pour-las-monaco\/\",\"name\":\"L\u2019Abb\u00e9-Deschamps, une enceinte hostile pour Monaco - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2022-12-26T08:00:00+00:00\",\"dateModified\":\"2022-12-26T17:17:39+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/12\/26\/labbe-deschamps-une-enceinte-hostile-pour-las-monaco\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2022\/12\/26\/labbe-deschamps-une-enceinte-hostile-pour-las-monaco\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/12\/26\/labbe-deschamps-une-enceinte-hostile-pour-las-monaco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019Abb\u00e9-Deschamps, une enceinte hostile pour Monaco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019Abb\u00e9-Deschamps, une enceinte hostile pour Monaco - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2022\/12\/26\/labbe-deschamps-une-enceinte-hostile-pour-las-monaco\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019Abb\u00e9-Deschamps, une enceinte hostile pour Monaco - La Diagonale","og_description":"Monaco a d\u00e9j\u00e0 affront\u00e9 Auxerre dans son stade \u00e0 31 reprises dans le cadre de la Ligue 1 et cela s\u2019est rarement bien pass\u00e9 puisque les Rouge et Blanc n\u2019y ont empoch\u00e9 que cinq succ\u00e8s. Bourguignons et Mon\u00e9gasques ont partag\u00e9 les points \u00e0 12 reprises tandis que l\u2019AJA s\u2019est impos\u00e9e 14 fois. Entre mars 2001 [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/12\/26\/labbe-deschamps-une-enceinte-hostile-pour-las-monaco\/","og_site_name":"La Diagonale","article_published_time":"2022-12-26T08:00:00+00:00","article_modified_time":"2022-12-26T17:17:39+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/12\/ajaasm.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/12\/ajaasm.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/12\/26\/labbe-deschamps-une-enceinte-hostile-pour-las-monaco\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/12\/26\/labbe-deschamps-une-enceinte-hostile-pour-las-monaco\/","name":"L\u2019Abb\u00e9-Deschamps, une enceinte hostile pour Monaco - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2022-12-26T08:00:00+00:00","dateModified":"2022-12-26T17:17:39+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/12\/26\/labbe-deschamps-une-enceinte-hostile-pour-las-monaco\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2022\/12\/26\/labbe-deschamps-une-enceinte-hostile-pour-las-monaco\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/12\/26\/labbe-deschamps-une-enceinte-hostile-pour-las-monaco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"L\u2019Abb\u00e9-Deschamps, une enceinte hostile pour Monaco"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/7770"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=7770"}],"version-history":[{"count":2,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/7770\/revisions"}],"predecessor-version":[{"id":7810,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/7770\/revisions\/7810"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=7770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=7770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=7770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}