{"id":9432,"date":"2023-02-09T19:12:20","date_gmt":"2023-02-09T18:12:20","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=9432"},"modified":"2023-02-10T15:38:28","modified_gmt":"2023-02-10T14:38:28","slug":"monaco-serait-seduit-par-un-jeune-milieu-de-la-juventus","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/09\/monaco-serait-seduit-par-un-jeune-milieu-de-la-juventus\/","title":{"rendered":"Monaco serait s\u00e9duit par un jeune milieu de la Juventus"},"content":{"rendered":"\n\n\n<p>Des recruteurs de l&rsquo;AS Monaco se trouvaient \u00e0 Genk ce mercredi pour assister \u00e0 la rencontre de <em>Youth League<\/em> entre Genk et la Juventus. Le club de la Principaut\u00e9 aurait dans le viseur Joseph Nonge Boende, le jeune milieu de terrain U19 de la Juventus, selon le journaliste belge Sacha Tavolieri. <\/p>\n\n\n\n<p>D&rsquo;autres \u00e9missaires de clubs europ\u00e9ens \u00e9taient pr\u00e9sents lors de cette rencontre, comme ceux du Bayern Munich ou de l&rsquo;Eintracht Francfort, pour observer le Belge de 17 ans qui n&rsquo;a pas fini la rencontre, expuls\u00e9 peu apr\u00e8s l&rsquo;heure de jeu.<\/p>\n\n\n\n<p>Form\u00e9 en partie \u00e0 Anderlecht, Nonge Boende a rejoint Turin \u00e0 l&rsquo;\u00e9t\u00e9 2021. Selon <em>La Gazetta dello Sport<\/em>, Paul Pogba l&rsquo;aurait pris sous son aile aux entra\u00eenements et il pourrait avoir sa chance en \u00e9quipe premi\u00e8re dans les prochains mois. Le club turinois veut le prolonger alors qu&rsquo;il arrive en fin de contrat en juin 2024.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"fr\" dir=\"ltr\">\ud83c\udde7\ud83c\uddea\ud83d\udd25 Malgr\u00e9 son exclusion en 2e MT, Joseph <a href=\"https:\/\/twitter.com\/hashtag\/Nonge?src=hash&amp;ref_src=twsrc%5Etfw\">#Nonge<\/a> a attir\u00e9 l\u2019\u0153il des observateurs hier contre le <a href=\"https:\/\/twitter.com\/hashtag\/KRCGenk?src=hash&amp;ref_src=twsrc%5Etfw\">#KRCGenk<\/a> et plusieurs clubs comme l\u2019<a href=\"https:\/\/twitter.com\/hashtag\/ASMonaco?src=hash&amp;ref_src=twsrc%5Etfw\">#ASMonaco<\/a>, le <a href=\"https:\/\/twitter.com\/hashtag\/BayernMunich?src=hash&amp;ref_src=twsrc%5Etfw\">#BayernMunich<\/a> &amp; l\u2019<a href=\"https:\/\/twitter.com\/hashtag\/EintrachtFrankfurt?src=hash&amp;ref_src=twsrc%5Etfw\">#EintrachtFrankfurt<\/a> sont revenus \u00e0 la charge.<br>La <a href=\"https:\/\/twitter.com\/hashtag\/Juventus?src=hash&amp;ref_src=twsrc%5Etfw\">#Juventus<\/a>, qui discute d\u2019une prolongation, veut garder sa p\u00e9pite. <a href=\"https:\/\/t.co\/eBOIG8yUAj\">pic.twitter.com\/eBOIG8yUAj<\/a><\/p>&mdash; Sacha Tavolieri (@sachatavolieri) <a href=\"https:\/\/twitter.com\/sachatavolieri\/status\/1623661129380556801?ref_src=twsrc%5Etfw\">February 9, 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Des recruteurs de l&rsquo;AS Monaco se trouvaient \u00e0 Genk ce mercredi pour assister \u00e0 la rencontre de Youth League entre Genk et la Juventus. Le club de la Principaut\u00e9 aurait dans le viseur Joseph Nonge Boende, le jeune milieu de terrain U19 de la Juventus, selon le journaliste belge Sacha Tavolieri. D&rsquo;autres \u00e9missaires de clubs [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[86,407,111,110],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Monaco serait s\u00e9duit par un jeune milieu de la Juventus - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/09\/monaco-serait-seduit-par-un-jeune-milieu-de-la-juventus\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Monaco serait s\u00e9duit par un jeune milieu de la Juventus - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Des recruteurs de l&rsquo;AS Monaco se trouvaient \u00e0 Genk ce mercredi pour assister \u00e0 la rencontre de Youth League entre Genk et la Juventus. Le club de la Principaut\u00e9 aurait dans le viseur Joseph Nonge Boende, le jeune milieu de terrain U19 de la Juventus, selon le journaliste belge Sacha Tavolieri. D&rsquo;autres \u00e9missaires de clubs [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/09\/monaco-serait-seduit-par-un-jeune-milieu-de-la-juventus\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-09T18:12:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-10T14:38:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/02\/nonge.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/02\/nonge.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/09\/monaco-serait-seduit-par-un-jeune-milieu-de-la-juventus\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/09\/monaco-serait-seduit-par-un-jeune-milieu-de-la-juventus\/\",\"name\":\"Monaco serait s\u00e9duit par un jeune milieu de la Juventus - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2023-02-09T18:12:20+00:00\",\"dateModified\":\"2023-02-10T14:38:28+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/09\/monaco-serait-seduit-par-un-jeune-milieu-de-la-juventus\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/09\/monaco-serait-seduit-par-un-jeune-milieu-de-la-juventus\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/09\/monaco-serait-seduit-par-un-jeune-milieu-de-la-juventus\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Monaco serait s\u00e9duit par un jeune milieu de la Juventus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Monaco serait s\u00e9duit par un jeune milieu de la Juventus - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/09\/monaco-serait-seduit-par-un-jeune-milieu-de-la-juventus\/","og_locale":"fr_FR","og_type":"article","og_title":"Monaco serait s\u00e9duit par un jeune milieu de la Juventus - La Diagonale","og_description":"Des recruteurs de l&rsquo;AS Monaco se trouvaient \u00e0 Genk ce mercredi pour assister \u00e0 la rencontre de Youth League entre Genk et la Juventus. Le club de la Principaut\u00e9 aurait dans le viseur Joseph Nonge Boende, le jeune milieu de terrain U19 de la Juventus, selon le journaliste belge Sacha Tavolieri. D&rsquo;autres \u00e9missaires de clubs [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/09\/monaco-serait-seduit-par-un-jeune-milieu-de-la-juventus\/","og_site_name":"La Diagonale","article_published_time":"2023-02-09T18:12:20+00:00","article_modified_time":"2023-02-10T14:38:28+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/02\/nonge.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2023\/02\/nonge.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/09\/monaco-serait-seduit-par-un-jeune-milieu-de-la-juventus\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/09\/monaco-serait-seduit-par-un-jeune-milieu-de-la-juventus\/","name":"Monaco serait s\u00e9duit par un jeune milieu de la Juventus - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2023-02-09T18:12:20+00:00","dateModified":"2023-02-10T14:38:28+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/09\/monaco-serait-seduit-par-un-jeune-milieu-de-la-juventus\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/09\/monaco-serait-seduit-par-un-jeune-milieu-de-la-juventus\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/09\/monaco-serait-seduit-par-un-jeune-milieu-de-la-juventus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Monaco serait s\u00e9duit par un jeune milieu de la Juventus"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/9432"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=9432"}],"version-history":[{"count":4,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/9432\/revisions"}],"predecessor-version":[{"id":9462,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/9432\/revisions\/9462"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=9432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=9432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=9432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}