{"id":956,"date":"2022-04-16T21:31:49","date_gmt":"2022-04-16T19:31:49","guid":{"rendered":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/16\/la-reserve-sombre-chez-le-leader\/"},"modified":"2022-07-26T14:20:37","modified_gmt":"2022-07-26T12:20:37","slug":"la-reserve-sombre-chez-le-leader","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/16\/la-reserve-sombre-chez-le-leader\/","title":{"rendered":"La r\u00e9serve sombre chez le leader"},"content":{"rendered":"<p>Pas de miracle pour l&rsquo;\u00e9quipe r\u00e9serve de l&rsquo;AS Monaco. Les hommes de St\u00e9phane Nado ont v\u00e9cu une apr\u00e8s-midi cauchemardesque sur la pelouse du leader, Goal FC (5-0), au stade Ludovic Giuly. Le premier acte a \u00e9t\u00e9 cataclysmique pour les As\u00e9mistes, puisqu&rsquo;ils ont rejoint les vestiaires avec quatre buts dans la musette et surtout \u00e0 dix suite \u00e0 l&rsquo;expulsion de leur gardien, [fra\u00eechement professionnel](https:\/\/www.ladiagonale.net\/news-1146-premier-contrat-professionnel-pour-zadi-prolongations-pour-el-maach-et-torres), Alain Zadi.\t<\/p>\n<p>Cette 25e journ\u00e9e marque un v\u00e9ritable point de bascule. Au classement, l&rsquo;ASM est d\u00e9sormais 13e, premier rel\u00e9guable avec 25 points et \u00e0 \u00e9galit\u00e9 avec Rumilly-Valli\u00e8res. Les Rhodaniens se sont d\u2019ailleurs inclin\u00e9s face \u00e0 Saint-Priest, ce qui permet \u00e0 ces derniers de sortir de la zone rouge. En 12e place, Lyon-La Duch\u00e8re poss\u00e8de deux points d\u2019avance sur les Rouge et Blanc. M\u00eame si la dynamique est mauvaise c\u00f4t\u00e9 mon\u00e9gasque (une victoire en onze matchs), il reste encore cinq rencontres et quinze points \u00e0 prendre pour tenter de se sauver.<\/p>\n<p>**Composition :** Zadi, Platret, El-Maach, Okou, Silva, Semedo, Baranik, Magassa, Ribeiro, Lemarechal, Bakali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pas de miracle pour l&rsquo;\u00e9quipe r\u00e9serve de l&rsquo;AS Monaco. Les hommes de St\u00e9phane Nado ont v\u00e9cu une apr\u00e8s-midi cauchemardesque sur la pelouse du leader, Goal FC (5-0), au stade Ludovic Giuly. Le premier acte a \u00e9t\u00e9 cataclysmique pour les As\u00e9mistes, puisqu&rsquo;ils ont rejoint les vestiaires avec quatre buts dans la musette et surtout \u00e0 dix [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La r\u00e9serve sombre chez le leader - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/16\/la-reserve-sombre-chez-le-leader\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La r\u00e9serve sombre chez le leader - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Pas de miracle pour l&rsquo;\u00e9quipe r\u00e9serve de l&rsquo;AS Monaco. Les hommes de St\u00e9phane Nado ont v\u00e9cu une apr\u00e8s-midi cauchemardesque sur la pelouse du leader, Goal FC (5-0), au stade Ludovic Giuly. Le premier acte a \u00e9t\u00e9 cataclysmique pour les As\u00e9mistes, puisqu&rsquo;ils ont rejoint les vestiaires avec quatre buts dans la musette et surtout \u00e0 dix [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/16\/la-reserve-sombre-chez-le-leader\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-16T19:31:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-26T12:20:37+00:00\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/16\/la-reserve-sombre-chez-le-leader\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/16\/la-reserve-sombre-chez-le-leader\/\",\"name\":\"La r\u00e9serve sombre chez le leader - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2022-04-16T19:31:49+00:00\",\"dateModified\":\"2022-07-26T12:20:37+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/16\/la-reserve-sombre-chez-le-leader\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/16\/la-reserve-sombre-chez-le-leader\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/16\/la-reserve-sombre-chez-le-leader\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La r\u00e9serve sombre chez le leader\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La r\u00e9serve sombre chez le leader - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/16\/la-reserve-sombre-chez-le-leader\/","og_locale":"fr_FR","og_type":"article","og_title":"La r\u00e9serve sombre chez le leader - La Diagonale","og_description":"Pas de miracle pour l&rsquo;\u00e9quipe r\u00e9serve de l&rsquo;AS Monaco. Les hommes de St\u00e9phane Nado ont v\u00e9cu une apr\u00e8s-midi cauchemardesque sur la pelouse du leader, Goal FC (5-0), au stade Ludovic Giuly. Le premier acte a \u00e9t\u00e9 cataclysmique pour les As\u00e9mistes, puisqu&rsquo;ils ont rejoint les vestiaires avec quatre buts dans la musette et surtout \u00e0 dix [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/16\/la-reserve-sombre-chez-le-leader\/","og_site_name":"La Diagonale","article_published_time":"2022-04-16T19:31:49+00:00","article_modified_time":"2022-07-26T12:20:37+00:00","author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/16\/la-reserve-sombre-chez-le-leader\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/16\/la-reserve-sombre-chez-le-leader\/","name":"La r\u00e9serve sombre chez le leader - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2022-04-16T19:31:49+00:00","dateModified":"2022-07-26T12:20:37+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/16\/la-reserve-sombre-chez-le-leader\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/16\/la-reserve-sombre-chez-le-leader\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/16\/la-reserve-sombre-chez-le-leader\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"La r\u00e9serve sombre chez le leader"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/956"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=956"}],"version-history":[{"count":1,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/956\/revisions"}],"predecessor-version":[{"id":1858,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/956\/revisions\/1858"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}