{"id":964,"date":"2022-04-18T21:09:36","date_gmt":"2022-04-18T19:09:36","guid":{"rendered":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/18\/la-semaine-des-pretes-pellegri-buteur\/"},"modified":"2022-07-26T14:20:35","modified_gmt":"2022-07-26T12:20:35","slug":"la-semaine-des-pretes-pellegri-buteur","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/18\/la-semaine-des-pretes-pellegri-buteur\/","title":{"rendered":"La semaine des pr\u00eat\u00e9s : Pellegri buteur"},"content":{"rendered":"<p>Pietro Pellegri a mis fin \u00e0 une tr\u00e8s longue disette avec le Torino. Face \u00e0 la Lazio Rome, l\u2019attaquant italien a inscrit son premier but depuis le 6 d\u00e9cembre 2020. C\u2019\u00e9tait avec l\u2019AS Monaco, face \u00e0 Lille. Le joueur pr\u00eat\u00e9 par l\u2019ASM a remplac\u00e9 Belotti \u00e0 la mi-temps et aurait pu donner la victoire aux siens mais la Lazio est revenu dans le temps additionnel (1-1). <\/p>\n<p>En Ligue 1, Jean-Eudes Aholou, qui ne reviendra pas \u00e0 l\u2019ASM, a \u00e9t\u00e9 titularis\u00e9 avec Strasbourg pour la troisi\u00e8me fois cons\u00e9cutive face \u00e0 Troyes (1-1) et s\u2019est r\u00e9v\u00e9l\u00e9 solide dans l\u2019impact d\u00e9fensif avant de sortir \u00e0 la 64e minute. Mais le quotidien *L\u2019\u00c9quipe* lui a seulement attribu\u00e9 la moyenne. Avec Nantes, Geubbels est entr\u00e9 \u00e0 la 86e minute de jeu contre Angers (1-1).<\/p>\n<p>Antonio Barreca est le dernier \u00e0 avoir jou\u00e9 parmi les joueurs pr\u00eat\u00e9s par l\u2019ASM. Il \u00e9tait titularis\u00e9 face \u00e0 la Reggina (d\u00e9faite 1-0) et est sorti \u00e0 la 57e minute. Il a \u00e9t\u00e9 peu sollicit\u00e9 au cours de cette partie. <\/p>\n<p>Lecomte est rest\u00e9 sur le banc, comme \u00e0 son habitude, avec l\u2019Atl\u00e9tico de Madrid. En Ligue des Champions contre Manchester City (0-0) et contre l\u2019Espanyol (2-1) en Liga. Au cours de cette derni\u00e8re rencontre, un ancien mon\u00e9gasque, Geoffrey Kondogbia, a \u00e9t\u00e9 exclu. Strahinja Pavlovic \u00e9tait sur le banc aujourd\u2019hui (lundi, ndlr) pour la 30e journ\u00e9e de Super League suisse face \u00e0 Sion (0-0).<\/p>\n<p>Enfin, une semaine de repos pour Arthur Zagr\u00e9 et Anthony Musaba puisque aucune rencontre n\u2019\u00e9tait pr\u00e9vue en Eredivisie cette semaine.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pietro Pellegri a mis fin \u00e0 une tr\u00e8s longue disette avec le Torino. Face \u00e0 la Lazio Rome, l\u2019attaquant italien a inscrit son premier but depuis le 6 d\u00e9cembre 2020. C\u2019\u00e9tait avec l\u2019AS Monaco, face \u00e0 Lille. Le joueur pr\u00eat\u00e9 par l\u2019ASM a remplac\u00e9 Belotti \u00e0 la mi-temps et aurait pu donner la victoire aux [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La semaine des pr\u00eat\u00e9s : Pellegri buteur - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/18\/la-semaine-des-pretes-pellegri-buteur\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La semaine des pr\u00eat\u00e9s : Pellegri buteur - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Pietro Pellegri a mis fin \u00e0 une tr\u00e8s longue disette avec le Torino. Face \u00e0 la Lazio Rome, l\u2019attaquant italien a inscrit son premier but depuis le 6 d\u00e9cembre 2020. C\u2019\u00e9tait avec l\u2019AS Monaco, face \u00e0 Lille. Le joueur pr\u00eat\u00e9 par l\u2019ASM a remplac\u00e9 Belotti \u00e0 la mi-temps et aurait pu donner la victoire aux [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/18\/la-semaine-des-pretes-pellegri-buteur\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-18T19:09:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-26T12:20:35+00:00\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/18\/la-semaine-des-pretes-pellegri-buteur\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/18\/la-semaine-des-pretes-pellegri-buteur\/\",\"name\":\"La semaine des pr\u00eat\u00e9s : Pellegri buteur - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2022-04-18T19:09:36+00:00\",\"dateModified\":\"2022-07-26T12:20:35+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/18\/la-semaine-des-pretes-pellegri-buteur\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/18\/la-semaine-des-pretes-pellegri-buteur\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/18\/la-semaine-des-pretes-pellegri-buteur\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La semaine des pr\u00eat\u00e9s : Pellegri buteur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La semaine des pr\u00eat\u00e9s : Pellegri buteur - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/18\/la-semaine-des-pretes-pellegri-buteur\/","og_locale":"fr_FR","og_type":"article","og_title":"La semaine des pr\u00eat\u00e9s : Pellegri buteur - La Diagonale","og_description":"Pietro Pellegri a mis fin \u00e0 une tr\u00e8s longue disette avec le Torino. Face \u00e0 la Lazio Rome, l\u2019attaquant italien a inscrit son premier but depuis le 6 d\u00e9cembre 2020. C\u2019\u00e9tait avec l\u2019AS Monaco, face \u00e0 Lille. Le joueur pr\u00eat\u00e9 par l\u2019ASM a remplac\u00e9 Belotti \u00e0 la mi-temps et aurait pu donner la victoire aux [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/18\/la-semaine-des-pretes-pellegri-buteur\/","og_site_name":"La Diagonale","article_published_time":"2022-04-18T19:09:36+00:00","article_modified_time":"2022-07-26T12:20:35+00:00","author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/18\/la-semaine-des-pretes-pellegri-buteur\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/18\/la-semaine-des-pretes-pellegri-buteur\/","name":"La semaine des pr\u00eat\u00e9s : Pellegri buteur - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2022-04-18T19:09:36+00:00","dateModified":"2022-07-26T12:20:35+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/18\/la-semaine-des-pretes-pellegri-buteur\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/18\/la-semaine-des-pretes-pellegri-buteur\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/18\/la-semaine-des-pretes-pellegri-buteur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"La semaine des pr\u00eat\u00e9s : Pellegri buteur"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/964"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=964"}],"version-history":[{"count":1,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/964\/revisions"}],"predecessor-version":[{"id":1850,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/964\/revisions\/1850"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}