{"id":966,"date":"2022-04-19T15:25:32","date_gmt":"2022-04-19T13:25:32","guid":{"rendered":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/19\/nubel-un-derby-est-toujours-special\/"},"modified":"2022-07-26T14:20:35","modified_gmt":"2022-07-26T12:20:35","slug":"nubel-un-derby-est-toujours-special","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/19\/nubel-un-derby-est-toujours-special\/","title":{"rendered":"N\u00fcbel : \u00ab Un derby est toujours sp\u00e9cial \u00bb"},"content":{"rendered":"<p>Alexander N\u00fcbel \u00e9tait en conf\u00e9rence de presse, la veille du derby face \u00e0 Nice. Pour le gardien de l\u2019AS Monaco, ce match sera forc\u00e9ment un peu particulier : \u00ab *Ces matchs sont toujours sp\u00e9ciaux. Il y a une notion de rivalit\u00e9, entre supporters et entre clubs, avec une grosse ambiance, et on la ressent d\u00e8s la veille*, a-t-il r\u00e9v\u00e9l\u00e9. *Je peux vous dire qu\u2019aujourd\u2019hui nous avons fait une bonne s\u00e9ance et que nous serons pr\u00eats.* \u00bb<\/p>\n<p>Les Ni\u00e7ois poss\u00e8dent la meilleure d\u00e9fense de Ligue 1, avec 28 buts encaiss\u00e9s, et Alexander N\u00fcbel suit avec attention les performances de son homologue ni\u00e7ois, Walter Benitez : \u00ab *Je regarde les performances des autres gardiens, y compris celles de Benitez. Il fait une tr\u00e8s belle saison mais toute sa d\u00e9fense travaille bien, car c\u2019est la meilleure du championnat.* \u00bb<\/p>\n<p>Mais Monaco n\u2019est pas en reste et se r\u00e9v\u00e8le beaucoup plus solide depuis quelques semaines. Et N\u00fcbel pense avoir l\u2019explication : \u00ab *Il y a une meilleure communication et coordination au sein de l\u2019\u00e9quipe. On \u00e9change mieux car il y a plus de temps pour travailler, avec une seule rencontre par semaine, et de fa\u00e7on plus approfondie. On se trouve mieux sur le terrain, y compris pour moi.* \u00bb<\/p>\n<p>Le gardien de 25 ans, qui a [assur\u00e9 qu\u2019il serait encore \u00e0 Monaco la saison prochaine](https:\/\/www.ladiagonale.net\/news-1177-nubel-assure-quil-sera-la-lan-prochain), confirme que la phase d\u2019adaptation est d\u00e9sormais termin\u00e9e. Le portier a d\u2019ailleurs pr\u00e9cis\u00e9 qu\u2019il s\u2019exprimait autant que possible en fran\u00e7ais sur le terrain avec les d\u00e9fenseurs fran\u00e7ais comme Badiashile et Disasi : \u00ab *J\u2019ai une vraie connexion avec mes d\u00e9fenseurs. On s\u2019est adapt\u00e9s, ils savent comment je proc\u00e8de avec le jeu au pied. On se sent \u00e0 l\u2019aise maintenant.* \u00bb <\/p>\n<p>Un jeu au pied qui a gagn\u00e9 en importance et N\u00fcbel sait qu\u2019il peut faire mieux : \u00ab *Il faut trouver un \u00e9quilibre entre les relances courtes et longues, mais le plus important c\u2019est d\u2019emp\u00eacher l\u2019\u00e9quipe adverse de marquer et de faire des arr\u00eats. Mais c\u2019est certain que le jeu au pied est plus important depuis quelques ann\u00e9es. Je dois beaucoup progresser sur ce domaine. J\u2019ai \u00e9volu\u00e9 avec Neuer pendant un an et j\u2019ai vu ce sur quoi je dois m\u2019am\u00e9liorer.* \u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alexander N\u00fcbel \u00e9tait en conf\u00e9rence de presse, la veille du derby face \u00e0 Nice. Pour le gardien de l\u2019AS Monaco, ce match sera forc\u00e9ment un peu particulier : \u00ab *Ces matchs sont toujours sp\u00e9ciaux. Il y a une notion de rivalit\u00e9, entre supporters et entre clubs, avec une grosse ambiance, et on la ressent d\u00e8s [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>N\u00fcbel : \u00ab Un derby est toujours sp\u00e9cial \u00bb - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/19\/nubel-un-derby-est-toujours-special\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"N\u00fcbel : \u00ab Un derby est toujours sp\u00e9cial \u00bb - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Alexander N\u00fcbel \u00e9tait en conf\u00e9rence de presse, la veille du derby face \u00e0 Nice. Pour le gardien de l\u2019AS Monaco, ce match sera forc\u00e9ment un peu particulier : \u00ab *Ces matchs sont toujours sp\u00e9ciaux. Il y a une notion de rivalit\u00e9, entre supporters et entre clubs, avec une grosse ambiance, et on la ressent d\u00e8s [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/19\/nubel-un-derby-est-toujours-special\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-19T13:25:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-26T12:20:35+00:00\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/19\/nubel-un-derby-est-toujours-special\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/19\/nubel-un-derby-est-toujours-special\/\",\"name\":\"N\u00fcbel : \u00ab Un derby est toujours sp\u00e9cial \u00bb - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2022-04-19T13:25:32+00:00\",\"dateModified\":\"2022-07-26T12:20:35+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/19\/nubel-un-derby-est-toujours-special\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/19\/nubel-un-derby-est-toujours-special\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/19\/nubel-un-derby-est-toujours-special\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"N\u00fcbel : \u00ab Un derby est toujours sp\u00e9cial \u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"N\u00fcbel : \u00ab Un derby est toujours sp\u00e9cial \u00bb - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/19\/nubel-un-derby-est-toujours-special\/","og_locale":"fr_FR","og_type":"article","og_title":"N\u00fcbel : \u00ab Un derby est toujours sp\u00e9cial \u00bb - La Diagonale","og_description":"Alexander N\u00fcbel \u00e9tait en conf\u00e9rence de presse, la veille du derby face \u00e0 Nice. Pour le gardien de l\u2019AS Monaco, ce match sera forc\u00e9ment un peu particulier : \u00ab *Ces matchs sont toujours sp\u00e9ciaux. Il y a une notion de rivalit\u00e9, entre supporters et entre clubs, avec une grosse ambiance, et on la ressent d\u00e8s [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/19\/nubel-un-derby-est-toujours-special\/","og_site_name":"La Diagonale","article_published_time":"2022-04-19T13:25:32+00:00","article_modified_time":"2022-07-26T12:20:35+00:00","author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/19\/nubel-un-derby-est-toujours-special\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/19\/nubel-un-derby-est-toujours-special\/","name":"N\u00fcbel : \u00ab Un derby est toujours sp\u00e9cial \u00bb - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2022-04-19T13:25:32+00:00","dateModified":"2022-07-26T12:20:35+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/19\/nubel-un-derby-est-toujours-special\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/19\/nubel-un-derby-est-toujours-special\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/19\/nubel-un-derby-est-toujours-special\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"N\u00fcbel : \u00ab Un derby est toujours sp\u00e9cial \u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/966"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=966"}],"version-history":[{"count":1,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/966\/revisions"}],"predecessor-version":[{"id":1848,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/966\/revisions\/1848"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}