{"id":981,"date":"2022-04-21T09:35:45","date_gmt":"2022-04-21T07:35:45","guid":{"rendered":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/21\/galtier-a-beaucoup-de-regrets\/"},"modified":"2022-07-26T14:20:31","modified_gmt":"2022-07-26T12:20:31","slug":"galtier-a-beaucoup-de-regrets","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/21\/galtier-a-beaucoup-de-regrets\/","title":{"rendered":"Galtier a beaucoup de regrets"},"content":{"rendered":"<p>La d\u00e9ception \u00e9tait forc\u00e9ment du c\u00f4t\u00e9 ni\u00e7ois apr\u00e8s la belle victoire de l\u2019AS Monaco dans ce 102e derby de la C\u00f4te d\u2019Azur. Un seul but a \u00e9t\u00e9 inscrit, par Golovin, suite \u00e0 un ballon d\u00e9tourn\u00e9 de Benitez. Le gardien ni\u00e7ois regrette cette faute de main : \u00ab *Le centre arrive fort, je veux le d\u00e9vier, le ballon arrive malheureusement dans les pieds d\u2019un Mon\u00e9gasque (Golovin, ndlr)\u2026 On est d\u00e9\u00e7u, on a pouss\u00e9 pour au moins \u00e9galiser mais Monaco a bien d\u00e9fendu jusqu\u2019\u00e0 la fin du match.* \u00bb <\/p>\n<p>Christophe Galtier \u00e9tait quant \u00e0 lui d\u00e9\u00e7u pour ses joueurs, qu\u2019il a estim\u00e9 au niveau de la rencontre : \u00ab *C\u2019est toujours emb\u00eatant d\u2019encaisser un but, encore plus juste avant la pause. On peut avoir beaucoup de regrets, les joueurs ont fait le match qu\u2019il fallait faire dans l\u2019engagement, dans le jeu. On pouvait s\u2019attendre \u00e0 \u00eatre malmen\u00e9, j\u2019ai aim\u00e9 leur comportement pour emp\u00eacher Monaco de jouer tr\u00e8s haut, on les a tr\u00e8s bien press\u00e9s.* \u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La d\u00e9ception \u00e9tait forc\u00e9ment du c\u00f4t\u00e9 ni\u00e7ois apr\u00e8s la belle victoire de l\u2019AS Monaco dans ce 102e derby de la C\u00f4te d\u2019Azur. Un seul but a \u00e9t\u00e9 inscrit, par Golovin, suite \u00e0 un ballon d\u00e9tourn\u00e9 de Benitez. Le gardien ni\u00e7ois regrette cette faute de main : \u00ab *Le centre arrive fort, je veux le d\u00e9vier, [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Galtier a beaucoup de regrets - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/21\/galtier-a-beaucoup-de-regrets\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Galtier a beaucoup de regrets - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"La d\u00e9ception \u00e9tait forc\u00e9ment du c\u00f4t\u00e9 ni\u00e7ois apr\u00e8s la belle victoire de l\u2019AS Monaco dans ce 102e derby de la C\u00f4te d\u2019Azur. Un seul but a \u00e9t\u00e9 inscrit, par Golovin, suite \u00e0 un ballon d\u00e9tourn\u00e9 de Benitez. Le gardien ni\u00e7ois regrette cette faute de main : \u00ab *Le centre arrive fort, je veux le d\u00e9vier, [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/21\/galtier-a-beaucoup-de-regrets\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-21T07:35:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-26T12:20:31+00:00\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/21\/galtier-a-beaucoup-de-regrets\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/21\/galtier-a-beaucoup-de-regrets\/\",\"name\":\"Galtier a beaucoup de regrets - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2022-04-21T07:35:45+00:00\",\"dateModified\":\"2022-07-26T12:20:31+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/21\/galtier-a-beaucoup-de-regrets\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/21\/galtier-a-beaucoup-de-regrets\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/21\/galtier-a-beaucoup-de-regrets\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Galtier a beaucoup de regrets\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Galtier a beaucoup de regrets - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/21\/galtier-a-beaucoup-de-regrets\/","og_locale":"fr_FR","og_type":"article","og_title":"Galtier a beaucoup de regrets - La Diagonale","og_description":"La d\u00e9ception \u00e9tait forc\u00e9ment du c\u00f4t\u00e9 ni\u00e7ois apr\u00e8s la belle victoire de l\u2019AS Monaco dans ce 102e derby de la C\u00f4te d\u2019Azur. Un seul but a \u00e9t\u00e9 inscrit, par Golovin, suite \u00e0 un ballon d\u00e9tourn\u00e9 de Benitez. Le gardien ni\u00e7ois regrette cette faute de main : \u00ab *Le centre arrive fort, je veux le d\u00e9vier, [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/21\/galtier-a-beaucoup-de-regrets\/","og_site_name":"La Diagonale","article_published_time":"2022-04-21T07:35:45+00:00","article_modified_time":"2022-07-26T12:20:31+00:00","author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/21\/galtier-a-beaucoup-de-regrets\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/21\/galtier-a-beaucoup-de-regrets\/","name":"Galtier a beaucoup de regrets - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2022-04-21T07:35:45+00:00","dateModified":"2022-07-26T12:20:31+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/21\/galtier-a-beaucoup-de-regrets\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/21\/galtier-a-beaucoup-de-regrets\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/21\/galtier-a-beaucoup-de-regrets\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Galtier a beaucoup de regrets"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/981"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=981"}],"version-history":[{"count":1,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/981\/revisions"}],"predecessor-version":[{"id":1833,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/981\/revisions\/1833"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}